{"id":13852,"date":"2023-11-16T15:53:13","date_gmt":"2023-11-16T14:53:13","guid":{"rendered":"https:\/\/sad-borg.82-223-8-23.plesk.page\/?p=13852"},"modified":"2024-09-10T23:10:00","modified_gmt":"2024-09-10T22:10:00","slug":"as-duas-vitorias-das-campeas-do-mundo","status":"publish","type":"post","link":"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/","title":{"rendered":"As duas vit\u00f3rias das campe\u00e3s do mundo"},"content":{"rendered":"<p>Campe&atilde;s do mundo. Campe&atilde;s mundiais do desporto mais masculinizado do mundo. Campe&otilde;es, apesar de tudo e face a tudo. Campe&atilde;s duas vezes, as jogadoras da sele&ccedil;&atilde;o espanhola, ao decidirem voltar a levantar a voz perante o que n&atilde;o devia acontecer, mas continua a acontecer: o <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Machismo&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;A cren&ccedil;a na superioridade dos homens sobre as mulheres, que perpetua os pap&eacute;is e estere&oacute;tipos de g&eacute;nero que limitam a igualdade e perpetuam a discrimina&ccedil;&atilde;o e a desigualdade.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/machismo\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">machismo<\/a>, a infantiliza&ccedil;&atilde;o e os abusos de poder sobre as mulheres; sobre as desportistas, tamb&eacute;m.<\/p>\n\n\n\n<p>Este gesto das futebolistas espanholas coloca-as numa posi&ccedil;&atilde;o privilegiada para acelerar a mudan&ccedil;a que t&ecirc;m vindo a exigir e de que o futebol tanto precisa. Com a sua falta de jeito, o antigo presidente da federa&ccedil;&atilde;o espanhola de futebol, Luis Rubiales, serviu-lhes a mudan&ccedil;a num prato. Elas n&atilde;o perderam a oportunidade e, como Megan Rapinoe e as suas colegas, nos Estados Unidos e Ada Hegerberg, na Noruega haviam feito antes delas, assumiram a sua responsabilidade social.<\/p>\n\n\n\n<p>&ldquo;Acab&aacute;mos de ganhar um Campeonato do Mundo, mas n&atilde;o se fala muito disso, porque est&atilde;o a acontecer coisas que eu n&atilde;o gostaria de deixar passar em branco. Como sociedade, n&atilde;o devemos permitir abusos de poder numa rela&ccedil;&atilde;o de trabalho ou desrespeito. Estamos contigo, com a minha colega Jenni [Hermoso] e com todas as mulheres que sofrem o mesmo. Espero que continuemos a trabalhar para que esta sociedade melhore&rdquo;, disse Aitana Bonmat&iacute;, depois de receber o pr&eacute;mio que a proclamou a melhor jogadora da UEFA da &eacute;poca passada.<\/p>\n\n\n\n<p>Referia-se ao caso Rubiales, o beijo roubado a Jennifer Hermoso pelo agora ex-presidente da federa&ccedil;&atilde;o na cerim&oacute;nia de entrega de medalhas da final do Campeonato do Mundo, que, juntamente com o gesto obsceno do presidente no camarote VIP do evento, ofuscou injustamente os feitos desportivos das 23 jogadoras que disputaram o campeonato e ajudaram a abrir caminho &agrave; Austr&aacute;lia e &agrave; Nova Zel&acirc;ndia.<\/p>\n\n\n\n<p>&Eacute; uma pena e, ao mesmo tempo, um bom sinal: a sociedade evoluiu o suficiente para que, nesta altura, acontecimentos como este n&atilde;o possam ser ignorados. Ilustram a realidade das mulheres futebolistas no nosso pa&iacute;s, mas n&atilde;o s&oacute;: as mulheres, desportistas ou n&atilde;o, s&atilde;o v&iacute;timas habituais do <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Machismo&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;A cren&ccedil;a na superioridade dos homens sobre as mulheres, que perpetua os pap&eacute;is e estere&oacute;tipos de g&eacute;nero que limitam a igualdade e perpetuam a discrimina&ccedil;&atilde;o e a desigualdade.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/machismo\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">machismo<\/a> e dos abusos de poder dos nossos superiores, na sua maioria, homens. O comportamento de Rubiales apenas serviu para tornar vis&iacute;vel esse facto numa &aacute;rea que muitos homens ainda consideram ser do dom&iacute;nio exclusivo dos mach&otilde;es, como o antigo presidente da Federa&ccedil;&atilde;o e os seus correligion&aacute;rios deixaram claro no dia da final e nas suas subsequentes apari&ccedil;&otilde;es p&uacute;blicas.<\/p>\n\n\n\n<p>Foi assim que a popularidade do pr&oacute;prio futebol e os avan&ccedil;os culturais do <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Feminismo&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Movimento social e pol&iacute;tico que luta pela igualdade de direitos entre homens e mulheres, opondo-se &agrave; discrimina&ccedil;&atilde;o com base no g&eacute;nero.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/trad-life-uma-escolha-feminista\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Trad-life: uma escolha feminista?.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/8-m-denuncia-a-discriminacao-invisivel-dos-prestadores-de-cuidados\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;8-M denuncia a discrimina&ccedil;&atilde;o invis&iacute;vel dos prestadores de cuidados&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/feminismo\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">feminismo<\/a> nos &uacute;ltimos anos fizeram o impens&aacute;vel: provocaram uma agita&ccedil;&atilde;o pol&iacute;tica, social e jur&iacute;dica de propor&ccedil;&otilde;es internacionais. <strong>A press&atilde;o pol&iacute;tica e social que obrigou Rubiales a demitir-se e o processo judicial que o antigo presidente enfrenta atualmente &ndash; n&atilde;o queria demitir-se, mas acabou por faz&ecirc;-lo por raz&otilde;es de conveni&ecirc;ncia &ndash; n&atilde;o teriam acontecido h&aacute; cinco anos. <\/strong>O gesto teria sido considerado normal, sem provocar qualquer tipo de rea&ccedil;&atilde;o institucional ou social. Tal como os muitos comportamentos machistas que normaliz&aacute;mos no nosso quotidiano.<\/p>\n\n\n\n<p>Felizmente, s&atilde;o cada vez menos. A onda feminista tem vindo a desmascar&aacute;-los. <strong>Em 2017, o movimento #metoo\/#me too abriu a porta &agrave; den&uacute;ncia p&uacute;blica das agress&otilde;es e abusos sexuais contra as mulheres.<\/strong> Tornou-se viral nas redes sociais sob esse hashtag, na sequ&ecirc;ncia das alega&ccedil;&otilde;es de <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Abuso sexual&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;O abuso sexual envolve coer&ccedil;&atilde;o, manipula&ccedil;&atilde;o ou for&ccedil;a para envolver uma pessoa em atividade sexual sem o seu consentimento ou quando esta n&atilde;o &eacute; capaz de dar o seu consentimento informado, causando traumas e violando a sua integridade f&iacute;sica e emocional.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/abuso-sexual\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">abuso sexual<\/a> contra o produtor de cinema norte-americano Harvey Weinstein. Desde ent&atilde;o, tem sido utilizada por centenas de milhares de mulheres em todo o mundo para se declararem v&iacute;timas de ass&eacute;dio, agress&atilde;o ou <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Abuso sexual&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;O abuso sexual envolve coer&ccedil;&atilde;o, manipula&ccedil;&atilde;o ou for&ccedil;a para envolver uma pessoa em atividade sexual sem o seu consentimento ou quando esta n&atilde;o &eacute; capaz de dar o seu consentimento informado, causando traumas e violando a sua integridade f&iacute;sica e emocional.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/abuso-sexual\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">abuso sexual<\/a>. Algumas s&atilde;o famosas (Lady Gaga, Mira Sorvino, Patricia Arquette ou Juliette Binoche); a maioria &eacute; an&oacute;nima. Nasceu no mundo do cinema e do espet&aacute;culo e, de uma forma menos massiva, estendeu-se &agrave; cultura em geral, &agrave; pol&iacute;tica e a outros dom&iacute;nios.<\/p>\n\n\n\n<p>Tamb&eacute;m em 2017, em Espanha, a senten&ccedil;a do chamado processo &ldquo;La Manada&rdquo; provocou uma rea&ccedil;&atilde;o viral de milhares de mulheres. O gatilho foi um artigo da diretora do jornal P&uacute;blico, Virginia P&eacute;rez Alonso, no qual ela contava uma agress&atilde;o que sofreu quando era adolescente. A iniciativa da jornalista Cristina Fallar&aacute;s de partilhar o artigo nas redes com o hashtag <em>#cu&eacute;ntalo<\/em> permitiu que milhares de mulheres expusessem os seus casos como v&iacute;timas do <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Machismo&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;A cren&ccedil;a na superioridade dos homens sobre as mulheres, que perpetua os pap&eacute;is e estere&oacute;tipos de g&eacute;nero que limitam a igualdade e perpetuam a discrimina&ccedil;&atilde;o e a desigualdade.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/machismo\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">machismo<\/a>. <strong>Em agosto do ano passado, a aprova&ccedil;&atilde;o da &ldquo;lei do sim &eacute; sim&rdquo; conseguiu fazer do consentimento expresso o elemento principal no julgamento de casos de abuso ou agress&atilde;o sexual, transferindo assim a perspetiva de g&eacute;nero para o sistema judicial. <\/strong>O debate aceso que teve lugar antes e depois da promulga&ccedil;&atilde;o da lei contribuiu para despertar consci&ecirc;ncias e feminizar a vis&atilde;o social que temos do <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Abuso sexual&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;O abuso sexual envolve coer&ccedil;&atilde;o, manipula&ccedil;&atilde;o ou for&ccedil;a para envolver uma pessoa em atividade sexual sem o seu consentimento ou quando esta n&atilde;o &eacute; capaz de dar o seu consentimento informado, causando traumas e violando a sua integridade f&iacute;sica e emocional.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/abuso-sexual\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">abuso sexual<\/a> e do abuso de poder. Tanto assim &eacute; que as <strong>futebolistas internacionais espanholas falam agora de uma posi&ccedil;&atilde;o de poder e n&atilde;o de v&iacute;timas, como demonstra o seu slogan: &ldquo;Acabou&rdquo;.<\/strong><\/p>\n\n\n\n<p>Por todas estas raz&otilde;es, a evolu&ccedil;&atilde;o do caso Rubiales, que chegou ao Parlamento Europeu, e a realiza&ccedil;&atilde;o do Campeonato do Mundo s&atilde;o avan&ccedil;os que devem ser celebrados. E muito.<\/p>\n\n\n\n<p><strong>Evolu&ccedil;&atilde;o mete&oacute;rica<\/strong><\/p>\n\n\n\n<p>N&atilde;o esque&ccedil;amos que, pouco antes do esc&acirc;ndalo, os jogadores espanh&oacute;is tinham ganho o seu primeiro Campeonato do Mundo contra todas as probabilidades. Era apenas a sua terceira participa&ccedil;&atilde;o num Campeonato do Mundo (Canad&aacute; 2015, Fran&ccedil;a 2019 e Austr&aacute;lia e Nova Zel&acirc;ndia 2023) e estavam muito atr&aacute;s de pa&iacute;ses como os Estados Unidos, a Inglaterra, a Holanda, a Alemanha e o Jap&atilde;o, que j&aacute; tinham vencido a competi&ccedil;&atilde;o.<\/p>\n\n\n\n<p>Como &eacute; que se explica este salto da obscuridade para o topo em apenas quatro anos? A grande melhoria de alguns clubes da liga feminina espanhola, a qualidade das jogadoras mais jovens, o profissionalismo crescente, mas ainda prec&aacute;rio, da liga feminina.<\/p>\n\n\n\n<p>Entre o &uacute;ltimo Campeonato do Mundo e este, o Barcelona afirmou-se como uma das melhores equipas da Europa, conquistando quase todos os seus t&iacute;tulos nacionais, duas Ligas dos Campe&otilde;es (2020\/21 e 2022\/23) e sendo finalista de outra. Competir contra os melhores da Europa tornou as jogadoras azulgranas melhores, e elas formam a espinha dorsal da sele&ccedil;&atilde;o espanhola: nove das 23 jogadoras. Os exemplos mais evidentes s&atilde;o Alexia Putellas e Aitana Bonmat&iacute;. Entre a Fran&ccedil;a 2019 e a Austr&aacute;lia 2023, Putellas foi duas vezes eleita a melhor jogadora do mundo. &Eacute; prov&aacute;vel que Bonmat&iacute; siga as suas pisadas esta &eacute;poca, tendo j&aacute; sido eleita a jogadora do ano e a melhor jogadora do Campeonato do Mundo.<\/p>\n\n\n\n<p>O Bar&ccedil;a beneficiou da decis&atilde;o do Real Madrid de criar uma equipa feminina e contratar algumas das melhores jogadoras da Europa. Nem que seja por uma quest&atilde;o de corre&ccedil;&atilde;o pol&iacute;tica ou por raz&otilde;es comerciais (os patrocinadores viram a popularidade econ&oacute;mica e social das equipas femininas), o facto de os dois maiores clubes espanh&oacute;is replicarem a sua rivalidade na liga feminina eleva o n&iacute;vel da competi&ccedil;&atilde;o. Se clubes hist&oacute;ricos como o Atl&eacute;tico de Madrid, o Levante e a Real Sociedad investirem mais nas suas equipas femininas, o crescimento ser&aacute; ainda maior.<\/p>\n\n\n\n<p><strong>Ainda &eacute; uma luta. As futebolistas da Liga F tiveram de entrar novamente em greve para conseguir um novo acordo que melhorasse as suas condi&ccedil;&otilde;es de trabalho. <\/strong>As suas reivindica&ccedil;&otilde;es de mais profissionalismo e melhores sal&aacute;rios foram confrontadas com argumentos que continuam a subestimar o potencial das competi&ccedil;&otilde;es femininas, apesar de os espetadores terem demonstrado repetidamente que o produto, quando apostado, gera interesse.<\/p>\n\n\n\n<p>&Eacute;, pois, surpreendente constatar o excelente desempenho das sele&ccedil;&otilde;es nacionais jovens femininas, que nos &uacute;ltimos anos ganharam quase continuamente os Campeonatos da Europa (sub-17 e sub-19) e os Campeonatos do Mundo (sub-17). <strong>S&atilde;o cada vez mais as raparigas que praticam futebol desde muito jovens, quer em equipas femininas, quer em equipas mistas onde competem com rapazes at&eacute; quase &agrave; adolesc&ecirc;ncia.<\/strong> &Eacute; o caso da campe&atilde; do mundo Ona Batlle na Uni&oacute; Esportiva Vilassar. Aqui, <strong>as raparigas compensam a maior for&ccedil;a dos seus companheiros de equipa com t&eacute;cnica e intelig&ecirc;ncia, e &eacute; exatamente isso que demonstram mais tarde em competi&ccedil;&otilde;es internacionais contra advers&aacute;rios muitas vezes fisicamente mais fortes.<\/strong><\/p>\n\n\n\n<p>A federa&ccedil;&atilde;o soube tirar partido desta evolu&ccedil;&atilde;o na sociedade &ndash; j&aacute; n&atilde;o &eacute; um choque ver uma rapariga a jogar futebol &ndash; e nos clubes em geral, em benef&iacute;cio da sele&ccedil;&atilde;o nacional. <strong>&Agrave; sua maneira, Rubiales optou por<\/strong> aumentar os recursos consagrados &agrave;s equipas femininas. Funcionou bem com as sele&ccedil;&otilde;es jovens. N&atilde;o &eacute; o caso da equipa principal. Ap&oacute;s o Europeu de Inglaterra (2022), a maioria das jogadoras internacionais exigiu melhores condi&ccedil;&otilde;es para continuar a competir pela sele&ccedil;&atilde;o nacional. O problema n&atilde;o era apenas o treinador Jorge Vilda, recentemente demitido. Queriam treinadores, nutricionistas, massagistas, psic&oacute;logos, profissionais e condi&ccedil;&otilde;es que estivessem &agrave; altura do desafio que se avizinhava, como &eacute; o caso da sele&ccedil;&atilde;o masculina.<\/p>\n\n\n\n<p>A luta foi dura e intensa. Muitas vezes subestimada e mal interpretada &ndash; as jogadoras n&atilde;o sabiam como expressar publicamente o que queriam &ndash; como uma birra de raparigas caprichosas. Nada podia estar mais longe da verdade. Tanto assim &eacute; que, <strong>antes do Campeonato do Mundo, Rubiales cedeu o suficiente para permitir que muitas das jogadoras que n&atilde;o tinham sido convocadas no ano passado regressassem &agrave; sele&ccedil;&atilde;o nacional.<\/strong> Outras, como Mapi Le&oacute;n e Patri Guijarro, mantiveram as suas posi&ccedil;&otilde;es e n&atilde;o participaram no recente Campeonato do Mundo.<\/p>\n\n\n\n<p><strong>Quinta privada de Rubiales<\/strong><\/p>\n\n\n\n<p>A concess&atilde;o m&iacute;nima de Rubiales explica muita coisa. O t&iacute;tulo inesperado, em parte. E o seu comportamento posterior, quase tudo. Como o homem de ontem que &eacute;, o antigo presidente da federa&ccedil;&atilde;o acredita que, se a sele&ccedil;&atilde;o feminina &eacute; hoje campe&atilde; do mundo, isso se deve ao que fez por uma equipa que, como as outras, faz parte de um cortijo ou de uma quinta que ele geriu sem que ningu&eacute;m o questionasse ou questionasse o que quer que fosse. Os &uacute;nicos que o fizeram foram os jogadores que agora s&atilde;o campe&otilde;es, e j&aacute; o s&atilde;o h&aacute; meses. Com o Campeonato do Mundo, a situa&ccedil;&atilde;o inverteu-se.<\/p>\n\n\n\n<p>Na sua compar&ecirc;ncia perante a assembleia geral da federa&ccedil;&atilde;o, em que Rubiales tentou justificar o injustific&aacute;vel depois de at&eacute; o atual presidente do governo, Pedro S&aacute;nchez, o ter chamado &agrave; responsabilidade pelo beijo n&atilde;o consentido, <strong>o dirigente exibiu descaradamente todas as caracter&iacute;sticas de um manual machista: nega&ccedil;&atilde;o, arrog&acirc;ncia e superioridade moral, bem como um ego sobredimensionado que tentou esconder com uma pat&eacute;tica vitimiza&ccedil;&atilde;o.<\/strong><\/p>\n\n\n\n<p><strong>Um homem assim &eacute; incapaz de compreender que as mulheres que ele e um dos seus correligion&aacute;rios (o treinador Jorge Vilda) tornaram campe&atilde;s do mundo n&atilde;o lhe prestam homenagem.<\/strong> Foi por isso que mostrou as virilhas no balne&aacute;rio, sem se importar onde estava, quem estava &agrave; sua volta ou que milh&otilde;es de olhos (muitos deles crian&ccedil;as) em todo o mundo estavam a ver. Foi por isso que apalpou os jogadores na cerim&oacute;nia de entrega dos pr&eacute;mios como se fossem os seus brinquedos. Foi por isso que deu um beijo na boca de Jennifer Hermoso e considerou-o &ldquo;normal&rdquo;. Foi por isso que se escandalizou e se sentiu v&iacute;tima de uma ca&ccedil;ada, quando a sociedade em geral o interpretou como um abuso. Foi por isso que se manteve &ndash; e continua a manter-se &ndash; inamov&iacute;vel na sua posi&ccedil;&atilde;o, dando pontap&eacute;s e gritando como uma crian&ccedil;a pequena a quem tiraram o brinquedo preferido.<\/p>\n\n\n\n<p>A Federa&ccedil;&atilde;o era mais do que isso para ele. Era o seu reino, essa estrutura de poder entorpecente dominada por homens de outra era, onde est&atilde;o em jogo tanto dinheiro e tantos interesses que at&eacute; as vozes que j&aacute; n&atilde;o se sentem confort&aacute;veis com o discurso do homem das cavernas se calam e o aplaudem submissamente.<\/p>\n\n\n\n<p>A julgar pelos seus coment&aacute;rios posteriores, pode ser o caso do treinador da equipa masculina, Luis de la Fuente, que at&eacute; se levantou para aplaudir quando Rubiales falou de &ldquo;falso <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Feminismo&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Movimento social e pol&iacute;tico que luta pela igualdade de direitos entre homens e mulheres, opondo-se &agrave; discrimina&ccedil;&atilde;o com base no g&eacute;nero.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/trad-life-uma-escolha-feminista\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Trad-life: uma escolha feminista?.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/8-m-denuncia-a-discriminacao-invisivel-dos-prestadores-de-cuidados\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;8-M denuncia a discrimina&ccedil;&atilde;o invis&iacute;vel dos prestadores de cuidados&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/feminismo\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">feminismo<\/a>&rdquo; e disse dias depois que n&atilde;o se reconhecia na pessoa que aplaudiu com tanto entusiasmo.<\/p>\n\n\n\n<p>Vilda, o treinador da equipa feminina, tamb&eacute;m disse n&atilde;o partilhar algumas das opini&otilde;es de Rubiales, que tamb&eacute;m aplaudiu. Como sempre, isto aconteceu depois do evento, quando os pol&iacute;ticos nacionais e a opini&atilde;o internacional j&aacute; tinham condenado a atitude do presidente e apelado &agrave;s inst&acirc;ncias competentes para que tomassem medidas para o destituir do cargo.<\/p>\n\n\n\n<p>Com algumas honrosas exce&ccedil;&otilde;es (Borja Iglesias, Isco, do Sevilha, e o guarda-redes David de Gea), <strong>o futebol masculino permaneceu mudo durante dias. O seu sil&ecirc;ncio foi eloquente. <\/strong>Tanto mais que as suas cong&eacute;neres femininas emitiram um comunicado conjunto a declarar que &ldquo;isto acabou&rdquo;. Foram necess&aacute;rias quase duas semanas para que a equipa feminina espanhola tornasse p&uacute;blica a sua posi&ccedil;&atilde;o: &ldquo;Queremos repudiar o que consideramos ser o comportamento inaceit&aacute;vel do Sr. Rubiales, que n&atilde;o esteve &agrave; altura da institui&ccedil;&atilde;o que representa. Estamos firme e claramente do lado dos valores que o desporto representa. O futebol espanhol deve ser um motor de respeito, inspira&ccedil;&atilde;o, igualdade e diversidade, dando o exemplo no seu comportamento dentro e fora do campo&rdquo;. A mensagem &eacute; irrepreens&iacute;vel. Agora s&oacute; falta que todos acreditem nela e ajam em conformidade.<\/p>\n\n\n\n<p><strong>As reivindica&ccedil;&otilde;es das mulheres<\/strong><\/p>\n\n\n\n<p>Em contraste com a imobilidade e a tibieza dos homens, as mulheres aproveitaram os holofotes que tinham ganho para denunciar e fazer ouvir as suas exig&ecirc;ncias. &ldquo;Estou muito magoada com o que aconteceu depois da final&rdquo;, disse a treinadora da Inglaterra, Sarina Wiegman, depois de receber o pr&eacute;mio de Treinador do Ano na Gala da UEFA. &ldquo;Esta equipa [Espanha] devia ser celebrada e ouvida. Pe&ccedil;o uma salva de palmas e dedico-lhes este trof&eacute;u&rdquo;, continuou. Na altura, Rubiales ainda era presidente &ndash; a FIFA tinha-o suspendido temporariamente &ndash; e a federa&ccedil;&atilde;o estava a fazer gestos de cosm&eacute;tica.<\/p>\n\n\n\n<p>E &eacute; isso que os jogadores espanh&oacute;is continuam a denunciar. Enquanto o caso de Hermoso continua a avan&ccedil;ar nos tribunais, os seus companheiros de equipa dizem que a demiss&atilde;o de Rubiales e a destitui&ccedil;&atilde;o de Vilda n&atilde;o s&atilde;o suficientes. Exigem uma verdadeira mudan&ccedil;a na federa&ccedil;&atilde;o, que continua a ser dominada pelos capangas do antigo presidente, e na estrutura que envolve a sele&ccedil;&atilde;o nacional feminina.<\/p>\n\n\n\n<p>A nova treinadora espanhola, Montse Tom&eacute;, foi obrigada a adiar por v&aacute;rios dias o an&uacute;ncio do seu plantel para o pr&oacute;ximo desafio, a Ta&ccedil;a das Na&ccedil;&otilde;es, que antecede os Jogos Ol&iacute;mpicos de Paris, porque 21 das 23 jogadoras do Campeonato do Mundo e outras 18 internacionais mantiveram a sua posi&ccedil;&atilde;o de n&atilde;o regressarem &agrave; sele&ccedil;&atilde;o nacional enquanto n&atilde;o lhes fossem asseguradas as mudan&ccedil;as estruturais que exigem.<\/p>\n\n\n\n<p>&ldquo;Os acontecimentos a que infelizmente todos puderam assistir n&atilde;o s&atilde;o &uacute;nicos e ultrapassam as quest&otilde;es desportivas. Temos de ter toler&acirc;ncia zero para estes actos, pelo nosso companheiro, por n&oacute;s e por todas as mulheres&rdquo;, afirmam as jogadoras num novo comunicado. Na carta, as jogadoras enumeram as mudan&ccedil;as que pretendem ver: uma reestrutura&ccedil;&atilde;o da organiza&ccedil;&atilde;o do futebol feminino (com a nomea&ccedil;&atilde;o de um novo diretor e mudan&ccedil;as na equipa t&eacute;cnica); uma remodela&ccedil;&atilde;o do gabinete presidencial e do secret&aacute;rio-geral (Andreu Camps); a demiss&atilde;o do presidente da Real Federa&ccedil;&atilde;o Espanhola de Futebol (RFEF) (Pedro Rocha); uma reestrutura&ccedil;&atilde;o do departamento de comunica&ccedil;&atilde;o e marketing; e uma reestrutura&ccedil;&atilde;o do departamento de integridade.<\/p>\n\n\n\n<p>&ldquo;Hoje &eacute; o in&iacute;cio de uma nova fase. Estamos a mudar a estrutura e estou confiante de que faremos um bom trabalho, que estaremos num ambiente seguro e que os jogadores poder&atilde;o desenvolver a sua profiss&atilde;o como merecem&rdquo;, disse Montse Tom&eacute; depois de anunciar a lista de convocados, que inclui 15 campe&otilde;es do mundo, 19 dos signat&aacute;rios da declara&ccedil;&atilde;o que pedia a mudan&ccedil;a e quatro dos 15 que n&atilde;o regressaram &agrave; sele&ccedil;&atilde;o nacional para o Mundial (Mapi Le&oacute;n, Patri Guijarro, Amaiur Sarriegi e Luc&iacute;a Garc&iacute;a), mas n&atilde;o Jennifer Hermoso, &ldquo;para a proteger&rdquo;, segundo a treinadora.<\/p>\n\n\n\n<p>&ldquo;Proteger-me de qu&ecirc;, ou de quem?&rdquo;, respondeu Hermoso numa declara&ccedil;&atilde;o em que expressava a sua solidariedade para com as suas colegas de equipa. As jogadoras tamb&eacute;m deixaram claro que a sua posi&ccedil;&atilde;o n&atilde;o tinha mudado, que tinham sido convocadas contra a sua vontade e que estavam a considerar n&atilde;o responder &agrave; chamada do treinador. A for&ccedil;a com que responderam ao desafio da Federa&ccedil;&atilde;o levou o governo a intervir mais uma vez atrav&eacute;s do Consejo Superior del Deporte (CSD).<\/p>\n\n\n\n<p>Ap&oacute;s horas de reuni&otilde;es entre as duas partes, chegou-se a um acordo para evitar o embara&ccedil;o internacional que seria disputar a Ta&ccedil;a das Na&ccedil;&otilde;es sem os campe&otilde;es do mundo: 21 dos 23 jogadores convocados v&atilde;o disputar os dois pr&oacute;ximos jogos. Mapi Le&oacute;n e Patri Guijarro n&atilde;o jogar&atilde;o. Os jogadores alegaram que tinham sido convocados quando foram declarados ineleg&iacute;veis e n&atilde;o se sentiam em condi&ccedil;&otilde;es de jogar. Os jogadores conseguiram evitar ser sancionados pela sua recusa.<\/p>\n\n\n\n<p>N&atilde;o foi o &uacute;nico sucesso: chegaram a uma s&eacute;rie de acordos em que a federa&ccedil;&atilde;o e o CDS se comprometem a &ldquo;trabalhar em conjunto&rdquo; e a uma comiss&atilde;o tripartida mista [federa&ccedil;&atilde;o, CDS e jogadores] para dar seguimento a esses acordos, em que o organismo governamental se compromete a avan&ccedil;ar nas &ldquo;<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Pol&iacute;ticas de g&eacute;nero&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;As pol&iacute;ticas de g&eacute;nero s&atilde;o estrat&eacute;gias e a&ccedil;&otilde;es governamentais ou institucionais concebidas para abordar e eliminar as desigualdades e a discrimina&ccedil;&atilde;o entre homens e mulheres e para promover a igualdade de oportunidades e de direitos entre homens e mulheres.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/politicas-de-genero\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">pol&iacute;ticas de g&eacute;nero<\/a>, igualdade salarial e melhoria das infraestruturas, bem como a clarificar a agress&atilde;o sexual e a classific&aacute;-la como crime muito grave quando cometida no dom&iacute;nio do desporto&rdquo;. A Federa&ccedil;&atilde;o comprometeu-se a efetuar sem demora as mudan&ccedil;as estruturais exigidas pelas futebolistas.<\/p>\n\n\n\n<p>A batalha n&atilde;o termina aqui. As mulheres est&atilde;o numa posi&ccedil;&atilde;o forte para acelerar as mudan&ccedil;as que pretendem e quebrar um novo teto de vidro e, como j&aacute; demonstraram, est&atilde;o dispostas a sacrificar-se para o fazer. Alexia Putellas, duas vezes vencedora da Bola de Ouro, deixou isso bem claro quando aceitou a Medalha de Ouro de Honra da Generalitat para o Barcelona Femen&iacute; (futebol feminino): &ldquo;N&atilde;o vamos ficar por aqui. Estamos aqui para ficar e ajudar os que vierem depois de n&oacute;s. Precisamos de consenso, coragem e lideran&ccedil;a por parte das institui&ccedil;&otilde;es. N&atilde;o vos vamos desiludir&rdquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A 20 de agosto, a sele&ccedil;&atilde;o nacional de futebol feminino venceu o Campeonato do Mundo e, 30 dias depois, as campe&atilde;s cumpriram a promessa de mudan&ccedil;as profundas na Federa&ccedil;&atilde;o. Pelo meio, o chamado &quot;caso Rubiales&quot;, o esc&acirc;ndalo que exp&ocirc;s o <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Machismo&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;A cren&ccedil;a na superioridade dos homens sobre as mulheres, que perpetua os pap&eacute;is e estere&oacute;tipos de g&eacute;nero que limitam a igualdade e perpetuam a discrimina&ccedil;&atilde;o e a desigualdade.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/machismo\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">machismo<\/a> e os abusos de poder de que as mulheres eram alvo. A sua coragem provocou uma verdadeira revolu&ccedil;&atilde;o. Esta &eacute; a hist&oacute;ria de uma dupla vit&oacute;ria<\/p>\n","protected":false},"author":32,"featured_media":13847,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[365,483],"tags":[186,134],"coauthors":[154],"class_list":{"0":"post-13852","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-eventos-historicos","8":"category-sociedade-e-cultura","9":"tag-igualdad-pt-pt","10":"tag-igualdade"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>As duas vit\u00f3rias das campe\u00e3s do mundo - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"As duas vit\u00f3rias das campe\u00e3s do mundo - xqthenews\" \/>\n<meta property=\"og:description\" content=\"A 20 de agosto, a sele&ccedil;&atilde;o nacional de futebol feminino venceu o Campeonato do Mundo e, 30 dias depois, as campe&atilde;s cumpriram a promessa de mudan&ccedil;as profundas na Federa&ccedil;&atilde;o. Pelo meio, o chamado &quot;caso Rubiales&quot;, o esc&acirc;ndalo que exp&ocirc;s o machismo e os abusos de poder de que as mulheres eram alvo. A sua coragem provocou uma verdadeira revolu&ccedil;&atilde;o. Esta &eacute; a hist&oacute;ria de uma dupla vit&oacute;ria\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-16T14:53:13+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-10T22:10:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2023\/11\/msg701610333-1416.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"810\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Noelia Rom\u00e1n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Noelia Rom\u00e1n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo estimado de leitura\" \/>\n\t<meta name=\"twitter:data2\" content=\"16 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Noelia Rom\u00e1n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/as-duas-vitorias-das-campeas-do-mundo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/as-duas-vitorias-das-campeas-do-mundo\\\/\"},\"author\":{\"name\":\"Noelia Rom\u00e1n\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/79ee46753f092f99662c6af8fb61ee47\"},\"headline\":\"As duas vit\u00f3rias das campe\u00e3s do mundo\",\"datePublished\":\"2023-11-16T14:53:13+00:00\",\"dateModified\":\"2024-09-10T22:10:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/as-duas-vitorias-das-campeas-do-mundo\\\/\"},\"wordCount\":3150,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/as-duas-vitorias-das-campeas-do-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/msg701610333-1416.jpg\",\"keywords\":[\"Igualdad\",\"Igualdade\"],\"articleSection\":[\"Eventos hist\u00f3ricos\",\"Sociedade e cultura\"],\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/as-duas-vitorias-das-campeas-do-mundo\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/as-duas-vitorias-das-campeas-do-mundo\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/as-duas-vitorias-das-campeas-do-mundo\\\/\",\"name\":\"As duas vit\u00f3rias das campe\u00e3s do mundo - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/as-duas-vitorias-das-campeas-do-mundo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/as-duas-vitorias-das-campeas-do-mundo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/msg701610333-1416.jpg\",\"datePublished\":\"2023-11-16T14:53:13+00:00\",\"dateModified\":\"2024-09-10T22:10:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/79ee46753f092f99662c6af8fb61ee47\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/as-duas-vitorias-das-campeas-do-mundo\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/as-duas-vitorias-das-campeas-do-mundo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/as-duas-vitorias-das-campeas-do-mundo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/msg701610333-1416.jpg\",\"contentUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/msg701610333-1416.jpg\",\"width\":1280,\"height\":810},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/as-duas-vitorias-das-campeas-do-mundo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"As duas vit\u00f3rias das campe\u00e3s do mundo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/79ee46753f092f99662c6af8fb61ee47\",\"name\":\"Noelia Rom\u00e1n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-PT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a08477d6966012c1b71f368ceece95dd8aac13940fd67cda4da03e91f9ff681?s=96&d=mm&r=g6b39c6de9940c167d077c5e1fddf7782\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a08477d6966012c1b71f368ceece95dd8aac13940fd67cda4da03e91f9ff681?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6a08477d6966012c1b71f368ceece95dd8aac13940fd67cda4da03e91f9ff681?s=96&d=mm&r=g\",\"caption\":\"Noelia Rom\u00e1n\"},\"url\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/author\\\/noeliaroman\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"As duas vit\u00f3rias das campe\u00e3s do mundo - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/","og_locale":"pt_PT","og_type":"article","og_title":"As duas vit\u00f3rias das campe\u00e3s do mundo - xqthenews","og_description":"A 20 de agosto, a sele&ccedil;&atilde;o nacional de futebol feminino venceu o Campeonato do Mundo e, 30 dias depois, as campe&atilde;s cumpriram a promessa de mudan&ccedil;as profundas na Federa&ccedil;&atilde;o. Pelo meio, o chamado &quot;caso Rubiales&quot;, o esc&acirc;ndalo que exp&ocirc;s o machismo e os abusos de poder de que as mulheres eram alvo. A sua coragem provocou uma verdadeira revolu&ccedil;&atilde;o. Esta &eacute; a hist&oacute;ria de uma dupla vit&oacute;ria","og_url":"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/","og_site_name":"xqthenews","article_published_time":"2023-11-16T14:53:13+00:00","article_modified_time":"2024-09-10T22:10:00+00:00","og_image":[{"width":1280,"height":810,"url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2023\/11\/msg701610333-1416.jpg","type":"image\/jpeg"}],"author":"Noelia Rom\u00e1n","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Noelia Rom\u00e1n","Tempo estimado de leitura":"16 minutos","Written by":"Noelia Rom\u00e1n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/#article","isPartOf":{"@id":"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/"},"author":{"name":"Noelia Rom\u00e1n","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/79ee46753f092f99662c6af8fb61ee47"},"headline":"As duas vit\u00f3rias das campe\u00e3s do mundo","datePublished":"2023-11-16T14:53:13+00:00","dateModified":"2024-09-10T22:10:00+00:00","mainEntityOfPage":{"@id":"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/"},"wordCount":3150,"commentCount":0,"image":{"@id":"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2023\/11\/msg701610333-1416.jpg","keywords":["Igualdad","Igualdade"],"articleSection":["Eventos hist\u00f3ricos","Sociedade e cultura"],"inLanguage":"pt-PT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/","url":"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/","name":"As duas vit\u00f3rias das campe\u00e3s do mundo - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/#primaryimage"},"image":{"@id":"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2023\/11\/msg701610333-1416.jpg","datePublished":"2023-11-16T14:53:13+00:00","dateModified":"2024-09-10T22:10:00+00:00","author":{"@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/79ee46753f092f99662c6af8fb61ee47"},"breadcrumb":{"@id":"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/"]}]},{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/#primaryimage","url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2023\/11\/msg701610333-1416.jpg","contentUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2023\/11\/msg701610333-1416.jpg","width":1280,"height":810},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/pt-pt\/as-duas-vitorias-das-campeas-do-mundo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"As duas vit\u00f3rias das campe\u00e3s do mundo"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"},{"@type":"Person","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/79ee46753f092f99662c6af8fb61ee47","name":"Noelia Rom\u00e1n","image":{"@type":"ImageObject","inLanguage":"pt-PT","@id":"https:\/\/secure.gravatar.com\/avatar\/6a08477d6966012c1b71f368ceece95dd8aac13940fd67cda4da03e91f9ff681?s=96&d=mm&r=g6b39c6de9940c167d077c5e1fddf7782","url":"https:\/\/secure.gravatar.com\/avatar\/6a08477d6966012c1b71f368ceece95dd8aac13940fd67cda4da03e91f9ff681?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6a08477d6966012c1b71f368ceece95dd8aac13940fd67cda4da03e91f9ff681?s=96&d=mm&r=g","caption":"Noelia Rom\u00e1n"},"url":"https:\/\/xqthenews.com\/pt-pt\/author\/noeliaroman\/"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/posts\/13852","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/users\/32"}],"replies":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/comments?post=13852"}],"version-history":[{"count":0,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/posts\/13852\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/media\/13847"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=13852"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/categories?post=13852"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/tags?post=13852"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/coauthors?post=13852"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}