{"id":28527,"date":"2025-03-18T11:45:51","date_gmt":"2025-03-18T10:45:51","guid":{"rendered":"https:\/\/xqthenews.com\/glossary\/parteira\/"},"modified":"2025-03-18T12:53:15","modified_gmt":"2025-03-18T11:53:15","slug":"parteira","status":"publish","type":"glossary","link":"https:\/\/xqthenews.com\/pt-pt\/glossary\/parteira\/","title":{"rendered":"Parteira"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Uma profissional de sa&uacute;de especializada na gravidez, no parto e no p&oacute;s-parto. Acompanha as mulheres durante o processo de parto e presta cuidados &agrave; m&atilde;e e ao rec&eacute;m-nascido. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uma profissional de sa&uacute;de especializada na gravidez, no parto e no p&oacute;s-parto. Acompanha as mulheres durante o processo de parto e presta cuidados &agrave; m&atilde;e e ao rec&eacute;m-nascido.<\/p>\n","protected":false},"author":27,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[152],"class_list":["post-28527","glossary","type-glossary","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Parteira - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/parteira\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Parteira - xqthenews\" \/>\n<meta property=\"og:description\" content=\"Uma profissional de sa&uacute;de especializada na gravidez, no parto e no p&oacute;s-parto. Acompanha as mulheres durante o processo de parto e presta cuidados &agrave; m&atilde;e e ao rec&eacute;m-nascido.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/parteira\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-18T11:53:15+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Le\u00f3n Var\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/parteira\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/parteira\\\/\",\"name\":\"Parteira - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"datePublished\":\"2025-03-18T10:45:51+00:00\",\"dateModified\":\"2025-03-18T11:53:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/parteira\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/parteira\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/parteira\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Parteira\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Parteira - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/pt-pt\/glossary\/parteira\/","og_locale":"pt_PT","og_type":"article","og_title":"Parteira - xqthenews","og_description":"Uma profissional de sa&uacute;de especializada na gravidez, no parto e no p&oacute;s-parto. Acompanha as mulheres durante o processo de parto e presta cuidados &agrave; m&atilde;e e ao rec&eacute;m-nascido.","og_url":"https:\/\/xqthenews.com\/pt-pt\/glossary\/parteira\/","og_site_name":"xqthenews","article_modified_time":"2025-03-18T11:53:15+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Manuel Le\u00f3n Var\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/pt-pt\/glossary\/parteira\/","url":"https:\/\/xqthenews.com\/pt-pt\/glossary\/parteira\/","name":"Parteira - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"datePublished":"2025-03-18T10:45:51+00:00","dateModified":"2025-03-18T11:53:15+00:00","breadcrumb":{"@id":"https:\/\/xqthenews.com\/pt-pt\/glossary\/parteira\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/pt-pt\/glossary\/parteira\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/pt-pt\/glossary\/parteira\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Parteira"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/glossary\/28527","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":1,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/glossary\/28527\/revisions"}],"predecessor-version":[{"id":28528,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/glossary\/28527\/revisions\/28528"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=28527"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/coauthors?post=28527"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}