{"id":26820,"date":"2024-12-17T12:52:47","date_gmt":"2024-12-17T11:52:47","guid":{"rendered":"https:\/\/xqthenews.com\/glossary\/zero-residuos\/"},"modified":"2024-12-17T12:58:36","modified_gmt":"2024-12-17T11:58:36","slug":"zero-residuos","status":"publish","type":"glossary","link":"https:\/\/xqthenews.com\/pt-pt\/glossary\/zero-residuos\/","title":{"rendered":"Zero Res\u00edduos"},"content":{"rendered":"<p>O movimento <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Zero Res&iacute;duos&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;O movimento Zero Res&iacute;duos &eacute; um movimento de estilo de vida promovido, entre outros, por Paul Palmer no seu livro &amp;lt;em&amp;gt;Getting to Zero Waste&amp;lt;\/em&amp;gt;. Defende a redu&ccedil;&atilde;o dos res&iacute;duos gerados na vida quotidiana das pessoas, a fim de atenuar os efeitos das altera&ccedil;&otilde;es clim&aacute;ticas, cuidar da natureza e viver de forma mais simples e consciente. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/zero-residuos\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Zero Res&iacute;duos<\/a> &eacute; um movimento de estilo de vida promovido, entre outros, por Paul Palmer no seu livro <em>Getting to Zero Waste<\/em>. Defende a redu&ccedil;&atilde;o dos res&iacute;duos gerados na vida quotidiana das pessoas, a fim de atenuar os efeitos das <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Altera&ccedil;&otilde;es clim&aacute;ticas&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Causadas pelo aquecimento global, as altera&ccedil;&otilde;es clim&aacute;ticas referem-se &agrave;s varia&ccedil;&otilde;es dos padr&otilde;es meteorol&oacute;gicos de longo prazo na Terra, como a temperatura, os n&iacute;veis do mar e a precipita&ccedil;&atilde;o. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;A principal causa das altera&ccedil;&otilde;es clim&aacute;ticas &eacute; a combust&atilde;o de combust&iacute;veis f&oacute;sseis como o petr&oacute;leo, o carv&atilde;o e o g&aacute;s natural, que emitem gases com efeito de estufa para a atmosfera. Outras atividades humanas, como a agricultura e a desfloresta&ccedil;&atilde;o, tamb&eacute;m contribuem para a sua prolifera&ccedil;&atilde;o. O problema &eacute; que estes gases captam o calor na atmosfera: &eacute; o chamado efeito de estufa.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;(Fonte: European Youth Portal)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/movimentos-de-jovens-na-europa-pelas-respostas-a-crise-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Movimentos de jovens na Europa pelas respostas &agrave; crise clim&aacute;tica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/a-tua-lancheira-de-plastico-esta-a-poluir-o-planeta-e-o-seu-sistema-endocrino\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A tua lancheira de pl&aacute;stico est&aacute; a poluir o planeta e o seu sistema end&oacute;crino.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/economia-circular-materia-organica-en-el-pasado-el-presente-y-el-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A mat&eacute;ria org&acirc;nica no passado, presente e futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/cimeira-mundial-do-clima-cop-28-no-dubai\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Cimeira Mundial do Clima COP 28 no Dubai&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/emergencia-climatica-e-os-desafios-para-a-saude\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Emerg&ecirc;ncia clim&aacute;tica e os desafios para a sa&uacute;de&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/alteracoes-climaticas\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">altera&ccedil;&otilde;es clim&aacute;ticas<\/a>, cuidar da <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Natureza&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;A natureza &eacute; um termo amplo que se refere a tudo o que existe no mundo natural, incluindo todos os seres vivos, plantas, animais, ecossistemas, paisagens, fen&oacute;menos naturais e recursos naturais. &Eacute; o conjunto de elementos que comp&otilde;em o ambiente em que vivemos, incluindo o ar, a &aacute;gua, o solo e a biodiversidade. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;(Fonte: S&oacute; Escola)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/economia-circular-materia-organica-en-el-pasado-el-presente-y-el-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A mat&eacute;ria org&acirc;nica no passado, presente e futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/o-papel-da-juventude-na-transicao-ecologica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;O papel da juventude na transi&ccedil;&atilde;o ecol&oacute;gica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/o-impacto-das-alteracoes-climaticas-no-sul-de-italia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;O impacto das altera&ccedil;&otilde;es clim&aacute;ticas no sul de It&aacute;lia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/dana-de-outono-no-mediterraneo-depois-da-tempestade-nao-ha-calma\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;DANA de outono no Mediterr&acirc;neo: depois da tempestade, n&atilde;o h&aacute; calma&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/restaurar-a-natureza-exemplos-de-sucesso-na-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Restaurar a Natureza &ndash; Exemplos de sucesso na Europa&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\"  href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/natureza\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>natureza<\/a> e viver de forma mais simples e consciente. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>O movimento <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Zero Res&iacute;duos&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;O movimento Zero Res&iacute;duos &eacute; um movimento de estilo de vida promovido, entre outros, por Paul Palmer no seu livro &amp;lt;em&amp;gt;Getting to Zero Waste&amp;lt;\/em&amp;gt;. Defende a redu&ccedil;&atilde;o dos res&iacute;duos gerados na vida quotidiana das pessoas, a fim de atenuar os efeitos das altera&ccedil;&otilde;es clim&aacute;ticas, cuidar da natureza e viver de forma mais simples e consciente. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/zero-residuos\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Zero Res&iacute;duos<\/a> &eacute; um movimento de estilo de vida promovido, entre outros, por Paul Palmer no seu livro Getting to Zero Waste. Defende a redu&ccedil;&atilde;o dos res&iacute;duos gerados na vida quotidiana das pessoas, a fim de atenuar os efeitos das <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Altera&ccedil;&otilde;es clim&aacute;ticas&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Causadas pelo aquecimento global, as altera&ccedil;&otilde;es clim&aacute;ticas referem-se &agrave;s varia&ccedil;&otilde;es dos padr&otilde;es meteorol&oacute;gicos de longo prazo na Terra, como a temperatura, os n&iacute;veis do mar e a precipita&ccedil;&atilde;o. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;A principal causa das altera&ccedil;&otilde;es clim&aacute;ticas &eacute; a combust&atilde;o de combust&iacute;veis f&oacute;sseis como o petr&oacute;leo, o carv&atilde;o e o g&aacute;s natural, que emitem gases com efeito de estufa para a atmosfera. Outras atividades humanas, como a agricultura e a desfloresta&ccedil;&atilde;o, tamb&eacute;m contribuem para a sua prolifera&ccedil;&atilde;o. O problema &eacute; que estes gases captam o calor na atmosfera: &eacute; o chamado efeito de estufa.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;(Fonte: European Youth Portal)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/movimentos-de-jovens-na-europa-pelas-respostas-a-crise-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Movimentos de jovens na Europa pelas respostas &agrave; crise clim&aacute;tica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/a-tua-lancheira-de-plastico-esta-a-poluir-o-planeta-e-o-seu-sistema-endocrino\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A tua lancheira de pl&aacute;stico est&aacute; a poluir o planeta e o seu sistema end&oacute;crino.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/economia-circular-materia-organica-en-el-pasado-el-presente-y-el-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A mat&eacute;ria org&acirc;nica no passado, presente e futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/cimeira-mundial-do-clima-cop-28-no-dubai\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Cimeira Mundial do Clima COP 28 no Dubai&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/emergencia-climatica-e-os-desafios-para-a-saude\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Emerg&ecirc;ncia clim&aacute;tica e os desafios para a sa&uacute;de&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/alteracoes-climaticas\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">altera&ccedil;&otilde;es clim&aacute;ticas<\/a>, cuidar da <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Natureza&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;A natureza &eacute; um termo amplo que se refere a tudo o que existe no mundo natural, incluindo todos os seres vivos, plantas, animais, ecossistemas, paisagens, fen&oacute;menos naturais e recursos naturais. &Eacute; o conjunto de elementos que comp&otilde;em o ambiente em que vivemos, incluindo o ar, a &aacute;gua, o solo e a biodiversidade. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;(Fonte: S&oacute; Escola)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/economia-circular-materia-organica-en-el-pasado-el-presente-y-el-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A mat&eacute;ria org&acirc;nica no passado, presente e futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/o-papel-da-juventude-na-transicao-ecologica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;O papel da juventude na transi&ccedil;&atilde;o ecol&oacute;gica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/o-impacto-das-alteracoes-climaticas-no-sul-de-italia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;O impacto das altera&ccedil;&otilde;es clim&aacute;ticas no sul de It&aacute;lia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/dana-de-outono-no-mediterraneo-depois-da-tempestade-nao-ha-calma\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;DANA de outono no Mediterr&acirc;neo: depois da tempestade, n&atilde;o h&aacute; calma&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/restaurar-a-natureza-exemplos-de-sucesso-na-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Restaurar a Natureza &ndash; Exemplos de sucesso na Europa&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/natureza\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">natureza<\/a> e viver de forma mais simples e consciente.<\/p>\n","protected":false},"author":27,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[152],"class_list":["post-26820","glossary","type-glossary","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Zero Res\u00edduos - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/zero-residuos\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Zero Res\u00edduos - xqthenews\" \/>\n<meta property=\"og:description\" content=\"O movimento Zero Res&iacute;duos &eacute; um movimento de estilo de vida promovido, entre outros, por Paul Palmer no seu livro Getting to Zero Waste. Defende a redu&ccedil;&atilde;o dos res&iacute;duos gerados na vida quotidiana das pessoas, a fim de atenuar os efeitos das altera&ccedil;&otilde;es clim&aacute;ticas, cuidar da natureza e viver de forma mais simples e consciente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/zero-residuos\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-17T11:58:36+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Le\u00f3n Var\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/zero-residuos\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/zero-residuos\\\/\",\"name\":\"Zero Res\u00edduos - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"datePublished\":\"2024-12-17T11:52:47+00:00\",\"dateModified\":\"2024-12-17T11:58:36+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/zero-residuos\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/zero-residuos\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/zero-residuos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Zero Res\u00edduos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Zero Res\u00edduos - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/pt-pt\/glossary\/zero-residuos\/","og_locale":"pt_PT","og_type":"article","og_title":"Zero Res\u00edduos - xqthenews","og_description":"O movimento Zero Res&iacute;duos &eacute; um movimento de estilo de vida promovido, entre outros, por Paul Palmer no seu livro Getting to Zero Waste. Defende a redu&ccedil;&atilde;o dos res&iacute;duos gerados na vida quotidiana das pessoas, a fim de atenuar os efeitos das altera&ccedil;&otilde;es clim&aacute;ticas, cuidar da natureza e viver de forma mais simples e consciente.","og_url":"https:\/\/xqthenews.com\/pt-pt\/glossary\/zero-residuos\/","og_site_name":"xqthenews","article_modified_time":"2024-12-17T11:58:36+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Manuel Le\u00f3n Var\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/pt-pt\/glossary\/zero-residuos\/","url":"https:\/\/xqthenews.com\/pt-pt\/glossary\/zero-residuos\/","name":"Zero Res\u00edduos - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"datePublished":"2024-12-17T11:52:47+00:00","dateModified":"2024-12-17T11:58:36+00:00","breadcrumb":{"@id":"https:\/\/xqthenews.com\/pt-pt\/glossary\/zero-residuos\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/pt-pt\/glossary\/zero-residuos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/pt-pt\/glossary\/zero-residuos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Zero Res\u00edduos"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/glossary\/26820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":1,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/glossary\/26820\/revisions"}],"predecessor-version":[{"id":26821,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/glossary\/26820\/revisions\/26821"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=26820"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/coauthors?post=26820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}