{"id":13984,"date":"2023-11-15T19:11:57","date_gmt":"2023-11-15T19:11:57","guid":{"rendered":"https:\/\/sad-borg.82-223-8-23.plesk.page\/glossary\/territorios-palestinianos-ocupados\/"},"modified":"2023-11-16T10:18:08","modified_gmt":"2023-11-16T10:18:08","slug":"territorios-palestinianos-ocupados","status":"publish","type":"glossary","link":"https:\/\/xqthenews.com\/pt-pt\/glossary\/territorios-palestinianos-ocupados\/","title":{"rendered":"Territ\u00f3rios Palestinianos Ocupados"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Os &ldquo;<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Territ&oacute;rios Palestinianos Ocupados&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Os &amp;quot;Territ&oacute;rios Palestinianos Ocupados&amp;quot; referem-se a &aacute;reas como a Cisjord&acirc;nia e Gaza sob controlo israelita ap&oacute;s a guerra de 1967.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/territorios-palestinianos-ocupados\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Territ&oacute;rios Palestinianos Ocupados<\/a>&rdquo; referem-se a &aacute;reas como a Cisjord&acirc;nia e Gaza sob controlo israelita ap&oacute;s a <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidade, conflito armado entre duas ou mais na&ccedil;&otilde;es livres ou entre fac&ccedil;&otilde;es de um mesmo Estado. Traz a morte e a destrui&ccedil;&atilde;o de recursos e bens e tem por objectivo impor a vontade dos vencedores aos vencidos.&amp;lt;br&amp;gt;Com as guerras, muitos pa&iacute;ses ficaram arruinados e endividados.  &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/plastico-inunda-os-mares-cronica-de-um-novo-ecocidio-na-costa-galega\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Pl&aacute;stico inunda os mares: cr&oacute;nica de um novo ecoc&iacute;dio na costa galega&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/repowereu-e-a-independencia-energetica-europeia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;RePowerEu e a independ&ecirc;ncia energ&eacute;tica europeia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/equidade-de-genero-e-o-impulso-para-a-acao-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Equidade de G&eacute;nero e o Impulso para a A&ccedil;&atilde;o Clim&aacute;tica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/zelenski-a-dignidade-da-ucrania-face-a-putin-e-trump\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Zelenski: A dignidade da Ucr&acirc;nia face a Putin e Trump&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/as-distopias-tornam-se-realidade-o-mundo-atual-atraves-do-prisma-da-ficcao\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;As distopias tornam-se realidade: o mundo atual atrav&eacute;s do prisma da fic&ccedil;&atilde;o&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\"  href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/guerra\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>guerra<\/a> de 1967.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Os &ldquo;<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Territ&oacute;rios Palestinianos Ocupados&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Os &amp;quot;Territ&oacute;rios Palestinianos Ocupados&amp;quot; referem-se a &aacute;reas como a Cisjord&acirc;nia e Gaza sob controlo israelita ap&oacute;s a guerra de 1967.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/territorios-palestinianos-ocupados\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Territ&oacute;rios Palestinianos Ocupados<\/a>&rdquo; referem-se a &aacute;reas como a Cisjord&acirc;nia e Gaza sob controlo israelita ap&oacute;s a <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidade, conflito armado entre duas ou mais na&ccedil;&otilde;es livres ou entre fac&ccedil;&otilde;es de um mesmo Estado. Traz a morte e a destrui&ccedil;&atilde;o de recursos e bens e tem por objectivo impor a vontade dos vencedores aos vencidos.&amp;lt;br&amp;gt;Com as guerras, muitos pa&iacute;ses ficaram arruinados e endividados.  &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/plastico-inunda-os-mares-cronica-de-um-novo-ecocidio-na-costa-galega\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Pl&aacute;stico inunda os mares: cr&oacute;nica de um novo ecoc&iacute;dio na costa galega&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/repowereu-e-a-independencia-energetica-europeia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;RePowerEu e a independ&ecirc;ncia energ&eacute;tica europeia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/equidade-de-genero-e-o-impulso-para-a-acao-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Equidade de G&eacute;nero e o Impulso para a A&ccedil;&atilde;o Clim&aacute;tica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/zelenski-a-dignidade-da-ucrania-face-a-putin-e-trump\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Zelenski: A dignidade da Ucr&acirc;nia face a Putin e Trump&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/as-distopias-tornam-se-realidade-o-mundo-atual-atraves-do-prisma-da-ficcao\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;As distopias tornam-se realidade: o mundo atual atrav&eacute;s do prisma da fic&ccedil;&atilde;o&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a> de 1967.<\/p>\n","protected":false},"author":27,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[152],"class_list":["post-13984","glossary","type-glossary","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Territ\u00f3rios Palestinianos Ocupados - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/territorios-palestinianos-ocupados\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Territ\u00f3rios Palestinianos Ocupados - xqthenews\" \/>\n<meta property=\"og:description\" content=\"Os &ldquo;Territ&oacute;rios Palestinianos Ocupados&rdquo; referem-se a &aacute;reas como a Cisjord&acirc;nia e Gaza sob controlo israelita ap&oacute;s a guerra de 1967.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/territorios-palestinianos-ocupados\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-16T10:18:08+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Le\u00f3n Var\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/territorios-palestinianos-ocupados\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/territorios-palestinianos-ocupados\\\/\",\"name\":\"Territ\u00f3rios Palestinianos Ocupados - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"datePublished\":\"2023-11-15T19:11:57+00:00\",\"dateModified\":\"2023-11-16T10:18:08+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/territorios-palestinianos-ocupados\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/territorios-palestinianos-ocupados\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/territorios-palestinianos-ocupados\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Territ\u00f3rios Palestinianos Ocupados\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Territ\u00f3rios Palestinianos Ocupados - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/pt-pt\/glossary\/territorios-palestinianos-ocupados\/","og_locale":"pt_PT","og_type":"article","og_title":"Territ\u00f3rios Palestinianos Ocupados - xqthenews","og_description":"Os &ldquo;Territ&oacute;rios Palestinianos Ocupados&rdquo; referem-se a &aacute;reas como a Cisjord&acirc;nia e Gaza sob controlo israelita ap&oacute;s a guerra de 1967.","og_url":"https:\/\/xqthenews.com\/pt-pt\/glossary\/territorios-palestinianos-ocupados\/","og_site_name":"xqthenews","article_modified_time":"2023-11-16T10:18:08+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Manuel Le\u00f3n Var\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/pt-pt\/glossary\/territorios-palestinianos-ocupados\/","url":"https:\/\/xqthenews.com\/pt-pt\/glossary\/territorios-palestinianos-ocupados\/","name":"Territ\u00f3rios Palestinianos Ocupados - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"datePublished":"2023-11-15T19:11:57+00:00","dateModified":"2023-11-16T10:18:08+00:00","breadcrumb":{"@id":"https:\/\/xqthenews.com\/pt-pt\/glossary\/territorios-palestinianos-ocupados\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/pt-pt\/glossary\/territorios-palestinianos-ocupados\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/pt-pt\/glossary\/territorios-palestinianos-ocupados\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Territ\u00f3rios Palestinianos Ocupados"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/glossary\/13984","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":0,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/glossary\/13984\/revisions"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=13984"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/coauthors?post=13984"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}