{"id":13974,"date":"2023-11-15T19:15:29","date_gmt":"2023-11-15T19:15:29","guid":{"rendered":"https:\/\/sad-borg.82-223-8-23.plesk.page\/glossary\/limiar-de-pobreza\/"},"modified":"2023-11-16T10:15:46","modified_gmt":"2023-11-16T10:15:46","slug":"limiar-de-pobreza","status":"publish","type":"glossary","link":"https:\/\/xqthenews.com\/pt-pt\/glossary\/limiar-de-pobreza\/","title":{"rendered":"Limiar de pobreza"},"content":{"rendered":"<p class=\"wp-block-paragraph\">O &ldquo;<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Limiar de pobreza&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;O &amp;quot;limiar de pobreza&amp;quot; &eacute; o n&iacute;vel m&iacute;nimo de rendimento ou de recursos necess&aacute;rios para satisfazer as necessidades b&aacute;sicas, marcando a fronteira entre a pobreza e a n&atilde;o pobreza.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/limiar-de-pobreza\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">limiar de pobreza<\/a>&rdquo; &eacute; o n&iacute;vel m&iacute;nimo de rendimento ou de recursos necess&aacute;rios para satisfazer as necessidades b&aacute;sicas, marcando a fronteira entre a pobreza e a n&atilde;o pobreza.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O &ldquo;<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Limiar de pobreza&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;O &amp;quot;limiar de pobreza&amp;quot; &eacute; o n&iacute;vel m&iacute;nimo de rendimento ou de recursos necess&aacute;rios para satisfazer as necessidades b&aacute;sicas, marcando a fronteira entre a pobreza e a n&atilde;o pobreza.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/limiar-de-pobreza\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">limiar de pobreza<\/a>&rdquo; &eacute; o n&iacute;vel m&iacute;nimo de rendimento ou de recursos necess&aacute;rios para satisfazer as necessidades b&aacute;sicas, marcando a fronteira entre a pobreza e a n&atilde;o pobreza.<\/p>\n","protected":false},"author":27,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[152],"class_list":["post-13974","glossary","type-glossary","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Limiar de pobreza - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/limiar-de-pobreza\/\" \/>\n<meta property=\"og:locale\" content=\"pt_PT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Limiar de pobreza - xqthenews\" \/>\n<meta property=\"og:description\" content=\"O &ldquo;limiar de pobreza&rdquo; &eacute; o n&iacute;vel m&iacute;nimo de rendimento ou de recursos necess&aacute;rios para satisfazer as necessidades b&aacute;sicas, marcando a fronteira entre a pobreza e a n&atilde;o pobreza.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/pt-pt\/glossary\/limiar-de-pobreza\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-16T10:15:46+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Le\u00f3n Var\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/limiar-de-pobreza\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/limiar-de-pobreza\\\/\",\"name\":\"Limiar de pobreza - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"datePublished\":\"2023-11-15T19:15:29+00:00\",\"dateModified\":\"2023-11-16T10:15:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/limiar-de-pobreza\\\/#breadcrumb\"},\"inLanguage\":\"pt-PT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/limiar-de-pobreza\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/glossary\\\/limiar-de-pobreza\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/pt-pt\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Limiar de pobreza\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-PT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Limiar de pobreza - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/pt-pt\/glossary\/limiar-de-pobreza\/","og_locale":"pt_PT","og_type":"article","og_title":"Limiar de pobreza - xqthenews","og_description":"O &ldquo;limiar de pobreza&rdquo; &eacute; o n&iacute;vel m&iacute;nimo de rendimento ou de recursos necess&aacute;rios para satisfazer as necessidades b&aacute;sicas, marcando a fronteira entre a pobreza e a n&atilde;o pobreza.","og_url":"https:\/\/xqthenews.com\/pt-pt\/glossary\/limiar-de-pobreza\/","og_site_name":"xqthenews","article_modified_time":"2023-11-16T10:15:46+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Manuel Le\u00f3n Var\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/pt-pt\/glossary\/limiar-de-pobreza\/","url":"https:\/\/xqthenews.com\/pt-pt\/glossary\/limiar-de-pobreza\/","name":"Limiar de pobreza - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"datePublished":"2023-11-15T19:15:29+00:00","dateModified":"2023-11-16T10:15:46+00:00","breadcrumb":{"@id":"https:\/\/xqthenews.com\/pt-pt\/glossary\/limiar-de-pobreza\/#breadcrumb"},"inLanguage":"pt-PT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/pt-pt\/glossary\/limiar-de-pobreza\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/pt-pt\/glossary\/limiar-de-pobreza\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/pt-pt\/"},{"@type":"ListItem","position":2,"name":"Limiar de pobreza"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-PT"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/glossary\/13974","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":0,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/glossary\/13974\/revisions"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/media?parent=13974"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/pt-pt\/wp-json\/wp\/v2\/coauthors?post=13974"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}