{"id":24409,"date":"2024-10-02T08:18:28","date_gmt":"2024-10-02T07:18:28","guid":{"rendered":"https:\/\/xqthenews.com\/?p=24409"},"modified":"2024-10-02T12:11:27","modified_gmt":"2024-10-02T11:11:27","slug":"mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche","status":"publish","type":"post","link":"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/","title":{"rendered":"Mobilit\u00e0 soft e inclusiva: per citt\u00e0 veramente ecologiche"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><strong><em>La crescente domanda globale di trasporto rende urgente trovare soluzioni in grado di garantire una <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> ecologica, pi&ugrave; pulita, sicura ed efficiente per tutti.<\/em><\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il concetto di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> soft, noto anche come <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> responsabile dal punto di vista ambientale o <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> non motorizzata, &egrave; uno dei pilastri fondamentali delle <em>citt&agrave; verdi<\/em>, progettate per essere ecologicamente sostenibili, economicamente valide e socialmente giuste.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La necessit&agrave; di ridurre le <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Emissioni&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Rilascio di gas serra nell&amp;#039;atmosfera da varie fonti, come combustione di combustibili fossili, produzione industriale e agricoltura.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-vostro-cestino-del-pranzo-in-plastica-inquina-il-pianeta-e-il-vostro-sistema-endocrino\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il vostro cestino del pranzo in plastica inquina il pianeta e il vostro sistema endocrino&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/a-dubai-il-vertice-mondiale-sul-clima-cop-28\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A Dubai il vertice mondiale sul clima COP 28&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/greencomp-liniziativa-che-puo-trasformare-leducazione-ambientale-dei-giovani\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;GreenComp: l&amp;#8217;iniziativa che pu&ograve; trasformare l&amp;#8217;educazione ambientale dei giovani?&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/emissioni\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">emissioni<\/a> di gas serra per raggiungere la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Neutralit&agrave; carbonica&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Raggiungere la neutralit&agrave; carbonica significa ottenere un equilibrio tra le emissioni di gas a effetto serra (GHG), che includono anidride carbonica e metano, e il loro assorbimento nell&amp;#039;atmosfera attraverso i cosiddetti serbatoi di carbonio, riducendo le emissioni il pi&ugrave; vicino possibile allo zero.&amp;lt;br\/&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;(Fonte: Ess&ecirc;ncia do Ambiente)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/a-dubai-il-vertice-mondiale-sul-clima-cop-28\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A Dubai il vertice mondiale sul clima COP 28&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/foreste-la-pedina-chiave-nel-gioco-ambientale-degli-scacchi\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Foreste: la pedina chiave nel gioco ambientale degli scacchi&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/neutralita-carbonica\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">neutralit&agrave; carbonica<\/a> entro il 2050, cos&igrave; come la riduzione del traffico automobilistico nei tragitti quotidiani e i problemi associati alla <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> urbana, hanno spinto le amministrazioni pubbliche ad adottare nuove misure &ndash; come la restrizione della circolazione delle auto in alcune aree &ndash; e a promuovere metodi di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> soft, come incentivi all&rsquo;uso dei trasporti pubblici, il car sharing e l&rsquo;uso della bicicletta. Inoltre, i comuni hanno investito nella costruzione di nuove infrastrutture per la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> urbana, come piste ciclabili, infrastrutture pedonali e parcheggi. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">L&rsquo;implementazione di queste infrastrutture, previste nei piani di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> nazionali e internazionali, e che fanno parte delle soluzioni per raggiungere gli obiettivi di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Neutralit&agrave; carbonica&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Raggiungere la neutralit&agrave; carbonica significa ottenere un equilibrio tra le emissioni di gas a effetto serra (GHG), che includono anidride carbonica e metano, e il loro assorbimento nell&amp;#039;atmosfera attraverso i cosiddetti serbatoi di carbonio, riducendo le emissioni il pi&ugrave; vicino possibile allo zero.&amp;lt;br\/&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;(Fonte: Ess&ecirc;ncia do Ambiente)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/a-dubai-il-vertice-mondiale-sul-clima-cop-28\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A Dubai il vertice mondiale sul clima COP 28&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/foreste-la-pedina-chiave-nel-gioco-ambientale-degli-scacchi\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Foreste: la pedina chiave nel gioco ambientale degli scacchi&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/neutralita-carbonica\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">neutralit&agrave; carbonica<\/a>, mira a rispondere sia alle esigenze dei <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Cittadini&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Un concetto che comprende questioni di diritti e responsabilit&agrave;, cos&igrave; come idee di uguaglianza, diversit&agrave; e giustizia sociale. Il concetto di cittadinanza non si limita all&amp;#039;atto di votare, ma comprende una vasta gamma di azioni che ciascuna persona intraprende che hanno un impatto sulla vita della comunit&agrave; (locale, nazionale, regionale e internazionale) e sono indissolubilmente legate alla sfera pubblica in cui le persone possono agire insieme.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;(Fonte: CIG &ndash; Comiss&atilde;o para a Cidadania e Igualde de G&eacute;nero)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-vostro-cestino-del-pranzo-in-plastica-inquina-il-pianeta-e-il-vostro-sistema-endocrino\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il vostro cestino del pranzo in plastica inquina il pianeta e il vostro sistema endocrino&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/economia-circular-materia-organica-en-el-pasado-el-presente-y-el-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Economia circolare: la materia organica nel passato, presente e futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/avvicinare-i-giovani-al-processo-decisionale-politico-una-sfida-urgente\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Avvicinare i giovani al processo decisionale politico: una sfida urgente&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/glossary\/agenda-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Agenda 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/le-tradizioni-natalizie-italiane-tra-sacro-e-profano\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Le tradizioni natalizie italiane, tra sacro e profano&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/cittadinanza\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">cittadini<\/a>, che ai paradigmi della transizione ecologica, incoraggiando e contribuendo a comportamenti pi&ugrave; sostenibili e all&rsquo;adozione di nuove abitudini di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> quotidiana.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In questo modo, si sta assistendo a un uso crescente di trasporti multimodali da parte dei <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Cittadini&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Un concetto che comprende questioni di diritti e responsabilit&agrave;, cos&igrave; come idee di uguaglianza, diversit&agrave; e giustizia sociale. Il concetto di cittadinanza non si limita all&amp;#039;atto di votare, ma comprende una vasta gamma di azioni che ciascuna persona intraprende che hanno un impatto sulla vita della comunit&agrave; (locale, nazionale, regionale e internazionale) e sono indissolubilmente legate alla sfera pubblica in cui le persone possono agire insieme.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;(Fonte: CIG &ndash; Comiss&atilde;o para a Cidadania e Igualde de G&eacute;nero)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-vostro-cestino-del-pranzo-in-plastica-inquina-il-pianeta-e-il-vostro-sistema-endocrino\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il vostro cestino del pranzo in plastica inquina il pianeta e il vostro sistema endocrino&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/economia-circular-materia-organica-en-el-pasado-el-presente-y-el-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Economia circolare: la materia organica nel passato, presente e futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/avvicinare-i-giovani-al-processo-decisionale-politico-una-sfida-urgente\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Avvicinare i giovani al processo decisionale politico: una sfida urgente&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/glossary\/agenda-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Agenda 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/le-tradizioni-natalizie-italiane-tra-sacro-e-profano\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Le tradizioni natalizie italiane, tra sacro e profano&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/cittadinanza\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">cittadini<\/a>, ma anche a una riduzione della dipendenza dai veicoli individuali e all&rsquo;uso maggiore di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Modalit&agrave; soft&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Mezzi di trasporto non motorizzati, inclusi camminare e andare in bicicletta, cos&igrave; come ausili alla mobilit&agrave; (skateboard, pattini a rotelle e simili).&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte&amp;lt;\/em&amp;gt;: Adattato da &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/modalita-soft\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">modalit&agrave; soft<\/a> come il ridesharing e il trasporto pubblico, cos&igrave; come opzioni di viaggio pi&ugrave; ecologiche e attive come camminare, andare in bicicletta e usare monopattini.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I trasporti pubblici, come autobus e metropolitane, svolgono un ruolo chiave nel combinare diverse modalit&agrave; di trasporto, contribuendo a ridurre la congestione, abbassare le <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Emissioni&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Rilascio di gas serra nell&amp;#039;atmosfera da varie fonti, come combustione di combustibili fossili, produzione industriale e agricoltura.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-vostro-cestino-del-pranzo-in-plastica-inquina-il-pianeta-e-il-vostro-sistema-endocrino\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il vostro cestino del pranzo in plastica inquina il pianeta e il vostro sistema endocrino&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/a-dubai-il-vertice-mondiale-sul-clima-cop-28\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A Dubai il vertice mondiale sul clima COP 28&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/greencomp-liniziativa-che-puo-trasformare-leducazione-ambientale-dei-giovani\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;GreenComp: l&amp;#8217;iniziativa che pu&ograve; trasformare l&amp;#8217;educazione ambientale dei giovani?&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/emissioni\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">emissioni<\/a> di inquinanti e migliorare la qualit&agrave; della vita nelle citt&agrave;. Tuttavia, la loro efficacia deve essere garantita per rappresentare una soluzione realistica, rispondendo alla sfida di fornire al pubblico informazioni sugli orari disponibili, con stime in tempo reale dei tempi di arrivo dei mezzi alle fermate successive, consentendo ai passeggeri di gestire efficacemente il proprio tempo e scegliere il mezzo giusto. Garantire questo, aumenta la percezione di credibilit&agrave; di questo tipo di trasporto tra i <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Cittadini&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Un concetto che comprende questioni di diritti e responsabilit&agrave;, cos&igrave; come idee di uguaglianza, diversit&agrave; e giustizia sociale. Il concetto di cittadinanza non si limita all&amp;#039;atto di votare, ma comprende una vasta gamma di azioni che ciascuna persona intraprende che hanno un impatto sulla vita della comunit&agrave; (locale, nazionale, regionale e internazionale) e sono indissolubilmente legate alla sfera pubblica in cui le persone possono agire insieme.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;(Fonte: CIG &ndash; Comiss&atilde;o para a Cidadania e Igualde de G&eacute;nero)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-vostro-cestino-del-pranzo-in-plastica-inquina-il-pianeta-e-il-vostro-sistema-endocrino\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il vostro cestino del pranzo in plastica inquina il pianeta e il vostro sistema endocrino&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/economia-circular-materia-organica-en-el-pasado-el-presente-y-el-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Economia circolare: la materia organica nel passato, presente e futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/avvicinare-i-giovani-al-processo-decisionale-politico-una-sfida-urgente\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Avvicinare i giovani al processo decisionale politico: una sfida urgente&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/glossary\/agenda-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Agenda 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/le-tradizioni-natalizie-italiane-tra-sacro-e-profano\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Le tradizioni natalizie italiane, tra sacro e profano&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/cittadinanza\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">cittadini<\/a>, traducendosi in un aumento dell&rsquo;uso di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Modalit&agrave; soft&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Mezzi di trasporto non motorizzati, inclusi camminare e andare in bicicletta, cos&igrave; come ausili alla mobilit&agrave; (skateboard, pattini a rotelle e simili).&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte&amp;lt;\/em&amp;gt;: Adattato da &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/modalita-soft\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">modalit&agrave; soft<\/a> quando si sceglie di viaggiare, in particolare usando il trasporto pubblico.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Anche la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> condivisa &egrave; una realt&agrave; in crescita nei grandi centri urbani, emergendo come un&rsquo;alternativa intelligente all&rsquo;uso dell&rsquo;auto privata. Oltre ai vantaggi economici, riduce il traffico e le <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Emissioni&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Rilascio di gas serra nell&amp;#039;atmosfera da varie fonti, come combustione di combustibili fossili, produzione industriale e agricoltura.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-vostro-cestino-del-pranzo-in-plastica-inquina-il-pianeta-e-il-vostro-sistema-endocrino\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il vostro cestino del pranzo in plastica inquina il pianeta e il vostro sistema endocrino&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/a-dubai-il-vertice-mondiale-sul-clima-cop-28\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A Dubai il vertice mondiale sul clima COP 28&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/greencomp-liniziativa-che-puo-trasformare-leducazione-ambientale-dei-giovani\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;GreenComp: l&amp;#8217;iniziativa che pu&ograve; trasformare l&amp;#8217;educazione ambientale dei giovani?&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/emissioni\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">emissioni<\/a> di inquinanti. Include il <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Carsharing&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Il servizio di trasporto basato sulla messa a disposizione del pubblico di una flotta di veicoli, evitando cos&igrave; i costi associati all&amp;#039;acquisto e alla manutenzione dei propri, pu&ograve; essere paragonato al noleggio a breve termine, che consente di utilizzare lo stesso veicolo a clienti diversi nel corso della giornata.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt; &amp;lt;\/em&amp;gt;&amp;lt;em&amp;gt;(Fonte: &amp;lt;\/em&amp;gt;&amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/carsharing\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">carsharing<\/a> per spostare pi&ugrave; persone, ad esempio attraverso il TVDE (Trasporto Individuale e Retribuito di passeggeri in veicoli non caratterizzati da una Piattaforma Elettronica), ma anche il <em><a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Carpooling&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Iniziativa in cui due o pi&ugrave; persone condividono un veicolo privato per percorrere lo stesso tragitto o parte di un tragitto simile.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte: &amp;lt;\/em&amp;gt;&amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/carpooling\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">carpooling<\/a><\/em>, il noleggio di <em>monopattini,<\/em> biciclette e <em>monopattini<\/em> elettrici.   <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il passaggio a modalit&agrave; di trasporto non motorizzate, come biciclette, monopattini e camminare, porta numerosi vantaggi che migliorano la qualit&agrave; della vita urbana. Tuttavia, ci sono ostacoli da superare, come la mancanza di infrastrutture adeguate, la necessit&agrave; di una condivisione armoniosa delle strade e la consapevolezza pubblica dell&rsquo;adozione di queste modalit&agrave; di viaggio. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">I vantaggi dei veicoli non motorizzati e della <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> soft includono la riduzione dell&rsquo;<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Inquinamento&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt; L&amp;#039;inquinamento &egrave; la presenza di sostanze nocive nell&amp;#039;ambiente, come nell&amp;#039;aria, nell&amp;#039;acqua o nel suolo. Queste sostanze possono essere causate da attivit&agrave; umane, come l&amp;#039;uso di prodotti chimici in agricoltura o i rifiuti industriali, e possono danneggiare la salute delle persone e degli ecosistemi. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-vostro-cestino-del-pranzo-in-plastica-inquina-il-pianeta-e-il-vostro-sistema-endocrino\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il vostro cestino del pranzo in plastica inquina il pianeta e il vostro sistema endocrino&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/la-plastica-invade-i-mari-cronaca-di-un-nuovo-ecocidio-al-largo-della-costa-galiziana\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La plastica invade i mari: cronaca di un nuovo ecocidio al largo della costa galiziana&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/lemergenza-climatica-e-le-sfide-per-la-salute\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&rsquo;Emergenza climatica e le sfide per la salute&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpatto-del-cambiamento-climatico-nel-sud-italia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&rsquo;impatto del cambiamento climatico nel sud Italia&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/inquinamento\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">inquinamento<\/a> atmosferico e acustico, maggiori spazi pubblici che invece di essere destinati a parcheggi e interfacce, vengono rinnovati e trasformati in aree verdi, spazi sociali o commerciali, migliorando l&rsquo;ambiente <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Urbano&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Urbano deriva dal latino &amp;quot;urbanus&rdquo; che significa &amp;quot;appartenente alla citt&agrave;&rdquo;. Urbano &egrave; tutto ci&ograve; che &egrave; legato alla vita in citt&agrave; e agli individui che la abitano. L&amp;#039;ambiente urbano presenta caratteristiche specifiche, quali: alta densit&agrave; di popolazione, infrastrutture moderne (strade pubbliche, trasporti, scuole, ospedali, ecc.), aree residenziali, commerciali e industriali, opzioni per il tempo libero e l&amp;#039;intrattenimento, offerte culturali, abitudini di vita private e il trambusto tipico delle citt&agrave;.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\"  href=\"https:\/\/xqthenews.com\/it\/glossary\/urbano\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>urbano<\/a> e la sicurezza dei pedoni. Inoltre, la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> soft &egrave; anche associata alla salute, poich&eacute; l&rsquo;uso di mezzi di trasporto attivi che richiedono uno sforzo fisico, come camminare o andare in bicicletta, promuove una popolazione pi&ugrave; sana e attiva, contribuendo al benessere fisico e mentale delle persone che adottano queste modalit&agrave;.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In questo modo, adottando i principi degli Obiettivi di Sviluppo Sostenibile delle Nazioni Unite, investendo in infrastrutture per la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> soft come marciapiedi sicuri, piste ciclabili ben segnalate, insieme a campagne educative e all&rsquo;incoraggiamento della <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> urbana attiva, consentiamo alle citt&agrave; di raggiungere livelli pi&ugrave; elevati di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Sostenibilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;la capacit&agrave; di un sistema di mantenersi in equilibrio. Il termine &egrave; stato utilizzato per descrivere gli equilibri che gli esseri umani devono mantenere per garantire le loro condizioni di vita e assicurare la loro continuit&agrave; sul pianeta. In questo senso, la sostenibilit&agrave; si riferisce al modo in cui l&amp;#039;umanit&agrave; deve interagire con le risorse del pianeta, in modo che il soddisfacimento dei bisogni del presente non comprometta il futuro.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Fonte: https:\/\/florestas.pt\/saiba-mais\/qual-o-significado-de-sustentabilidade\/&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/avvicinare-i-giovani-al-processo-decisionale-politico-una-sfida-urgente\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Avvicinare i giovani al processo decisionale politico: una sfida urgente&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/glossary\/agenda-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Agenda 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/a-dubai-il-vertice-mondiale-sul-clima-cop-28\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A Dubai il vertice mondiale sul clima COP 28&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/qual-e-la-posizione-delle-aziende-e-della-societa-nei-confronti-delleconomia-circolare\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Qual &egrave; la posizione delle aziende e della societ&agrave; nei confronti dell&amp;#8217;economia circolare?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-parlamento-determinera-la-traiettoria-delleuropa-del-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il Parlamento determiner&agrave; la traiettoria dell&rsquo;Europa del 2030&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/sostenibilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">sostenibilit&agrave;<\/a>, salute e inclusione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La consapevolezza collettiva della societ&agrave; &egrave; una parte molto importante di questo processo e deve essere rafforzata, poich&eacute; la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> &egrave; in gran parte il risultato di scelte individuali, come confermato dai risultati del primo <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Barometro&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Indagine periodica che misura l&amp;#039;evoluzione dell&amp;#039;opinione pubblica su temi specifici, come politica, economia o problemi sociali, riflettendo tendenze e cambiamenti.&amp;lt;br\/&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/barometro\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Barometro<\/a> della <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Mobilit&agrave;<\/a> di Europ Assistance, che evidenzia come &ldquo;sebbene gli europei siano consapevoli che le questioni ambientali devono essere una priorit&agrave; e che devono essere fatti sforzi per cambiare le abitudini di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a>, solo una piccola percentuale si sente davvero a disagio nell&rsquo;usare l&rsquo;auto, e anche se altri fattori come la pandemia e l&rsquo;<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Inflazione&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt; L&amp;#039;inflazione &egrave; in economia l&amp;#039;aumento generalizzato e sostenuto dei prezzi di beni e servizi&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/inflazione\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">inflazione<\/a> contribuiscono a cambiare i comportamenti, il cambiamento potrebbe richiedere ancora del tempo&rdquo;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il dibattito sulla <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> urbana &egrave; quindi essenziale per sensibilizzare sull&rsquo;importanza di questo settore nello sviluppo di citt&agrave; responsabili dal punto di vista ambientale e inclusivo, permettendoci di identificare soluzioni pi&ugrave; ecologiche che promuovano trasporti efficienti, sicuri e accessibili per tutti. Mentre ci muoviamo in questa direzione, tutti devono rendersi conto dell&rsquo;importanza di adottare metodi di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> pi&ugrave; sostenibili, come la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> soft, per raggiungere un futuro verde basato su ci&ograve; che vogliamo siano citt&agrave; veramente ecologiche.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tuttavia, il passaggio a mezzi di trasporto pi&ugrave; sostenibili significa ripensare le citt&agrave; e mettere gli utenti al primo posto, offrendo loro alternative pi&ugrave; economiche, accessibili, salutari e pulite. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Links:<\/strong><\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li><a href=\"https:\/\/www.consilium.europa.eu\/pt\/policies\/clean-and-sustainable-mobility\/\">https:\/\/www.consilium.europa.eu\/pt\/policies\/clean-and-sustainable-mobility\/<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/linktoleaders.com\/a-descarbonizacao-da-mobilidade-urbana-em-2050-e-uma-questao-politica-a-tecnologia-ja-existe-luis-amaral\/\">https:\/\/linktoleaders.com\/a-descarbonizacao-da-mobilidade-urbana-em-2050-e-uma-questao-politica-a-tecnologia-ja-existe-luis-amaral\/<\/a> <\/li>\n\n\n\n<li><a href=\"https:\/\/smart-cities.pt\/opiniao-entrevista\/mobilidade-suave-como-otimizar-e-monitorizar-os-seus-investimentos2903\/\">https:\/\/smart-cities.pt\/opiniao-entrevista\/mobilidade-suave-como-otimizar-e-monitorizar-os-seus-investimentos2903\/<\/a> <\/li>\n\n\n\n<li><a href=\"https:\/\/essenciadoambiente.pt\/portugal-pais-gasta-mensalidade-mobilidade\/\">https:\/\/essenciadoambiente.pt\/portugal-pais-gasta-mensalidade-mobilidade\/<\/a><\/li>\n\n\n\n<li><a href=\"https:\/\/www.itf-oecd.org\/\">https:\/\/www.itf-oecd.org\/<\/a> <\/li>\n\n\n\n<li><a href=\"https:\/\/www.tecmic.com\/transporte-intermodal\/\">https:\/\/www.tecmic.com\/transporte-intermodal\/<\/a> <\/li>\n\n\n\n<li><a href=\"https:\/\/transport.ec.europa.eu\/news-events\/news\/european-mobility-week-3000-cities-showcase-their-approaches-sustainable-urban-mobility-2023-09-15_en\">https:\/\/transport.ec.europa.eu\/news-events\/news\/european-mobility-week-3000-cities-showcase-their-approaches-sustainable-urban-mobility-2023-09-15_en<\/a> <\/li>\n\n\n\n<li><a href=\"https:\/\/transport.ec.europa.eu\/news-events\/news\/european-mobility-week-3000-cities-showcase-their-approaches-sustainable-urban-mobility-2023-09-15_en\">https:\/\/transport.ec.europa.eu\/news-events\/news\/european-mobility-week-3000-cities-showcase-their-approaches-sustainable-urban-mobility-2023-09-15_en<\/a> <\/li>\n\n\n\n<li><a href=\"https:\/\/transport.ec.europa.eu\/transport-themes\/sustainable-transport_en\">https:\/\/transport.ec.europa.eu\/transport-themes\/sustainable-transport_en<\/a> <\/li>\n\n\n\n<li><a href=\"https:\/\/transport.ec.europa.eu\/index_en\">https:\/\/transport.ec.europa.eu\/index_en<\/a> <\/li>\n\n\n\n<li><a href=\"https:\/\/www.e-konomista.pt\/mobilidade-partilhada\/\">https:\/\/www.e-konomista.pt\/mobilidade-partilhada\/<\/a> <\/li>\n\n\n\n<li><a href=\"https:\/\/marketeer.sapo.pt\/mobilidade-partilhada-vai-representar-7-de-todas-as-deslocacoes-ate-2030\/\">https:\/\/marketeer.sapo.pt\/mobilidade-partilhada-vai-representar-7-de-todas-as-deslocacoes-ate-2030\/<\/a> <\/li>\n\n\n\n<li><a href=\"https:\/\/www.imt-ip.pt\/sites\/IMTT\/Portugues\/Planeamento\/DocumentosdeReferencia\/PacotedaMobilidade\/Documents\/Pacote%20da%20Mobilidade\/Gloss%C3%A1rio_do%20Pacote%20da%20Mobilidade%20.pdf\">https:\/\/www.imt-ip.pt\/sites\/IMTT\/Portugues\/Planeamento\/DocumentosdeReferencia\/PacotedaMobilidade\/Documents\/Pacote%20da%20Mobilidade\/Gloss%C3%A1rio_do%20Pacote%20da%20Mobilidade%20.pdf<\/a> <\/li>\n<\/ul>\n\n\n<script>\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n<\/script>\n\n                <div class=\"gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework quiz_wrapper\" data-form-theme=\"gravity-theme\" data-form-index=\"0\" id=\"gform_wrapper_771\"><div id=\"gf_771\" class=\"gform_anchor\" tabindex=\"-1\"><\/div>\n                        <div class=\"gform_heading\">\n                            <h2 class=\"gform_title\">Quiz sulla comprensione della lettura. Mobilit&agrave; soft e inclusiva<\/h2>\n                            <p class=\"gform_description\"><\/p>\n                        <\/div><form method=\"post\" enctype=\"multipart\/form-data\" id=\"gform_771\" class=\"quiz\" action=\"\/it\/wp-json\/wp\/v2\/posts\/24409#gf_771\" data-formid=\"771\" novalidate> \r\n <input type=\"hidden\" class=\"gforms-pum\" value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}'>\n        <div id=\"gf_progressbar_wrapper_771\" class=\"gf_progressbar_wrapper\" data-start-at-zero=\"\">\n        \t<p class=\"gf_progressbar_title\">Passo <span class=\"gf_step_current_page\">1<\/span> di <span class=\"gf_step_page_count\">4<\/span><span class=\"gf_step_page_name\"><\/span>\n        \t<\/p>\n            <div class=\"gf_progressbar gf_progressbar_blue\" aria-hidden=\"true\">\n                <div class=\"gf_progressbar_percentage percentbar_blue percentbar_25\" style=\"width:25%;\"><span>25%<\/span><\/div>\n            <\/div><\/div>\n                        <div class=\"gform-body gform_body\"><div id=\"gform_page_771_1\" class=\"gform_page \" data-js=\"page-field-id-0\">\n\t\t\t\t\t<div class=\"gform_page_fields\"><div id=\"gform_fields_771\" class=\"gform_fields top_label form_sublabel_below description_below validation_below\"><fieldset id=\"field_771_1\" class=\"gfield gfield--type-quiz gfield--type-choice gfield--input-type-radio field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gquiz-field \" data-field-class=\"gquiz-field\"><legend class=\"gfield_label gform-field-label\">Quali sono alcuni dei vantaggi associati alla <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> soft?<\/legend><div class=\"ginput_container ginput_container_radio\"><div class=\"gfield_radio\" id=\"input_771_1\">\n\t\t\t<div class=\"gchoice gchoice_771_1_0\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_1\" type=\"radio\" value=\"gquiz1b2b27084\" id=\"choice_771_1_0\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_1_0\" id=\"label_771_1_0\" class=\"gform-field-label gform-field-label--type-inline\">Aumento dell&rsquo;<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Inquinamento&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt; L&amp;#039;inquinamento &egrave; la presenza di sostanze nocive nell&amp;#039;ambiente, come nell&amp;#039;aria, nell&amp;#039;acqua o nel suolo. Queste sostanze possono essere causate da attivit&agrave; umane, come l&amp;#039;uso di prodotti chimici in agricoltura o i rifiuti industriali, e possono danneggiare la salute delle persone e degli ecosistemi. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-vostro-cestino-del-pranzo-in-plastica-inquina-il-pianeta-e-il-vostro-sistema-endocrino\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il vostro cestino del pranzo in plastica inquina il pianeta e il vostro sistema endocrino&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/la-plastica-invade-i-mari-cronaca-di-un-nuovo-ecocidio-al-largo-della-costa-galiziana\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La plastica invade i mari: cronaca di un nuovo ecocidio al largo della costa galiziana&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/lemergenza-climatica-e-le-sfide-per-la-salute\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&rsquo;Emergenza climatica e le sfide per la salute&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpatto-del-cambiamento-climatico-nel-sud-italia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&rsquo;impatto del cambiamento climatico nel sud Italia&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/inquinamento\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">inquinamento<\/a> atmosferico e acustico.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_771_1_1\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_1\" type=\"radio\" value=\"gquiz12c53da11\" id=\"choice_771_1_1\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_1_1\" id=\"label_771_1_1\" class=\"gform-field-label gform-field-label--type-inline\">Carenza di infrastrutture adeguate.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_771_1_2\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_1\" type=\"radio\" value=\"gquiz1b6725f5d\" id=\"choice_771_1_2\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_1_2\" id=\"label_771_1_2\" class=\"gform-field-label gform-field-label--type-inline\">Miglioramento della qualit&agrave; della vita urbana e promozione della salute.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_771_1_3\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_1\" type=\"radio\" value=\"gquiz1b9538787\" id=\"choice_771_1_3\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_1_3\" id=\"label_771_1_3\" class=\"gform-field-label gform-field-label--type-inline\">Aumento della dipendenza dai veicoli individuali.<\/label>\n\t\t\t<\/div><\/div><\/div><\/fieldset><\/div>\n                    <\/div>\n                    <div class=\"gform-page-footer gform_page_footer top_label\">\n                         <input type=\"button\" id=\"gform_next_button_771_5\" class=\"gform_next_button gform-theme-button button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"next\" value=\"Avanti \"> \n                    <\/div>\n                <\/div>\n                <div id=\"gform_page_771_2\" class=\"gform_page\" data-js=\"page-field-id-5\" style=\"display:none;\">\n                    <div class=\"gform_page_fields\">\n                        <div id=\"gform_fields_771_2\" class=\"gform_fields top_label form_sublabel_below description_below validation_below\"><fieldset id=\"field_771_3\" class=\"gfield gfield--type-quiz gfield--type-choice gfield--input-type-radio gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gquiz-field \" data-field-class=\"gquiz-field\"><legend class=\"gfield_label gform-field-label\">Secondo le conclusioni del primo <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Barometro&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Indagine periodica che misura l&amp;#039;evoluzione dell&amp;#039;opinione pubblica su temi specifici, come politica, economia o problemi sociali, riflettendo tendenze e cambiamenti.&amp;lt;br\/&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/barometro\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Barometro<\/a> della <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Mobilit&agrave;<\/a> di Europ Assistance, qual &egrave; la conclusione principale per quanto riguarda la consapevolezza del pubblico nei confronti di una <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> responsabile dal punto di vista ambientale?<\/legend><div class=\"ginput_container ginput_container_radio\"><div class=\"gfield_radio\" id=\"input_771_3\">\n\t\t\t<div class=\"gchoice gchoice_771_3_0\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_3\" type=\"radio\" value=\"gquiz3394e91f2\" id=\"choice_771_3_0\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_3_0\" id=\"label_771_3_0\" class=\"gform-field-label gform-field-label--type-inline\">La maggioranza degli europei non sopporta l&rsquo;uso dell&rsquo;automobile.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_771_3_1\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_3\" type=\"radio\" value=\"gquiz3c5c436f4\" id=\"choice_771_3_1\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_3_1\" id=\"label_771_3_1\" class=\"gform-field-label gform-field-label--type-inline\">Anche se gli europei riconoscono l&rsquo;importanza dell&rsquo;ambiente, il cambiamento delle abitudini pu&ograve; richiedere tempo.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_771_3_2\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_3\" type=\"radio\" value=\"gquiz3b5aa3d2d\" id=\"choice_771_3_2\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_3_2\" id=\"label_771_3_2\" class=\"gform-field-label gform-field-label--type-inline\">La pandemia e l&rsquo;<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Inflazione&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt; L&amp;#039;inflazione &egrave; in economia l&amp;#039;aumento generalizzato e sostenuto dei prezzi di beni e servizi&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/inflazione\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">inflazione<\/a> hanno accelerato notevolmente il cambiamento dei comportamenti in materia di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a>.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_771_3_3\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_3\" type=\"radio\" value=\"gquiz3d1b23a18\" id=\"choice_771_3_3\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_3_3\" id=\"label_771_3_3\" class=\"gform-field-label gform-field-label--type-inline\">La pandemia e l&rsquo;<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Inflazione&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt; L&amp;#039;inflazione &egrave; in economia l&amp;#039;aumento generalizzato e sostenuto dei prezzi di beni e servizi&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/inflazione\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">inflazione<\/a> hanno accelerato notevolmente il cambiamento dei comportamenti in materia di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a>.<\/label>\n\t\t\t<\/div><\/div><\/div><\/fieldset><\/div>\n                    <\/div>\n                    <div class=\"gform-page-footer gform_page_footer top_label\">\n                        <input type=\"button\" id=\"gform_previous_button_771_6\" class=\"gform_previous_button gform-theme-button gform-theme-button--secondary button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"previous\" value=\"Precedente\"> <input type=\"button\" id=\"gform_next_button_771_6\" class=\"gform_next_button gform-theme-button button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"next\" value=\"Avanti \"> \n                    <\/div>\n                <\/div>\n                <div id=\"gform_page_771_3\" class=\"gform_page\" data-js=\"page-field-id-6\" style=\"display:none;\">\n                    <div class=\"gform_page_fields\">\n                        <div id=\"gform_fields_771_3\" class=\"gform_fields top_label form_sublabel_below description_below validation_below\"><fieldset id=\"field_771_4\" class=\"gfield gfield--type-quiz gfield--type-choice gfield--input-type-radio gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gquiz-field \" data-field-class=\"gquiz-field\"><legend class=\"gfield_label gform-field-label\">Qual &egrave; l'obiettivo principale della sensibilizzazione sull'importanza di una <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> responsabile dal punto di vista ambientale?<\/legend><div class=\"ginput_container ginput_container_radio\"><div class=\"gfield_radio\" id=\"input_771_4\">\n\t\t\t<div class=\"gchoice gchoice_771_4_0\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_4\" type=\"radio\" value=\"gquiz46a62d494\" id=\"choice_771_4_0\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_4_0\" id=\"label_771_4_0\" class=\"gform-field-label gform-field-label--type-inline\">Aumentare il numero di veicoli individuali nelle citt&agrave;.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_771_4_1\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_4\" type=\"radio\" value=\"gquiz488c89c8f\" id=\"choice_771_4_1\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_4_1\" id=\"label_771_4_1\" class=\"gform-field-label gform-field-label--type-inline\">Incoraggiare l&rsquo;uso esclusivo di mezzi di trasporto motorizzati.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_771_4_2\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_4\" type=\"radio\" value=\"gquiz4054f68d8\" id=\"choice_771_4_2\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_4_2\" id=\"label_771_4_2\" class=\"gform-field-label gform-field-label--type-inline\">Ridurre l&rsquo;accessibilit&agrave; al trasporto pubblico.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_771_4_3\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_4\" type=\"radio\" value=\"gquiz472a6fadb\" id=\"choice_771_4_3\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_4_3\" id=\"label_771_4_3\" class=\"gform-field-label gform-field-label--type-inline\">Identificare soluzioni pi&ugrave; ecologiche per la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> urbana e promuoverne l&rsquo;uso.<\/label>\n\t\t\t<\/div><\/div><\/div><\/fieldset><\/div>\n                    <\/div>\n                    <div class=\"gform-page-footer gform_page_footer top_label\">\n                        <input type=\"button\" id=\"gform_previous_button_771_8\" class=\"gform_previous_button gform-theme-button gform-theme-button--secondary button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"previous\" value=\"Precedente\"> <input type=\"button\" id=\"gform_next_button_771_8\" class=\"gform_next_button gform-theme-button button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"next\" value=\"Avanti \"> \n                    <\/div>\n                <\/div>\n                <div id=\"gform_page_771_4\" class=\"gform_page\" data-js=\"page-field-id-8\" style=\"display:none;\">\n                    <div class=\"gform_page_fields\">\n                        <div id=\"gform_fields_771_4\" class=\"gform_fields top_label form_sublabel_below description_below validation_below\"><fieldset id=\"field_771_7\" class=\"gfield gfield--type-quiz gfield--type-choice gfield--input-type-radio gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gquiz-field \" data-field-class=\"gquiz-field\"><legend class=\"gfield_label gform-field-label\">In che modo la tecnologia contribuisce a migliorare la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> urbana?<\/legend><div class=\"ginput_container ginput_container_radio\"><div class=\"gfield_radio\" id=\"input_771_7\">\n\t\t\t<div class=\"gchoice gchoice_771_7_0\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_7\" type=\"radio\" value=\"gquiz46a62d494\" id=\"choice_771_7_0\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_7_0\" id=\"label_771_7_0\" class=\"gform-field-label gform-field-label--type-inline\">Aumentando la congestione del traffico.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_771_7_1\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_7\" type=\"radio\" value=\"gquiz488c89c8f\" id=\"choice_771_7_1\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_7_1\" id=\"label_771_7_1\" class=\"gform-field-label gform-field-label--type-inline\">Migliorando l&rsquo;efficienza dei sistemi di transito e di trasporto pubblico.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_771_7_2\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_7\" type=\"radio\" value=\"gquiz4054f68d8\" id=\"choice_771_7_2\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_7_2\" id=\"label_771_7_2\" class=\"gform-field-label gform-field-label--type-inline\">Riducendo la necessit&agrave; di politiche ambientali.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_771_7_3\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_7\" type=\"radio\" value=\"gquiz74f61f4a6\" id=\"choice_771_7_3\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_771_7_3\" id=\"label_771_7_3\" class=\"gform-field-label gform-field-label--type-inline\">Aumentando la dipendenza dai veicoli individuali.<\/label>\n\t\t\t<\/div><\/div><\/div><\/fieldset><\/div><\/div>\n        <div class=\"gform-page-footer gform_page_footer top_label\"><input type=\"submit\" id=\"gform_previous_button_771\" class=\"gform_previous_button gform-theme-button gform-theme-button--secondary button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"previous\" value=\"Precedente\"> <input type=\"submit\" id=\"gform_submit_button_771\" class=\"gform_button button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"submit\" value=\"Inviare\"> \n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_submission_method\" data-js=\"gform_submission_method_771\" value=\"postback\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_theme\" data-js=\"gform_theme_771\" id=\"gform_theme_771\" value=\"gravity-theme\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_style_settings\" data-js=\"gform_style_settings_771\" id=\"gform_style_settings_771\" value='{\"inputPrimaryColor\":\"#204ce5\"}'>\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"is_submit_771\" value=\"1\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_submit\" value=\"771\">\n            \n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_currency\" data-currency=\"EUR\" value=\"lbYaOhK\/Rhw60Ue2H\/Ael6P+EgHUzh+QExt9JOAaLcCsrkoPbqagBh5e086Ycsd69Cwcy5A36j1Wt2NqyIyfE4d3Mnlhu9rgkS1LpmxhxzTuuIU=\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_unique_id\" value=\"\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"state_771\" value=\"WyJbXSIsIjVlMjNlOGUzOTg5N2RmMzcwZmE1ODRlNDZjZGJmYjNkIl0=\">\n            <input type=\"hidden\" autocomplete=\"off\" class=\"gform_hidden\" name=\"gform_target_page_number_771\" id=\"gform_target_page_number_771\" value=\"2\">\n            <input type=\"hidden\" autocomplete=\"off\" class=\"gform_hidden\" name=\"gform_source_page_number_771\" id=\"gform_source_page_number_771\" value=\"1\">\n            <input type=\"hidden\" name=\"gform_field_values\" value=\"\">\n            \n        <\/div>\n             <\/div><\/div>\n                        <\/form>\n                        <\/div><script>\ngform.initializeOnLoaded( function() {gformInitSpinner( 771, 'https:\/\/xqthenews.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_771').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_771');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_771').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_771').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_771').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_771').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_771').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_771').val();gformInitSpinner( 771, 'https:\/\/xqthenews.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [771, current_page]);window['gf_submitting_771'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_771').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_771').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [771]);window['gf_submitting_771'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_771').text());}else{jQuery('#gform_771').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"771\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_771\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_771\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_771\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 771, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} );\n<\/script>\n","protected":false},"excerpt":{"rendered":"<p>La crescente domanda globale di trasporto rende urgente trovare soluzioni in grado di garantire una <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> ecologica, pi&ugrave; pulita, sicura ed efficiente per tutti. Il concetto di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> soft, noto anche come <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> responsabile dal punto di vista ambientale o <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mobilit&agrave;&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Capacit&agrave; individuale di spostarsi in base alle esigenze e agli interessi di viaggio delle persone. I mezzi di trasporto disponibili e l&amp;#039;accessibilit&agrave; offerta dal sistema di trasporto influenzano la mobilit&agrave;, cos&igrave; come le caratteristiche individuali delle persone e l&amp;#039;ambiente familiare. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;em&amp;gt;(Fonte:&amp;lt;\/em&amp;gt; &amp;lt;em&amp;gt;Gloss&aacute;rio do Pacote da Mobilidade - IMT - Instituto da Mobilidade e dos Transportes)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripensare-la-mobilita-per-costruire-le-citta-del-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripensare la mobilit&agrave; per costruire le citt&agrave; del futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mobilit&agrave; soft e inclusiva: per citt&agrave; veramente ecologiche&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpronta-di-carbonio-e-ancora-importante-nella-lotta-contro-la-crisi-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&amp;#8217;impronta di carbonio &egrave; ancora importante nella lotta contro la crisi climatica?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mobilita\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mobilit&agrave;<\/a> non motorizzata, &egrave; uno dei pilastri fondamentali delle citt&agrave; verdi, progettate per essere ecologicamente<\/p>\n","protected":false},"author":61,"featured_media":24401,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[452,485],"tags":[566],"coauthors":[241],"class_list":["post-24409","post","type-post","status-publish","format-standard","has-post-thumbnail","category-ambiente","category-sostenibilita","tag-mobility-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Mobilit\u00e0 soft e inclusiva: per citt\u00e0 veramente ecologiche - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mobilit\u00e0 soft e inclusiva: per citt\u00e0 veramente ecologiche - xqthenews\" \/>\n<meta property=\"og:description\" content=\"La crescente domanda globale di trasporto rende urgente trovare soluzioni in grado di garantire una mobilit&agrave; ecologica, pi&ugrave; pulita, sicura ed efficiente per tutti. Il concetto di mobilit&agrave; soft, noto anche come mobilit&agrave; responsabile dal punto di vista ambientale o mobilit&agrave; non motorizzata, &egrave; uno dei pilastri fondamentali delle citt&agrave; verdi, progettate per essere ecologicamente\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-02T07:18:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-02T11:11:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/10\/Portada-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1250\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"In\u00eas Costa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"In\u00eas Costa\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\\\/\"},\"author\":{\"name\":\"In\u00eas Costa\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/c37319b10fdbf56021bb59a9233a1c03\"},\"headline\":\"Mobilit\u00e0 soft e inclusiva: per citt\u00e0 veramente ecologiche\",\"datePublished\":\"2024-10-02T07:18:28+00:00\",\"dateModified\":\"2024-10-02T11:11:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\\\/\"},\"wordCount\":989,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Portada-scaled.jpg\",\"keywords\":[\"Mobility\"],\"articleSection\":[\"Ambiente\",\"Sostenibilit\u00e0\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/it\\\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\\\/\",\"name\":\"Mobilit\u00e0 soft e inclusiva: per citt\u00e0 veramente ecologiche - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Portada-scaled.jpg\",\"datePublished\":\"2024-10-02T07:18:28+00:00\",\"dateModified\":\"2024-10-02T11:11:27+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/c37319b10fdbf56021bb59a9233a1c03\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/it\\\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Portada-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/10\\\/Portada-scaled.jpg\",\"width\":2560,\"height\":1250,\"caption\":\"Ripensare la mobilit\u00e0 urbana \u00e8 un'esigenza crescente | FreePik\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mobilit\u00e0 soft e inclusiva: per citt\u00e0 veramente ecologiche\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/c37319b10fdbf56021bb59a9233a1c03\",\"name\":\"In\u00eas Costa\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/ines-costa_avatar_1-96x96.png665f5476607967de4fb701963de2ad15\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/ines-costa_avatar_1-96x96.png\",\"contentUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/ines-costa_avatar_1-96x96.png\",\"caption\":\"In\u00eas Costa\"},\"description\":\"Nacida en Viseu,(Portugal), es licenciada en Publicidad y Relaciones P\u00fablicas por ESEV. Asesora de comunicaci\u00f3n en Ess\u00eancia - Comunica\u00e7\u00e3o Completa, forma parte del equipo del Departamento de Comunicaci\u00f3n y Educaci\u00f3n Ambiental - Ess\u00eancia do Ambiente - que utiliza las herramientas de comunicaci\u00f3n como aliado en el proceso de sensibilizaci\u00f3n y educaci\u00f3n ambiental.\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/author\\\/ines-costa\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mobilit\u00e0 soft e inclusiva: per citt\u00e0 veramente ecologiche - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/","og_locale":"it_IT","og_type":"article","og_title":"Mobilit\u00e0 soft e inclusiva: per citt\u00e0 veramente ecologiche - xqthenews","og_description":"La crescente domanda globale di trasporto rende urgente trovare soluzioni in grado di garantire una mobilit&agrave; ecologica, pi&ugrave; pulita, sicura ed efficiente per tutti. Il concetto di mobilit&agrave; soft, noto anche come mobilit&agrave; responsabile dal punto di vista ambientale o mobilit&agrave; non motorizzata, &egrave; uno dei pilastri fondamentali delle citt&agrave; verdi, progettate per essere ecologicamente","og_url":"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/","og_site_name":"xqthenews","article_published_time":"2024-10-02T07:18:28+00:00","article_modified_time":"2024-10-02T11:11:27+00:00","og_image":[{"width":2560,"height":1250,"url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/10\/Portada-scaled.jpg","type":"image\/jpeg"}],"author":"In\u00eas Costa","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"In\u00eas Costa","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/#article","isPartOf":{"@id":"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/"},"author":{"name":"In\u00eas Costa","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/c37319b10fdbf56021bb59a9233a1c03"},"headline":"Mobilit\u00e0 soft e inclusiva: per citt\u00e0 veramente ecologiche","datePublished":"2024-10-02T07:18:28+00:00","dateModified":"2024-10-02T11:11:27+00:00","mainEntityOfPage":{"@id":"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/"},"wordCount":989,"commentCount":0,"image":{"@id":"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/10\/Portada-scaled.jpg","keywords":["Mobility"],"articleSection":["Ambiente","Sostenibilit\u00e0"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/","url":"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/","name":"Mobilit\u00e0 soft e inclusiva: per citt\u00e0 veramente ecologiche - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/#primaryimage"},"image":{"@id":"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/10\/Portada-scaled.jpg","datePublished":"2024-10-02T07:18:28+00:00","dateModified":"2024-10-02T11:11:27+00:00","author":{"@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/c37319b10fdbf56021bb59a9233a1c03"},"breadcrumb":{"@id":"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/#primaryimage","url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/10\/Portada-scaled.jpg","contentUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/10\/Portada-scaled.jpg","width":2560,"height":1250,"caption":"Ripensare la mobilit\u00e0 urbana \u00e8 un'esigenza crescente | FreePik"},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/it\/mobilita-soft-e-inclusiva-per-citta-veramente-ecologiche\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Mobilit\u00e0 soft e inclusiva: per citt\u00e0 veramente ecologiche"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/c37319b10fdbf56021bb59a9233a1c03","name":"In\u00eas Costa","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/ines-costa_avatar_1-96x96.png665f5476607967de4fb701963de2ad15","url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/ines-costa_avatar_1-96x96.png","contentUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/ines-costa_avatar_1-96x96.png","caption":"In\u00eas Costa"},"description":"Nacida en Viseu,(Portugal), es licenciada en Publicidad y Relaciones P\u00fablicas por ESEV. Asesora de comunicaci\u00f3n en Ess\u00eancia - Comunica\u00e7\u00e3o Completa, forma parte del equipo del Departamento de Comunicaci\u00f3n y Educaci\u00f3n Ambiental - Ess\u00eancia do Ambiente - que utiliza las herramientas de comunicaci\u00f3n como aliado en el proceso de sensibilizaci\u00f3n y educaci\u00f3n ambiental.","url":"https:\/\/xqthenews.com\/it\/author\/ines-costa\/"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/posts\/24409","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/users\/61"}],"replies":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/comments?post=24409"}],"version-history":[{"count":0,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/posts\/24409\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/media\/24401"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/media?parent=24409"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/categories?post=24409"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/tags?post=24409"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/coauthors?post=24409"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}