{"id":20793,"date":"2024-04-16T08:03:15","date_gmt":"2024-04-16T07:03:15","guid":{"rendered":"https:\/\/sad-borg.82-223-8-23.plesk.page\/?p=20793"},"modified":"2024-11-07T12:12:11","modified_gmt":"2024-11-07T11:12:11","slug":"sephora-kids-unapologia-virale-della-cosmetorexia-precoce","status":"publish","type":"post","link":"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/","title":{"rendered":"Sephora Kids, un&#8217;apologia virale della cosmeticoressia precoce"},"content":{"rendered":"<p><strong>Il trend della Skincare, la cura della pelle, cos&igrave; diffusa sui social media, ha preso piede tra gli utenti minori di 12 anni, che recensiscono cosmetici su TikTok.<\/strong><\/p>\n\n\n\n<p>Negli ultimi tempi, quella della cura della pelle &egrave; diventata una pratica quasi compulsiva: siero di acido ialuronico, vitamina C, essenze, tonici, esfolianti, retinolo&hellip; Il fenomeno <em>skincare <\/em>si &egrave; diffuso in tutti gli strati della societ&agrave;, raggiungendo persino le fasce pi&ugrave; giovani: si tratta di ragazze sotto i 12 anni, diventate consumatrici di prodotti per il viso, trucco e prodotti di bellezza. Sono conosciute come &ldquo;Sephora Kids&rdquo; &ndash; un&rsquo;allusione al famoso negozio di cosmetici &ndash; e sono in tendenza sui social media, specialmente su TikTok.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Il rischio di cadere nella &ldquo;cosmetorexia&rdquo;<\/strong><\/h2>\n\n\n\n<p>I bambini emulano i pi&ugrave; grandi; quindi, &egrave; comune l&rsquo;uso di trucco e cosmetici come parte di un gioco di curiosit&agrave;, esplorazione ed imitazione. &ldquo;Sephora Kids&rdquo;, per&ograve;, non riguarda il gioco. Oltre ai minorenni che accedono ai contenuti degli <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Influencer&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;L&amp;#039;influencer &egrave; una persona molto popolare sui social network che, attraverso i post, sia sotto forma di testi, che di video, &egrave; un grado di influire sulle scelte e sulle opinioni di una determinata categoria di pubblico (i suoi follower).&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/la-plastica-invade-i-mari-cronaca-di-un-nuovo-ecocidio-al-largo-della-costa-galiziana\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La plastica invade i mari: cronaca di un nuovo ecocidio al largo della costa galiziana&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Sephora Kids, un&amp;#8217;apologia virale della cosmeticoressia precoce&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/xq-video-podcast-gli-impatti-dei-social-media-dalla-radicalizzazione-politica-alla-salute-mentale\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;XQ Video-Podcast. Gli impatti dei social media: dalla radicalizzazione politica alla salute mentale&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/trad-life-una-scelta-femminista\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Trad-life: una scelta femminista?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/maria-calado-i-disturbi-alimentari-iniziano-prima-e-colpiscono-piu-ragazze\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mar&iacute;a Calado: &amp;#8220;I disturbi alimentari iniziano prima e colpiscono pi&ugrave; ragazze&amp;#8221;&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/influencer\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">influencer<\/a> adulti, mostrando le loro routine di cura, sono le stesse dodicenni a essere protagoniste di questi video virali, in cui le ragazze prendono d&rsquo;assalto gli scaffali dei negozi di cosmetici, recensendo prodotti e mostrando come usarli.<\/p>\n\n\n\n<p>La skincare routine e l&rsquo;uso di prodotti che vanno oltre le reali esigenze di queste ragazze possono portare a problemi dermatologici. &ldquo;L&rsquo;esposizione indiscriminata a certi ingredienti attivi comuni nei prodotti anti-invecchiamento, ma inappropriati per il pubblico pi&ugrave; giovane, come il retinolo e gli acidi alfa idrossi, pu&ograve; causare effetti dannosi nel lungo periodo&rdquo;, <a href=\"https:\/\/www.idermic.es\/es\/skincare-en-adolescentes\/\"> spiega il centro medico Idermic<\/a>. Nel periodo pi&ugrave; immediato, gli esperti affermano che i problemi derivanti dall&rsquo;uso di &ldquo;prodotti che contengono <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;interferenti endocrini&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Gli interferenti endocrini sono sostanze chimiche che interferiscono con il sistema ormonale, influenzando la salute e lo sviluppo.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Sephora Kids, un&amp;#8217;apologia virale della cosmeticoressia precoce&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/interferenti-endocrini\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">interferenti endocrini<\/a>, o sono troppo occlusivi per la pelle acneica, possono esacerbare problemi dermatologici esistenti&rdquo;.<\/p>\n\n\n\n<p>La<a href=\"https:\/\/www.ocu.org\/salud\/cosmeticos\/noticias\/cosmetica-infantil-riesgos\"> OCU sottolinea come il rischio<\/a> di questa pratica non stia solo nella composizione di questi prodotti che potrebbero avere effetti su pelli che sono ancora in un momento di sviluppo, ma anche nel rischio di cadere nella &ldquo;cosmetorexia&rdquo;, un concetto di cui si discute sempre pi&ugrave; tra gli esperti.<strong> <\/strong>Idermic lo definisce come l&rsquo;ossessione nell&rsquo;acquisire e utilizzare una variet&agrave; di prodotti cosmetici, guidata da &ldquo;una costante ricerca della perfezione estetica alimentata da immagini irrealistiche promosse sui <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Social network&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Il termine deriva dall&amp;#039;inglese social networking service o social networking site che significa servizio di rete sociale o sito di rete sociale. Si tratta di un servizio internet per la gestione di rapporti e reti sociali, fruibile attraverso browser o applicazioni (App) che permette consente la comunicazione e la condivisione di testi, audio, immagini e video.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/non-mi-piace-che-mia-madre-pubblichi-foto-di-me-sui-social-media\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&amp;#8220;Non mi piace che mia madre pubblichi foto di me sui social media&amp;#8221;.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/avvicinare-i-giovani-al-processo-decisionale-politico-una-sfida-urgente\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Avvicinare i giovani al processo decisionale politico: una sfida urgente&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Sephora Kids, un&amp;#8217;apologia virale della cosmeticoressia precoce&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-parlamento-determinera-la-traiettoria-delleuropa-del-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il Parlamento determiner&agrave; la traiettoria dell&rsquo;Europa del 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/xq-video-podcast-gli-impatti-dei-social-media-dalla-radicalizzazione-politica-alla-salute-mentale\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;XQ Video-Podcast. Gli impatti dei social media: dalla radicalizzazione politica alla salute mentale&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/social-network\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">social network<\/a> e altri media&rdquo;.<\/p>\n\n\n\n<p>Per Conchita Sis&iacute;, direttrice della clinica Salud en Mente, il principale scatenante &egrave; la sovraesposizione dei minori ai <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Social network&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Il termine deriva dall&amp;#039;inglese social networking service o social networking site che significa servizio di rete sociale o sito di rete sociale. Si tratta di un servizio internet per la gestione di rapporti e reti sociali, fruibile attraverso browser o applicazioni (App) che permette consente la comunicazione e la condivisione di testi, audio, immagini e video.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/non-mi-piace-che-mia-madre-pubblichi-foto-di-me-sui-social-media\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&amp;#8220;Non mi piace che mia madre pubblichi foto di me sui social media&amp;#8221;.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/avvicinare-i-giovani-al-processo-decisionale-politico-una-sfida-urgente\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Avvicinare i giovani al processo decisionale politico: una sfida urgente&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Sephora Kids, un&amp;#8217;apologia virale della cosmeticoressia precoce&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-parlamento-determinera-la-traiettoria-delleuropa-del-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il Parlamento determiner&agrave; la traiettoria dell&rsquo;Europa del 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/xq-video-podcast-gli-impatti-dei-social-media-dalla-radicalizzazione-politica-alla-salute-mentale\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;XQ Video-Podcast. Gli impatti dei social media: dalla radicalizzazione politica alla salute mentale&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/social-network\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">social network<\/a>: &ldquo;Il consumo dilagante di questo tipo di contenuti facilita la creazione di <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Ideali&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Principi e valori personali che guidano le azioni, citati come la forza motrice dietro le iniziative dei protagonisti, che cercano di bilanciarli con le esigenze del mondo reale.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/inu-oh-rock-giapponese-tra-intersezionalta-gender-fluid-e-decolonialita\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Inu-Oh: rock giapponese tra intersezionalt&agrave;, gender fluid e decolonialit&agrave;.&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\"  href=\"https:\/\/xqthenews.com\/it\/glossary\/ideali\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>ideali<\/a> di bellezza da parte delle giovani ragazze, che le porta a seguire routine di cura <em>della pelle<\/em> e trucco non appropriate per la loro et&agrave;&rdquo;.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>In primo piano: limitare l&rsquo;accesso dei bambini ai social network<\/strong><\/h2>\n\n\n\n<p>Anche se l&rsquo;et&agrave; di registrazione per TikTok e Instagram &egrave; rispettivamente di 13 e 14 anni, un rapido sguardo alle piattaforme mostra che i protagonisti del trend &ldquo;Sephora Kids&rdquo; sono per lo pi&ugrave; giovani sotto i 12 anni. In alcuni casi, sono gli stessi genitori che facilitano l&rsquo;accesso dei loro figli ai social, o addirittura li incoraggiano attraverso lo <em>sharenting<\/em> &ndash; un concetto che si riferisce alla pratica dei genitori di diffondere attivamente sui <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Social network&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Il termine deriva dall&amp;#039;inglese social networking service o social networking site che significa servizio di rete sociale o sito di rete sociale. Si tratta di un servizio internet per la gestione di rapporti e reti sociali, fruibile attraverso browser o applicazioni (App) che permette consente la comunicazione e la condivisione di testi, audio, immagini e video.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/non-mi-piace-che-mia-madre-pubblichi-foto-di-me-sui-social-media\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&amp;#8220;Non mi piace che mia madre pubblichi foto di me sui social media&amp;#8221;.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/avvicinare-i-giovani-al-processo-decisionale-politico-una-sfida-urgente\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Avvicinare i giovani al processo decisionale politico: una sfida urgente&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Sephora Kids, un&amp;#8217;apologia virale della cosmeticoressia precoce&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-parlamento-determinera-la-traiettoria-delleuropa-del-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il Parlamento determiner&agrave; la traiettoria dell&rsquo;Europa del 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/xq-video-podcast-gli-impatti-dei-social-media-dalla-radicalizzazione-politica-alla-salute-mentale\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;XQ Video-Podcast. Gli impatti dei social media: dalla radicalizzazione politica alla salute mentale&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/social-network\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">social network<\/a> contenuti sui loro figli.<\/p>\n\n\n\n<p>Oltre alla mercificazione dell&rsquo;infanzia da parte dei genitori stessi &ndash; come i <a href=\"https:\/\/www.bbc.com\/mundo\/noticias-46435601\">casi dei bambini-influencer<\/a> di giocattoli &ndash; <a href=\"https:\/\/www.theguardian.com\/technology\/2023\/dec\/19\/tiktok-allowing-under-13s-to-keep-accounts-evidence-suggests\">un&rsquo;indagine del The Guardian<\/a> ha rivelato che i bambini sotto i 13 anni possono facilmente aggirare i controlli di accesso e creare un account su TikTok. Oltre ad aprire un account, possono facilmente evitare che venga chiuso dalla piattaforma, poich&eacute; &egrave; sufficiente segnalare che &egrave; gestito dai loro genitori.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Vietare o regolamentare?<\/strong><\/h2>\n\n\n\n<p>Quando si tratta dell&rsquo;acquisto di cosmetici, alcuni paesi europei, come la Svezia, stanno gi&agrave; imponendo restrizioni d&rsquo;et&agrave; sulla vendita di prodotti. Per scoraggiare il consumo da parte dei bambini, il piano &egrave; quello di cercare di controllarne i movimenti e impedire un uso prematuro di questo tipo di prodotti. Sui <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Social network&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Il termine deriva dall&amp;#039;inglese social networking service o social networking site che significa servizio di rete sociale o sito di rete sociale. Si tratta di un servizio internet per la gestione di rapporti e reti sociali, fruibile attraverso browser o applicazioni (App) che permette consente la comunicazione e la condivisione di testi, audio, immagini e video.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/non-mi-piace-che-mia-madre-pubblichi-foto-di-me-sui-social-media\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&amp;#8220;Non mi piace che mia madre pubblichi foto di me sui social media&amp;#8221;.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/avvicinare-i-giovani-al-processo-decisionale-politico-una-sfida-urgente\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Avvicinare i giovani al processo decisionale politico: una sfida urgente&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Sephora Kids, un&amp;#8217;apologia virale della cosmeticoressia precoce&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-parlamento-determinera-la-traiettoria-delleuropa-del-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il Parlamento determiner&agrave; la traiettoria dell&rsquo;Europa del 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/xq-video-podcast-gli-impatti-dei-social-media-dalla-radicalizzazione-politica-alla-salute-mentale\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;XQ Video-Podcast. Gli impatti dei social media: dalla radicalizzazione politica alla salute mentale&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/social-network\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">social network<\/a>, il <a href=\"https:\/\/www.aepd.es\/documento\/el-reglamento-de-servicios-digitales-dsa-explicado.pdf\">Regolamento Europeo sui Servizi Digitali<\/a> richiede alle piattaforme di essere garanti di vari elementi che riguardano minori, compreso il loro &ldquo;<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Benessere mentale&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Stato di equilibrio psicologico ed emotivo che permette di affrontare le sfide quotidiane senza stress eccessivo. Un uso eccessivo dei social pu&ograve; influenzarlo negativamente. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/benessere-mentale\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">benessere mentale<\/a>&rdquo;. Tuttavia, TikTok ha affrontato diverse battaglie contro i regolatori, una delle quali, alla fine del 2023, ha portato l&rsquo;UE a multarlo per 345 milioni di euro, per aver violato la legge sulla protezione dei dati sui minori. Per quanto riguarda l&rsquo;uso quotidiano dei <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Social network&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Il termine deriva dall&amp;#039;inglese social networking service o social networking site che significa servizio di rete sociale o sito di rete sociale. Si tratta di un servizio internet per la gestione di rapporti e reti sociali, fruibile attraverso browser o applicazioni (App) che permette consente la comunicazione e la condivisione di testi, audio, immagini e video.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/non-mi-piace-che-mia-madre-pubblichi-foto-di-me-sui-social-media\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&amp;#8220;Non mi piace che mia madre pubblichi foto di me sui social media&amp;#8221;.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/avvicinare-i-giovani-al-processo-decisionale-politico-una-sfida-urgente\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Avvicinare i giovani al processo decisionale politico: una sfida urgente&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Sephora Kids, un&amp;#8217;apologia virale della cosmeticoressia precoce&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-parlamento-determinera-la-traiettoria-delleuropa-del-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il Parlamento determiner&agrave; la traiettoria dell&rsquo;Europa del 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/xq-video-podcast-gli-impatti-dei-social-media-dalla-radicalizzazione-politica-alla-salute-mentale\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;XQ Video-Podcast. Gli impatti dei social media: dalla radicalizzazione politica alla salute mentale&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/social-network\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">social network<\/a> da parte dei giovanissimi, il dibattito tende a concentrarsi sul solito dilemma: vietare o regolamentare? La psicologa Conchita Sis&iacute; sostiene il &ldquo;lavoro continuo che coinvolga i genitori&rdquo;. In altre parole, anche se la linea del divieto potrebbe sembrare la pi&ugrave; semplice per gli adulti in prima battuta, la soluzione dovrebbe essere mirata a &ldquo;riorientare il loro uso, promuovere attenzione e controllo genitoriale in modo positivo sull&rsquo;uso dei <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Social network&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Il termine deriva dall&amp;#039;inglese social networking service o social networking site che significa servizio di rete sociale o sito di rete sociale. Si tratta di un servizio internet per la gestione di rapporti e reti sociali, fruibile attraverso browser o applicazioni (App) che permette consente la comunicazione e la condivisione di testi, audio, immagini e video.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/non-mi-piace-che-mia-madre-pubblichi-foto-di-me-sui-social-media\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&amp;#8220;Non mi piace che mia madre pubblichi foto di me sui social media&amp;#8221;.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/avvicinare-i-giovani-al-processo-decisionale-politico-una-sfida-urgente\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Avvicinare i giovani al processo decisionale politico: una sfida urgente&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Sephora Kids, un&amp;#8217;apologia virale della cosmeticoressia precoce&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-parlamento-determinera-la-traiettoria-delleuropa-del-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il Parlamento determiner&agrave; la traiettoria dell&rsquo;Europa del 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/xq-video-podcast-gli-impatti-dei-social-media-dalla-radicalizzazione-politica-alla-salute-mentale\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;XQ Video-Podcast. Gli impatti dei social media: dalla radicalizzazione politica alla salute mentale&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/social-network\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">social network<\/a>&rdquo;.<\/p>\n\n\n\n<hr class=\"wp-block-separator has-text-color has-vivid-green-cyan-color has-alpha-channel-opacity has-vivid-green-cyan-background-color has-background is-style-wide\">\n\n\n\n<div style=\"height:100px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class=\"gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework quiz_wrapper\" data-form-theme=\"gravity-theme\" data-form-index=\"0\" id=\"gform_wrapper_626\"><div id=\"gf_626\" class=\"gform_anchor\" tabindex=\"-1\"><\/div>\n                        <div class=\"gform_heading\">\n                            <h2 class=\"gform_title\">Quiz sulla comprensione della lettura. Sephora Kids, un&rsquo;apologia virale della cosmetorexia precoce<\/h2>\n                            <p class=\"gform_description\"><\/p>\n                        <\/div><form method=\"post\" enctype=\"multipart\/form-data\" id=\"gform_626\" class=\"quiz\" action=\"\/it\/wp-json\/wp\/v2\/posts\/20793#gf_626\" data-formid=\"626\" novalidate> \r\n <input type=\"hidden\" class=\"gforms-pum\" value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}'>\n        <div id=\"gf_progressbar_wrapper_626\" class=\"gf_progressbar_wrapper\" data-start-at-zero=\"\">\n        \t<p class=\"gf_progressbar_title\">Passo <span class=\"gf_step_current_page\">1<\/span> di <span class=\"gf_step_page_count\">3<\/span><span class=\"gf_step_page_name\"><\/span>\n        \t<\/p>\n            <div class=\"gf_progressbar gf_progressbar_blue\" aria-hidden=\"true\">\n                <div class=\"gf_progressbar_percentage percentbar_blue percentbar_33\" style=\"width:33%;\"><span>33%<\/span><\/div>\n            <\/div><\/div>\n                        <div class=\"gform-body gform_body\"><div id=\"gform_page_626_1\" class=\"gform_page \" data-js=\"page-field-id-0\">\n\t\t\t\t\t<div class=\"gform_page_fields\"><div id=\"gform_fields_626\" class=\"gform_fields top_label form_sublabel_below description_below validation_below\"><fieldset id=\"field_626_1\" class=\"gfield gfield--type-quiz gfield--type-choice gfield--input-type-radio field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gquiz-field \" data-field-class=\"gquiz-field\"><legend class=\"gfield_label gform-field-label\">Cosa sono, secondo il testo, i &quot;Sephora Kids&quot;?<\/legend><div class=\"ginput_container ginput_container_radio\"><div class=\"gfield_radio\" id=\"input_626_1\">\n\t\t\t<div class=\"gchoice gchoice_626_1_0\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_1\" type=\"radio\" value=\"gquiz1b2b27084\" id=\"choice_626_1_0\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_626_1_0\" id=\"label_626_1_0\" class=\"gform-field-label gform-field-label--type-inline\">Bambini che imitano gli adulti truccandosi.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_626_1_1\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_1\" type=\"radio\" value=\"gquiz12c53da11\" id=\"choice_626_1_1\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_626_1_1\" id=\"label_626_1_1\" class=\"gform-field-label gform-field-label--type-inline\">Ragazze di et&agrave; inferiore ai 12 anni protagoniste di video in cui recensiscono prodotti di bellezza.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_626_1_2\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_1\" type=\"radio\" value=\"gquiz1b6725f5d\" id=\"choice_626_1_2\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_626_1_2\" id=\"label_626_1_2\" class=\"gform-field-label gform-field-label--type-inline\">Adolescenti che guidano le tendenze di bellezza sui <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Social network&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Il termine deriva dall&amp;#039;inglese social networking service o social networking site che significa servizio di rete sociale o sito di rete sociale. Si tratta di un servizio internet per la gestione di rapporti e reti sociali, fruibile attraverso browser o applicazioni (App) che permette consente la comunicazione e la condivisione di testi, audio, immagini e video.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/non-mi-piace-che-mia-madre-pubblichi-foto-di-me-sui-social-media\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&amp;#8220;Non mi piace che mia madre pubblichi foto di me sui social media&amp;#8221;.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/avvicinare-i-giovani-al-processo-decisionale-politico-una-sfida-urgente\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Avvicinare i giovani al processo decisionale politico: una sfida urgente&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Sephora Kids, un&amp;#8217;apologia virale della cosmeticoressia precoce&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-parlamento-determinera-la-traiettoria-delleuropa-del-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il Parlamento determiner&agrave; la traiettoria dell&rsquo;Europa del 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/xq-video-podcast-gli-impatti-dei-social-media-dalla-radicalizzazione-politica-alla-salute-mentale\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;XQ Video-Podcast. Gli impatti dei social media: dalla radicalizzazione politica alla salute mentale&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/social-network\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">social network<\/a>.<\/label>\n\t\t\t<\/div><\/div><\/div><\/fieldset><\/div>\n                    <\/div>\n                    <div class=\"gform-page-footer gform_page_footer top_label\">\n                         <input type=\"button\" id=\"gform_next_button_626_5\" class=\"gform_next_button gform-theme-button button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"next\" value=\"Avanti \"> \n                    <\/div>\n                <\/div>\n                <div id=\"gform_page_626_2\" class=\"gform_page\" data-js=\"page-field-id-5\" style=\"display:none;\">\n                    <div class=\"gform_page_fields\">\n                        <div id=\"gform_fields_626_2\" class=\"gform_fields top_label form_sublabel_below description_below validation_below\"><fieldset id=\"field_626_3\" class=\"gfield gfield--type-quiz gfield--type-choice gfield--input-type-radio gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gquiz-field \" data-field-class=\"gquiz-field\"><legend class=\"gfield_label gform-field-label\">Qual &egrave; il termine usato per descrivere la pratica dei genitori di postare attivamente sui social media i propri figli?<\/legend><div class=\"ginput_container ginput_container_radio\"><div class=\"gfield_radio\" id=\"input_626_3\">\n\t\t\t<div class=\"gchoice gchoice_626_3_0\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_3\" type=\"radio\" value=\"gquiz3394e91f2\" id=\"choice_626_3_0\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_626_3_0\" id=\"label_626_3_0\" class=\"gform-field-label gform-field-label--type-inline\">Sharenting.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_626_3_1\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_3\" type=\"radio\" value=\"gquiz3b5aa3d2d\" id=\"choice_626_3_1\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_626_3_1\" id=\"label_626_3_1\" class=\"gform-field-label gform-field-label--type-inline\">Sephora Kids.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_626_3_2\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_3\" type=\"radio\" value=\"gquiz3d1b23a18\" id=\"choice_626_3_2\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_626_3_2\" id=\"label_626_3_2\" class=\"gform-field-label gform-field-label--type-inline\">Cosmetorexia.<\/label>\n\t\t\t<\/div><\/div><\/div><\/fieldset><\/div>\n                    <\/div>\n                    <div class=\"gform-page-footer gform_page_footer top_label\">\n                        <input type=\"button\" id=\"gform_previous_button_626_6\" class=\"gform_previous_button gform-theme-button gform-theme-button--secondary button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"previous\" value=\"Precedente\"> <input type=\"button\" id=\"gform_next_button_626_6\" class=\"gform_next_button gform-theme-button button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"next\" value=\"Avanti \"> \n                    <\/div>\n                <\/div>\n                <div id=\"gform_page_626_3\" class=\"gform_page\" data-js=\"page-field-id-6\" style=\"display:none;\">\n                    <div class=\"gform_page_fields\">\n                        <div id=\"gform_fields_626_3\" class=\"gform_fields top_label form_sublabel_below description_below validation_below\"><fieldset id=\"field_626_4\" class=\"gfield gfield--type-quiz gfield--type-choice gfield--input-type-radio gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gquiz-field \" data-field-class=\"gquiz-field\"><legend class=\"gfield_label gform-field-label\">Cosa suggerisce la psicologa Conchita Sis&iacute; come soluzione al dibattito sull'uso dei <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Social network&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Il termine deriva dall&amp;#039;inglese social networking service o social networking site che significa servizio di rete sociale o sito di rete sociale. Si tratta di un servizio internet per la gestione di rapporti e reti sociali, fruibile attraverso browser o applicazioni (App) che permette consente la comunicazione e la condivisione di testi, audio, immagini e video.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/non-mi-piace-che-mia-madre-pubblichi-foto-di-me-sui-social-media\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&amp;#8220;Non mi piace che mia madre pubblichi foto di me sui social media&amp;#8221;.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/avvicinare-i-giovani-al-processo-decisionale-politico-una-sfida-urgente\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Avvicinare i giovani al processo decisionale politico: una sfida urgente&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Sephora Kids, un&amp;#8217;apologia virale della cosmeticoressia precoce&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-parlamento-determinera-la-traiettoria-delleuropa-del-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il Parlamento determiner&agrave; la traiettoria dell&rsquo;Europa del 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/xq-video-podcast-gli-impatti-dei-social-media-dalla-radicalizzazione-politica-alla-salute-mentale\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;XQ Video-Podcast. Gli impatti dei social media: dalla radicalizzazione politica alla salute mentale&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/social-network\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">social network<\/a> da parte dei minori?<\/legend><div class=\"ginput_container ginput_container_radio\"><div class=\"gfield_radio\" id=\"input_626_4\">\n\t\t\t<div class=\"gchoice gchoice_626_4_0\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_4\" type=\"radio\" value=\"gquiz46a62d494\" id=\"choice_626_4_0\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_626_4_0\" id=\"label_626_4_0\" class=\"gform-field-label gform-field-label--type-inline\">Vietarne completamente l&rsquo;uso.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_626_4_1\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_4\" type=\"radio\" value=\"gquiz488c89c8f\" id=\"choice_626_4_1\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_626_4_1\" id=\"label_626_4_1\" class=\"gform-field-label gform-field-label--type-inline\">Regolamentare l&rsquo;accesso ai <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Social network&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Il termine deriva dall&amp;#039;inglese social networking service o social networking site che significa servizio di rete sociale o sito di rete sociale. Si tratta di un servizio internet per la gestione di rapporti e reti sociali, fruibile attraverso browser o applicazioni (App) che permette consente la comunicazione e la condivisione di testi, audio, immagini e video.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/non-mi-piace-che-mia-madre-pubblichi-foto-di-me-sui-social-media\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&amp;#8220;Non mi piace che mia madre pubblichi foto di me sui social media&amp;#8221;.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/avvicinare-i-giovani-al-processo-decisionale-politico-una-sfida-urgente\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Avvicinare i giovani al processo decisionale politico: una sfida urgente&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Sephora Kids, un&amp;#8217;apologia virale della cosmeticoressia precoce&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-parlamento-determinera-la-traiettoria-delleuropa-del-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il Parlamento determiner&agrave; la traiettoria dell&rsquo;Europa del 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/xq-video-podcast-gli-impatti-dei-social-media-dalla-radicalizzazione-politica-alla-salute-mentale\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;XQ Video-Podcast. Gli impatti dei social media: dalla radicalizzazione politica alla salute mentale&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/social-network\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">social network<\/a>.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_626_4_2\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_4\" type=\"radio\" value=\"gquiz4054f68d8\" id=\"choice_626_4_2\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_626_4_2\" id=\"label_626_4_2\" class=\"gform-field-label gform-field-label--type-inline\">Coinvolgere i genitori in una guida positiva e in un attento <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Monitoraggio&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Il processo continuo di osservazione e raccolta di dati su una determinata specie, ecosistema o fenomeno ambientale al fine di valutarne lo stato e l&amp;#039;evoluzione.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/monitoraggio\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">monitoraggio<\/a>.<\/label>\n\t\t\t<\/div><\/div><\/div><\/fieldset><\/div><\/div>\n        <div class=\"gform-page-footer gform_page_footer top_label\"><input type=\"submit\" id=\"gform_previous_button_626\" class=\"gform_previous_button gform-theme-button gform-theme-button--secondary button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"previous\" value=\"Precedente\"> <input type=\"submit\" id=\"gform_submit_button_626\" class=\"gform_button button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"submit\" value=\"Inviare\"> \n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_submission_method\" data-js=\"gform_submission_method_626\" value=\"postback\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_theme\" data-js=\"gform_theme_626\" id=\"gform_theme_626\" value=\"gravity-theme\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_style_settings\" data-js=\"gform_style_settings_626\" id=\"gform_style_settings_626\" value='{\"inputPrimaryColor\":\"#204ce5\"}'>\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"is_submit_626\" value=\"1\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_submit\" value=\"626\">\n            \n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_currency\" data-currency=\"EUR\" value=\"RRzhkwjuai9SbFUBQgnQZq1L\/KWnb2fPLgkXstgkzqr4PG8lfAFigNWq9\/O+RnTyXz5mxaP9\/ZjTojt6WUa9RPR5XhWA3nWRNujpbDHARfZEpnw=\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_unique_id\" value=\"\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"state_626\" value=\"WyJbXSIsIjVlMjNlOGUzOTg5N2RmMzcwZmE1ODRlNDZjZGJmYjNkIl0=\">\n            <input type=\"hidden\" autocomplete=\"off\" class=\"gform_hidden\" name=\"gform_target_page_number_626\" id=\"gform_target_page_number_626\" value=\"2\">\n            <input type=\"hidden\" autocomplete=\"off\" class=\"gform_hidden\" name=\"gform_source_page_number_626\" id=\"gform_source_page_number_626\" value=\"1\">\n            <input type=\"hidden\" name=\"gform_field_values\" value=\"\">\n            \n        <\/div>\n             <\/div><\/div>\n                        <\/form>\n                        <\/div><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 626, 'https:\/\/xqthenews.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_626').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_626');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_626').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_626').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_626').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_626').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_626').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_626').val();gformInitSpinner( 626, 'https:\/\/xqthenews.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [626, current_page]);window['gf_submitting_626'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_626').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_626').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [626]);window['gf_submitting_626'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_626').text());}else{jQuery('#gform_626').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"626\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_626\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_626\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_626\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 626, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Il trend della Skincare, la cura della pelle, cos&igrave; diffusa sui social media, ha preso piede tra gli utenti minori di 12 anni, che recensiscono cosmetici su TikTok.<\/p>\n","protected":false},"author":26,"featured_media":20666,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[455,482],"tags":[121],"coauthors":[143],"class_list":{"0":"post-20793","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-i-social-media","8":"category-societa-e-cultura","9":"tag-reti"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Sephora Kids, un&#039;apologia virale della cosmeticoressia precoce - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sephora Kids, un&#039;apologia virale della cosmeticoressia precoce - xqthenews\" \/>\n<meta property=\"og:description\" content=\"Il trend della Skincare, la cura della pelle, cos&igrave; diffusa sui social media, ha preso piede tra gli utenti minori di 12 anni, che recensiscono cosmetici su TikTok.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-16T07:03:15+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-07T11:12:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/04\/SEPHORA-KIDS.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\n\t<meta property=\"og:image:height\" content=\"720\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Laura Casamitjana\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@Casamitjana\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura Casamitjana\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\\\/\"},\"author\":{\"name\":\"Laura Casamitjana\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/7c019326fd251f5591a24de1868c7feb\"},\"headline\":\"Sephora Kids, un&#8217;apologia virale della cosmeticoressia precoce\",\"datePublished\":\"2024-04-16T07:03:15+00:00\",\"dateModified\":\"2024-11-07T11:12:11+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\\\/\"},\"wordCount\":781,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/SEPHORA-KIDS.jpeg\",\"keywords\":[\"Reti\"],\"articleSection\":[\"I social media\",\"Societ\u00e0 e cultura\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/it\\\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\\\/\",\"name\":\"Sephora Kids, un'apologia virale della cosmeticoressia precoce - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/SEPHORA-KIDS.jpeg\",\"datePublished\":\"2024-04-16T07:03:15+00:00\",\"dateModified\":\"2024-11-07T11:12:11+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/7c019326fd251f5591a24de1868c7feb\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/it\\\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/SEPHORA-KIDS.jpeg\",\"contentUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/SEPHORA-KIDS.jpeg\",\"width\":1280,\"height\":720,\"caption\":\"\\\"Ragazze di et\u00e0 inferiore ai 12 anni diventate consumatrici di prodotti per la cura del viso, il trucco e la bellezza\\\" | Freepik\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sephora Kids, un&#8217;apologia virale della cosmeticoressia precoce\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/7c019326fd251f5591a24de1868c7feb\",\"name\":\"Laura Casamitjana\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/laura-casamitjana_avatar_1-96x96.jpg2771612100b03aa6d85fa2461866085b\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/laura-casamitjana_avatar_1-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/laura-casamitjana_avatar_1-96x96.jpg\",\"caption\":\"Laura Casamitjana\"},\"description\":\"Periodista. M\u00e1ster en Periodismo Literario, Comunicaci\u00f3n y Humanidades de la Universidad Aut\u00f3noma de Barcelona. Codirectora y coguionista del documental \u201cBerracas. Mujeres supervivientes que construyen la paz en Colombia\u201d. Actualmente redactora del medio Catalunya Plural, de la Fundaci\u00f3 Periodisme Plural, y XQ The News, de colaboraci\u00f3n europea.\",\"sameAs\":[\"https:\\\/\\\/x.com\\\/Casamitjana\"],\"url\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/author\\\/lcasamitjana\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Sephora Kids, un'apologia virale della cosmeticoressia precoce - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/","og_locale":"it_IT","og_type":"article","og_title":"Sephora Kids, un'apologia virale della cosmeticoressia precoce - xqthenews","og_description":"Il trend della Skincare, la cura della pelle, cos&igrave; diffusa sui social media, ha preso piede tra gli utenti minori di 12 anni, che recensiscono cosmetici su TikTok.","og_url":"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/","og_site_name":"xqthenews","article_published_time":"2024-04-16T07:03:15+00:00","article_modified_time":"2024-11-07T11:12:11+00:00","og_image":[{"width":1280,"height":720,"url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/04\/SEPHORA-KIDS.jpeg","type":"image\/jpeg"}],"author":"Laura Casamitjana","twitter_card":"summary_large_image","twitter_creator":"@Casamitjana","twitter_misc":{"Scritto da":"Laura Casamitjana","Tempo di lettura stimato":"4 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/#article","isPartOf":{"@id":"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/"},"author":{"name":"Laura Casamitjana","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/7c019326fd251f5591a24de1868c7feb"},"headline":"Sephora Kids, un&#8217;apologia virale della cosmeticoressia precoce","datePublished":"2024-04-16T07:03:15+00:00","dateModified":"2024-11-07T11:12:11+00:00","mainEntityOfPage":{"@id":"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/"},"wordCount":781,"commentCount":0,"image":{"@id":"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/04\/SEPHORA-KIDS.jpeg","keywords":["Reti"],"articleSection":["I social media","Societ\u00e0 e cultura"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/","url":"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/","name":"Sephora Kids, un'apologia virale della cosmeticoressia precoce - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/#primaryimage"},"image":{"@id":"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/04\/SEPHORA-KIDS.jpeg","datePublished":"2024-04-16T07:03:15+00:00","dateModified":"2024-11-07T11:12:11+00:00","author":{"@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/7c019326fd251f5591a24de1868c7feb"},"breadcrumb":{"@id":"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/#primaryimage","url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/04\/SEPHORA-KIDS.jpeg","contentUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/04\/SEPHORA-KIDS.jpeg","width":1280,"height":720,"caption":"\"Ragazze di et\u00e0 inferiore ai 12 anni diventate consumatrici di prodotti per la cura del viso, il trucco e la bellezza\" | Freepik"},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/it\/sephora-kids-unapologia-virale-della-cosmetorexia-precoce\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Sephora Kids, un&#8217;apologia virale della cosmeticoressia precoce"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/7c019326fd251f5591a24de1868c7feb","name":"Laura Casamitjana","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/laura-casamitjana_avatar_1-96x96.jpg2771612100b03aa6d85fa2461866085b","url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/laura-casamitjana_avatar_1-96x96.jpg","contentUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/laura-casamitjana_avatar_1-96x96.jpg","caption":"Laura Casamitjana"},"description":"Periodista. M\u00e1ster en Periodismo Literario, Comunicaci\u00f3n y Humanidades de la Universidad Aut\u00f3noma de Barcelona. Codirectora y coguionista del documental \u201cBerracas. Mujeres supervivientes que construyen la paz en Colombia\u201d. Actualmente redactora del medio Catalunya Plural, de la Fundaci\u00f3 Periodisme Plural, y XQ The News, de colaboraci\u00f3n europea.","sameAs":["https:\/\/x.com\/Casamitjana"],"url":"https:\/\/xqthenews.com\/it\/author\/lcasamitjana\/"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/posts\/20793","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/users\/26"}],"replies":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/comments?post=20793"}],"version-history":[{"count":2,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/posts\/20793\/revisions"}],"predecessor-version":[{"id":25692,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/posts\/20793\/revisions\/25692"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/media\/20666"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/media?parent=20793"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/categories?post=20793"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/tags?post=20793"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/coauthors?post=20793"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}