{"id":14335,"date":"2023-11-22T08:00:43","date_gmt":"2023-11-22T07:00:43","guid":{"rendered":"https:\/\/sad-borg.82-223-8-23.plesk.page\/?p=14335"},"modified":"2024-09-10T23:05:43","modified_gmt":"2024-09-10T22:05:43","slug":"lintelligenza-artificiale-viola-i-diritti-umani","status":"publish","type":"post","link":"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/","title":{"rendered":"L&#8217;intelligenza artificiale v\u00ecola i diritti umani?"},"content":{"rendered":"<p class=\"wp-block-paragraph\">L&rsquo;intelligenza artificiale (AI) &egrave; considerata la tecnologia che, pi&ugrave; di ogni altra, rivoluzioner&agrave; la Societ&agrave; trasformando l&rsquo;economia e il lavoro, le abitudini di vite quotidiana e le relazioni interpersonali.<\/p>\n\n<p class=\"wp-block-paragraph\"> L&rsquo;impressionante capacit&agrave; di queste macchine di migliorare automaticamente, attraverso sistemi di autoapprendimento, consente loro di elaborare quantit&agrave; di dati sempre pi&ugrave; grandi, in tempi sempre pi&ugrave; ridotti e con una qualit&agrave; sempre pi&ugrave; elevata.<\/p>\n\n<p class=\"wp-block-paragraph\">In questo modo si ampliano gli ambiti in cui gli algoritmi della AI vengono utilizzati, spaziando dalla produzione industriale alla sanit&agrave;, dalla finanza al commercio, dalla sicurezza alle arti, dalle tecniche di riconoscimento facciale all&rsquo;informazione, dall&rsquo;agricoltura al tempo libero, dalla giustizia alla lotta ai cambiamenti climatici e la previsione delle catastrofi naturali.<\/p>\n\n<p class=\"wp-block-paragraph\">Assieme all&rsquo;entusiasmo crescono per&ograve; anche le preoccupazioni.<\/p>\n\n<p class=\"wp-block-paragraph\">Alcuni pi&ugrave; catastrofisti temono che questi sistemi informatici super intelligenti possano sfuggire al controllo e dominare l&rsquo;Umanit&agrave;, ma si tratta di scenari poco realistici, legati all&rsquo;immaginario collettivo di film come Matrix o Blade Runner.<\/p>\n\n<p class=\"wp-block-paragraph\">Al contrario, esistono preoccupazione molto pi&ugrave; concrete che riguardano:<\/p>\n\n<ul class=\"wp-block-list\">\n<li>la protecci&oacute;n de la intimidad<\/li>\n\n\n\n<li>el riesgo de que las m&aacute;quinas tomen decisiones sanitarias o jur&iacute;dicas cruciales de forma injusta o err&oacute;nea<\/li>\n\n\n\n<li>la dificultad para que los ciudadanos comprendan la l&oacute;gica que subyace a tales decisiones<\/li>\n\n\n\n<li>la posibilidad de que la IA influya o manipule la conciencia humana<\/li>\n\n\n\n<li>los peligros de su utilizaci&oacute;n por la delincuencia malintencionada u organizada<\/li>\n\n\n\n<li>los efectos letales de su uso en el &aacute;mbito militar<\/li>\n\n\n\n<li>&bull; gli impatti sull&rsquo;occupazione.<\/li>\n\n\n\n<li>&bull; la crescita delle <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Disuguaglianze&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;La parola &amp;quot;disuguaglianza&rdquo; indica un tipo di differenza sociale nell&rsquo;accesso a risorse di varia natura da cui possono scaturire opportunit&agrave; di vita per ciascun individuo.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-parlamento-determinera-la-traiettoria-delleuropa-del-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il Parlamento determiner&agrave; la traiettoria dell&rsquo;Europa del 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/giornalismo-ed-educazione-il-perche-delle-notizie-nellera-della-disinformazione\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Giornalismo ed educazione: il perch&eacute; delle notizie nell&amp;#8217;era della disinformazione&nbsp;&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-ruolo-dei-giovani-nella-transizione-ecologica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il ruolo dei giovani nella transizione ecologica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/tassare-i-ricchi-liniziativa-dei-cittadini-europei-per-una-tassa-sui-ricchi-in-tutta-lue\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Tassare i ricchi: l&rsquo;Iniziativa dei Cittadini Europei per una tassa sui ricchi in tutta l&rsquo;UE&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/disuguaglianze\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">disuguaglianze<\/a> sociali.<\/li>\n\n\n\n<li>y muchas otras implicaciones t&eacute;cnicas, filos&oacute;ficas, jur&iacute;dicas y &eacute;ticas.&nbsp;<\/li>\n<\/ul>\n\n<p class=\"wp-block-paragraph\">In generale &egrave; possibile affermare che i processi decisionali automatizzati possono presentare rischi o errori ed &egrave; proprio per questo motivo che bisogna approfondire seriamente quali criteri dovrebbero essere sviluppati per misurare la qualit&agrave; del processo decisionale.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>L&rsquo;azione delle Istituzioni europee<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Nel febbraio 2020, la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Commissione europea&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&Egrave; l&amp;#039;organo esecutivo dell&amp;#039;Unione Europea, responsabile della proposta legislativa e della gestione delle politiche per conto dell&amp;#039;UE.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-vostro-cestino-del-pranzo-in-plastica-inquina-il-pianeta-e-il-vostro-sistema-endocrino\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il vostro cestino del pranzo in plastica inquina il pianeta e il vostro sistema endocrino&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/economia-circular-materia-organica-en-el-pasado-el-presente-y-el-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Economia circolare: la materia organica nel passato, presente e futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/a-dubai-il-vertice-mondiale-sul-clima-cop-28\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A Dubai il vertice mondiale sul clima COP 28&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/la-plastica-invade-i-mari-cronaca-di-un-nuovo-ecocidio-al-largo-della-costa-galiziana\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La plastica invade i mari: cronaca di un nuovo ecocidio al largo della costa galiziana&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/lemergenza-climatica-e-le-sfide-per-la-salute\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&rsquo;Emergenza climatica e le sfide per la salute&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/commissione-europea\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Commissione Europea<\/a> ha pubblicato un libro bianco sull&rsquo;intelligenza artificiale intitolato &ldquo;<a href=\"https:\/\/commission.europa.eu\/publications\/white-paper-artificial-intelligence-european-approach-excellence-and-trust_en\">Un approccio europeo all&rsquo;eccellenza e alla fiducia<\/a>&ldquo;.<\/p>\n\n<p class=\"wp-block-paragraph\">In questo documento si delineano quelli che dovranno essere i principi fondamentali di un futuro quadro normativo europeo, sottolineando l&rsquo;importanza che tale quadro sia fondato sui valori fondamentali dell&rsquo;UE, inclusi il rispetto dei diritti umani (come indicato all&rsquo;articolo 2 del Trattato sull&rsquo;Unione europea).<\/p>\n\n<p class=\"wp-block-paragraph\">Nell&rsquo;aprile 2021, la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Commissione europea&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&Egrave; l&amp;#039;organo esecutivo dell&amp;#039;Unione Europea, responsabile della proposta legislativa e della gestione delle politiche per conto dell&amp;#039;UE.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-vostro-cestino-del-pranzo-in-plastica-inquina-il-pianeta-e-il-vostro-sistema-endocrino\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il vostro cestino del pranzo in plastica inquina il pianeta e il vostro sistema endocrino&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/economia-circular-materia-organica-en-el-pasado-el-presente-y-el-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Economia circolare: la materia organica nel passato, presente e futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/a-dubai-il-vertice-mondiale-sul-clima-cop-28\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A Dubai il vertice mondiale sul clima COP 28&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/la-plastica-invade-i-mari-cronaca-di-un-nuovo-ecocidio-al-largo-della-costa-galiziana\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La plastica invade i mari: cronaca di un nuovo ecocidio al largo della costa galiziana&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/lemergenza-climatica-e-le-sfide-per-la-salute\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&rsquo;Emergenza climatica e le sfide per la salute&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/commissione-europea\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Commissione europea<\/a> ha presentato una proposta di legge volta a regolamentare l&rsquo;utilizzo dell&rsquo;intelligenza artificiale e nel dicembre 2022, il Consiglio dell&rsquo;Unione Europea ha chiarito la sua posizione in merito, rimandando al Parlamento europeo il compito di delineare la propria posizione.<\/p>\n\n<p class=\"wp-block-paragraph\">Al termine di questa procedura le tre istituzioni dovranno concordare su un testo comune.<\/p>\n\n<p class=\"wp-block-paragraph\"> Nel giugno 2023 &egrave; intanto stata diffusa l&rsquo;ultima edizione del Rapporto sui <a href=\"https:\/\/fra.europa.eu\/en\/publication\/2023\/fundamental-rights-report-2023\">diritti fondamentali 2023<\/a> a cura della FRA (Agenzia dell&rsquo;Unione Europea per i Diritti Fondamentali) che passa in rassegna i principali sviluppi del settore con una particolare attenzione all&rsquo;AI. La relazione si basa su 91 interviste condotte con funzionari della pubblica amministrazione e personale di aziende private in alcuni Stati membri dell&rsquo;UE. Gli intervistati sono stati interrogati sull&rsquo;uso dell&rsquo;IA, sulla loro consapevolezza delle questioni relative ai diritti fondamentali e sulle pratiche di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Valutazione&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;La valutazione economica di un asset, di solito immobiliare, effettuata da un esperto per determinarne il prezzo di mercato.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/qual-e-la-posizione-delle-aziende-e-della-societa-nei-confronti-delleconomia-circolare\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Qual &egrave; la posizione delle aziende e della societ&agrave; nei confronti dell&amp;#8217;economia circolare?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/tassare-i-ricchi-liniziativa-dei-cittadini-europei-per-una-tassa-sui-ricchi-in-tutta-lue\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Tassare i ricchi: l&rsquo;Iniziativa dei Cittadini Europei per una tassa sui ricchi in tutta l&rsquo;UE&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ripristinare-la-natura-storie-di-successo-dalleuropa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ripristinare la natura: storie di successo dall&amp;#8217;Europa&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/valutazione\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">valutazione<\/a> e <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mitigazione&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Strategie e azioni intraprese per ridurre o limitare le emissioni di gas serra al fine di minimizzare gli effetti del cambiamento climatico.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/disinformazione-sul-clima-una-minaccia-per-lazione-climatica-e-il-futuro-dei-giovani\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Disinformazione sul clima: una minaccia per l&amp;#8217;azione climatica e il futuro dei giovani&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-ruolo-dei-giovani-nella-transizione-ecologica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il ruolo dei giovani nella transizione ecologica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/limpatto-del-cambiamento-climatico-nel-sud-italia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&rsquo;impatto del cambiamento climatico nel sud Italia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-portogallo-tra-i-paesi-europei-piu-colpiti-da-eventi-meteorologici-estremi\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il portogallo tra i paesi europei pi&ugrave; colpiti da eventi meteorologici estremi&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/recuperare-le-buone-pratiche-agricole-per-sconfiggere-il-batterio-xylella\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Recuperare le buone pratiche agricole per sconfiggere il batterio Xylella&nbsp;&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mitigazione\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mitigazione<\/a> dei rischi associati all&rsquo;utilizzo delle nuove tecnologie.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>L&rsquo;appello dei docenti universitari<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">A settembre 2023 un gruppo di oltre 150 docenti universitari tra i pi&ugrave; autorevoli di tutta Europa nei campi dell&rsquo;intelligenza artificiale, della protezione dei dati e dei diritti fondamentali ha pubblicato un &ldquo;<a href=\"https:\/\/www.ansa.it\/english\/news\/science_tecnology\/2023\/09\/27\/ai-university-lecturers-appeal-to-eu-to-protect-rights_4d44fdba-ab2b-4ba0-a68c-49bf671877cd.html\">ha pubblicato un &ldquo;Appello urgente per l&rsquo;approvazione di una solida valutazione d&rsquo;impatto sui diritti fondamentali nella legge UE sull&rsquo;intelligenza artificiale<\/a>&rdquo;. I firmatari si sono rivolti direttamente ai rappresentanti del Consiglio dell&rsquo;Unione europea, della <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Commissione europea&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&Egrave; l&amp;#039;organo esecutivo dell&amp;#039;Unione Europea, responsabile della proposta legislativa e della gestione delle politiche per conto dell&amp;#039;UE.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-vostro-cestino-del-pranzo-in-plastica-inquina-il-pianeta-e-il-vostro-sistema-endocrino\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il vostro cestino del pranzo in plastica inquina il pianeta e il vostro sistema endocrino&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/economia-circular-materia-organica-en-el-pasado-el-presente-y-el-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Economia circolare: la materia organica nel passato, presente e futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/a-dubai-il-vertice-mondiale-sul-clima-cop-28\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;A Dubai il vertice mondiale sul clima COP 28&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/la-plastica-invade-i-mari-cronaca-di-un-nuovo-ecocidio-al-largo-della-costa-galiziana\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La plastica invade i mari: cronaca di un nuovo ecocidio al largo della costa galiziana&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/lemergenza-climatica-e-le-sfide-per-la-salute\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;L&rsquo;Emergenza climatica e le sfide per la salute&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/commissione-europea\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Commissione europea<\/a> e del Parlamento europeo affinch&eacute; intervengano sul regolamento sull&rsquo;intelligenza artificiale (AI Act) di imminente approvazione, inserendo l&rsquo;obbligo di valutare l&rsquo;impatto sui diritti fondamentali (Fria), non solo nei settori considerati ad alto rischio ma in tutti gli ambiti di applicazione della IA, pubblici che privati. Vista l&rsquo;alta posta in gioco, gli accademici si appellano al principio di regolamentazione precauzionale.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>La presa di posizione dell&rsquo;ONU<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">In una dichiarazione di luglio 2023 l&rsquo;Alto Commissario delle Nazioni Unite per i Diritti Umani, <a href=\"https:\/\/www.ohchr.org\/en\/statements\/2023\/07\/artificial-intelligence-must-be-grounded-human-rights-says-high-commissioner\">Volker Turk ha fatto un appello<\/a> per la regolamentazione del settore.<\/p>\n\n<p class=\"wp-block-paragraph\">Secondo Turk, occorre fissare dei limiti e guardare a ci&ograve; che accadr&agrave; all&rsquo;intelligenza artificiale e alle nuove tecnologie tenendo ben fissa la prospettiva sui diritti umani e alla necessit&agrave; di adottare misure di salvaguardia per mitigare i potenziali rischi derivanti dai progressi dell&rsquo;IA.<\/p>\n\n<p class=\"wp-block-paragraph\">Il richiamo a un coinvolgimento urgente da parte di aziende e governi per lo sviluppo di tali misure sottolinea l&rsquo;importanza di affrontare proattivamente le sfide etiche, di sicurezza, di contrasto alle &ldquo;conseguenze indesiderate&rdquo; e di individuazione chiara sulla responsabilit&agrave; che non possono essere ascritte ad una macchina ma vanno personalizzate. L&rsquo;attenzione posta sulla &ldquo;questione del coinvolgimento umano&rdquo; indica la preoccupazione per il possibile superamento dei limiti nell&rsquo;automazione decisionale, con implicazioni dirette sulla dignit&agrave; umana e sui diritti fondamentali.<\/p>\n\n<h2 class=\"wp-block-heading\"><strong>L&rsquo;allarme di Amnesty International<\/strong><\/h2>\n\n<p class=\"wp-block-paragraph\">Nell&rsquo;aprile 2023, la segretaria generale di <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Amnesty International&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;strong&amp;gt; &amp;lt;\/strong&amp;gt;Amnesty International &egrave; un movimento globale di persone, fondato sull&amp;#039;adesione volontaria&amp;lt;strong&amp;gt;,&amp;lt;\/strong&amp;gt; un&amp;#039;organizzazione non governativa internazionale impegnata nella difesa dei diritti umani.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ci-dicono-torna-al-tuo-paese-ma-vogliamo-lavorare-la-storia-di-tre-giovani-che-vivono-in-un-furgone\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&amp;#8220;Ci dicono &amp;#8216;torna al tuo Paese&rdquo;, ma vogliamo lavorare&amp;#8221;: la storia di tre giovani che vivono in un furgone.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/tiktok-i-pericoli-dellalgoritmo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;TikTok, i pericoli dell&rsquo;algoritmo.&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/amnesty-international\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Amnesty International<\/a>, <a href=\"https:\/\/www.amnesty.eu\/news\/the-eu-must-respect-human-rights-of-migrants-in-the-ai-act\/\">Agn&egrave;s Callamard<\/a>, assieme ad un gruppo di organizzazioni della societ&agrave; civile guidata dalla Rete europea per i diritti digitali, ha pubblicato una lettera aperta indirizzata ai relatori e ai membri delle principali commissioni responsabili dell&rsquo;Atto sull&rsquo;intelligenza artificiale dell&rsquo;Unione europea (AI Act), esortandoli a vietare l&rsquo;utilizzo di specifici sistemi di intelligenza artificiale ritenuti incompatibili con i diritti umani dei migranti, <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Rifugiati&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;I rifugiati sono persone che fuggono da conflitti o persecuzioni e cercano protezione in un altro Paese&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/emigrare-per-smettere-di-nascondersi\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Emigrare per smettere di nascondersi&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ci-dicono-torna-al-tuo-paese-ma-vogliamo-lavorare-la-storia-di-tre-giovani-che-vivono-in-un-furgone\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&amp;#8220;Ci dicono &amp;#8216;torna al tuo Paese&rdquo;, ma vogliamo lavorare&amp;#8221;: la storia di tre giovani che vivono in un furgone.&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/rifugiati\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">rifugiati<\/a> e richiedenti asilo.<\/p>\n\n<p class=\"wp-block-paragraph\">La lettera sottolinea la necessit&agrave; di proibire:<\/p>\n\n<p class=\"wp-block-paragraph\">1.&nbsp; Sistemas automatizados de evaluaci&oacute;n de riesgos y elaboraci&oacute;n de perfiles: estos sistemas, que se utilizan para determinar el &ldquo;riesgo&rdquo; de actividades ilegales que podr&iacute;an cometer los inmigrantes, se consideran inadecuados por entra&ntilde;ar riesgos de discriminaci&oacute;n, invasi&oacute;n de la intimidad, p&eacute;rdida de libertades fundamentales y seguridad individual.<\/p>\n\n<p class=\"wp-block-paragraph\">2. Sistemas anal&iacute;ticos predictivos para la gesti&oacute;n de la migraci&oacute;n: El uso de este tipo de sistemas, cuyo objetivo es interceptar, restringir e impedir las salidas, aumenta el riesgo de devoluci&oacute;n y de violaciones del derecho de asilo.<\/p>\n\n<p class=\"wp-block-paragraph\">3.&nbsp;Herramientas de detecci&oacute;n de emociones y &ldquo;detectores de mentiras&rdquo;: se trata de herramientas que amenazan expl&iacute;citamente los derechos fundamentales, como la no discriminaci&oacute;n, la libertad y las garant&iacute;as procesales.<\/p>\n\n<p class=\"wp-block-paragraph\">4.&nbsp;Identificaci&oacute;n biom&eacute;trica remota (IBR): herramientas que pueden facilitar la vigilancia masiva y discriminatoria.<\/p>\n\n<p class=\"wp-block-paragraph\"><a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Amnesty International&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&amp;lt;strong&amp;gt; &amp;lt;\/strong&amp;gt;Amnesty International &egrave; un movimento globale di persone, fondato sull&amp;#039;adesione volontaria&amp;lt;strong&amp;gt;,&amp;lt;\/strong&amp;gt; un&amp;#039;organizzazione non governativa internazionale impegnata nella difesa dei diritti umani.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ci-dicono-torna-al-tuo-paese-ma-vogliamo-lavorare-la-storia-di-tre-giovani-che-vivono-in-un-furgone\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&amp;#8220;Ci dicono &amp;#8216;torna al tuo Paese&rdquo;, ma vogliamo lavorare&amp;#8221;: la storia di tre giovani che vivono in un furgone.&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/tiktok-i-pericoli-dellalgoritmo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;TikTok, i pericoli dell&rsquo;algoritmo.&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/amnesty-international\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Amnesty International<\/a>, sottolineando anche la necessit&agrave; di vietare l&rsquo;esportazione di tali tecnologie, cerca di influenzare positivamente l&rsquo;AI Act, sottolineando l&rsquo;importanza di un approccio che salvaguardi i diritti umani nel contesto dell&rsquo;impiego sempre pi&ugrave; diffuso dell&rsquo;intelligenza artificiale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alla vigilia del varo di una normativa europea che regolamenter&agrave; il settore della AI, si moltiplicano le prese di posizione e gli appelli per una maggiore attenzione alla <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Tutela&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;&Eacute; la responsabilit&agrave; legale di prendersi cura e prendere decisioni per il benessere di un bambino quando i genitori non sono in grado di farlo. Include la custodia e la protezione.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/economia-circular-materia-organica-en-el-pasado-el-presente-y-el-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Economia circolare: la materia organica nel passato, presente e futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/in-crescita-i-rapporti-sessuali-a-rischio-tra-adolescenti\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;In crescita i rapporti sessuali a rischio tra adolescenti.&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/tutela\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">tutela<\/a> dei diritti fondamentali.<\/p>\n","protected":false},"author":36,"featured_media":14320,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[449,398],"tags":[164],"coauthors":[170],"class_list":["post-14335","post","type-post","status-publish","format-standard","has-post-thumbnail","category-intelligenza-artificiale","category-scienza-e-tecnologia","tag-derechos-humanos-it"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>L&#039;intelligenza artificiale v\u00ecola i diritti umani? - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"L&#039;intelligenza artificiale v\u00ecola i diritti umani? - xqthenews\" \/>\n<meta property=\"og:description\" content=\"Alla vigilia del varo di una normativa europea che regolamenter&agrave; il settore della AI, si moltiplicano le prese di posizione e gli appelli per una maggiore attenzione alla tutela dei diritti fondamentali.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:published_time\" content=\"2023-11-22T07:00:43+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-10T22:05:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2023\/11\/AI-.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1357\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Mario Maffei - IdeaDinamica\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mario Maffei - IdeaDinamica\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/lintelligenza-artificiale-viola-i-diritti-umani\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/lintelligenza-artificiale-viola-i-diritti-umani\\\/\"},\"author\":{\"name\":\"Mario Maffei - IdeaDinamica\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/c6c5bb632a7244afc68b863ad29e17e7\"},\"headline\":\"L&#8217;intelligenza artificiale v\u00ecola i diritti umani?\",\"datePublished\":\"2023-11-22T07:00:43+00:00\",\"dateModified\":\"2024-09-10T22:05:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/lintelligenza-artificiale-viola-i-diritti-umani\\\/\"},\"wordCount\":1105,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/lintelligenza-artificiale-viola-i-diritti-umani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/AI-.jpeg\",\"keywords\":[\"Derechos humanos\"],\"articleSection\":[\"Intelligenza artificiale\",\"Scienza e tecnologia\"],\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/it\\\/lintelligenza-artificiale-viola-i-diritti-umani\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/lintelligenza-artificiale-viola-i-diritti-umani\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/lintelligenza-artificiale-viola-i-diritti-umani\\\/\",\"name\":\"L'intelligenza artificiale v\u00ecola i diritti umani? - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/lintelligenza-artificiale-viola-i-diritti-umani\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/lintelligenza-artificiale-viola-i-diritti-umani\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/AI-.jpeg\",\"datePublished\":\"2023-11-22T07:00:43+00:00\",\"dateModified\":\"2024-09-10T22:05:43+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/c6c5bb632a7244afc68b863ad29e17e7\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/lintelligenza-artificiale-viola-i-diritti-umani\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/it\\\/lintelligenza-artificiale-viola-i-diritti-umani\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/lintelligenza-artificiale-viola-i-diritti-umani\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/AI-.jpeg\",\"contentUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2023\\\/11\\\/AI-.jpeg\",\"width\":1920,\"height\":1357},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/lintelligenza-artificiale-viola-i-diritti-umani\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"L&#8217;intelligenza artificiale v\u00ecola i diritti umani?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/c6c5bb632a7244afc68b863ad29e17e7\",\"name\":\"Mario Maffei - IdeaDinamica\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/mario-maffei-ideadinamica_avatar_1-96x96.jpegb2f7dc39aa6185cedad3b6ffa9e1b565\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/mario-maffei-ideadinamica_avatar_1-96x96.jpeg\",\"contentUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/mario-maffei-ideadinamica_avatar_1-96x96.jpeg\",\"caption\":\"Mario Maffei - IdeaDinamica\"},\"description\":\"Periodista profesional y divulgador m\u00e9dico-cient\u00edfico, licenciado en Econom\u00eda por la Universidad Bocconi de Mil\u00e1n con especializaci\u00f3n en marketing sanitario. Profesor en cursos de grado y posgrado. Consejero delegado de la cooperativa IdeaDinamica.\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/author\\\/mario-maffei-ideadinamica\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"L'intelligenza artificiale v\u00ecola i diritti umani? - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/","og_locale":"it_IT","og_type":"article","og_title":"L'intelligenza artificiale v\u00ecola i diritti umani? - xqthenews","og_description":"Alla vigilia del varo di una normativa europea che regolamenter&agrave; il settore della AI, si moltiplicano le prese di posizione e gli appelli per una maggiore attenzione alla tutela dei diritti fondamentali.","og_url":"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/","og_site_name":"xqthenews","article_published_time":"2023-11-22T07:00:43+00:00","article_modified_time":"2024-09-10T22:05:43+00:00","og_image":[{"width":1920,"height":1357,"url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2023\/11\/AI-.jpeg","type":"image\/jpeg"}],"author":"Mario Maffei - IdeaDinamica","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Mario Maffei - IdeaDinamica","Tempo di lettura stimato":"5 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/#article","isPartOf":{"@id":"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/"},"author":{"name":"Mario Maffei - IdeaDinamica","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/c6c5bb632a7244afc68b863ad29e17e7"},"headline":"L&#8217;intelligenza artificiale v\u00ecola i diritti umani?","datePublished":"2023-11-22T07:00:43+00:00","dateModified":"2024-09-10T22:05:43+00:00","mainEntityOfPage":{"@id":"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/"},"wordCount":1105,"commentCount":0,"image":{"@id":"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2023\/11\/AI-.jpeg","keywords":["Derechos humanos"],"articleSection":["Intelligenza artificiale","Scienza e tecnologia"],"inLanguage":"it-IT","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/","url":"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/","name":"L'intelligenza artificiale v\u00ecola i diritti umani? - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/#primaryimage"},"image":{"@id":"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2023\/11\/AI-.jpeg","datePublished":"2023-11-22T07:00:43+00:00","dateModified":"2024-09-10T22:05:43+00:00","author":{"@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/c6c5bb632a7244afc68b863ad29e17e7"},"breadcrumb":{"@id":"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/#primaryimage","url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2023\/11\/AI-.jpeg","contentUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2023\/11\/AI-.jpeg","width":1920,"height":1357},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/it\/lintelligenza-artificiale-viola-i-diritti-umani\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/it\/"},{"@type":"ListItem","position":2,"name":"L&#8217;intelligenza artificiale v\u00ecola i diritti umani?"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/c6c5bb632a7244afc68b863ad29e17e7","name":"Mario Maffei - IdeaDinamica","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/mario-maffei-ideadinamica_avatar_1-96x96.jpegb2f7dc39aa6185cedad3b6ffa9e1b565","url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/mario-maffei-ideadinamica_avatar_1-96x96.jpeg","contentUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/mario-maffei-ideadinamica_avatar_1-96x96.jpeg","caption":"Mario Maffei - IdeaDinamica"},"description":"Periodista profesional y divulgador m\u00e9dico-cient\u00edfico, licenciado en Econom\u00eda por la Universidad Bocconi de Mil\u00e1n con especializaci\u00f3n en marketing sanitario. Profesor en cursos de grado y posgrado. Consejero delegado de la cooperativa IdeaDinamica.","url":"https:\/\/xqthenews.com\/it\/author\/mario-maffei-ideadinamica\/"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/posts\/14335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/users\/36"}],"replies":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/comments?post=14335"}],"version-history":[{"count":0,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/posts\/14335\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/media\/14320"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/media?parent=14335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/categories?post=14335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/tags?post=14335"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/coauthors?post=14335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}