{"id":28840,"date":"2025-03-31T11:43:14","date_gmt":"2025-03-31T10:43:14","guid":{"rendered":"https:\/\/xqthenews.com\/glossary\/carestia\/"},"modified":"2025-03-31T11:50:34","modified_gmt":"2025-03-31T10:50:34","slug":"carestia","status":"publish","type":"glossary","link":"https:\/\/xqthenews.com\/it\/glossary\/carestia\/","title":{"rendered":"Carestia"},"content":{"rendered":"<p>La <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Carestia&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;La carestia &egrave; una grave carenza di cibo che causa fame e sofferenza di massa, spesso dovuta a disastri naturali, conflitti o problemi economici, colpendo grandi popolazioni.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\"  href=\"https:\/\/xqthenews.com\/it\/glossary\/carestia\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>carestia<\/a> &egrave; una grave carenza di cibo che causa fame e sofferenza di massa, spesso dovuta a <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Disastri naturali&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;I disastri naturali sono eventi improvvisi di origine naturale, spesso imprevedibili, che possono causare vittime e danni materiali considerevoli; influiscono gravemente sulla sicurezza delle persone, sulle condizioni di vita della popolazione e sulla struttura socioeconomica di un paese, a causa dell&rsquo;interruzione dei processi tra ambiente naturale e sistema sociale. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;(Fonte: Infop&eacute;dia)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/disastri-naturali\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">disastri naturali<\/a>, conflitti o problemi economici, colpendo grandi popolazioni.<\/p>\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Carestia&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;La carestia &egrave; una grave carenza di cibo che causa fame e sofferenza di massa, spesso dovuta a disastri naturali, conflitti o problemi economici, colpendo grandi popolazioni.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/carestia\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">carestia<\/a> &egrave; una grave carenza di cibo che causa fame e sofferenza di massa, spesso dovuta a <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Disastri naturali&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;I disastri naturali sono eventi improvvisi di origine naturale, spesso imprevedibili, che possono causare vittime e danni materiali considerevoli; influiscono gravemente sulla sicurezza delle persone, sulle condizioni di vita della popolazione e sulla struttura socioeconomica di un paese, a causa dell&rsquo;interruzione dei processi tra ambiente naturale e sistema sociale. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;(Fonte: Infop&eacute;dia)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/disastri-naturali\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">disastri naturali<\/a>, conflitti o problemi economici, colpendo grandi popolazioni.<\/p>\n","protected":false},"author":27,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[152],"class_list":["post-28840","glossary","type-glossary","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Carestia - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/it\/glossary\/carestia\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carestia - xqthenews\" \/>\n<meta property=\"og:description\" content=\"La carestia &egrave; una grave carenza di cibo che causa fame e sofferenza di massa, spesso dovuta a disastri naturali, conflitti o problemi economici, colpendo grandi popolazioni.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/it\/glossary\/carestia\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-31T10:50:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Le\u00f3n Var\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/carestia\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/carestia\\\/\",\"name\":\"Carestia - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"datePublished\":\"2025-03-31T10:43:14+00:00\",\"dateModified\":\"2025-03-31T10:50:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/carestia\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/carestia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/carestia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carestia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carestia - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/it\/glossary\/carestia\/","og_locale":"it_IT","og_type":"article","og_title":"Carestia - xqthenews","og_description":"La carestia &egrave; una grave carenza di cibo che causa fame e sofferenza di massa, spesso dovuta a disastri naturali, conflitti o problemi economici, colpendo grandi popolazioni.","og_url":"https:\/\/xqthenews.com\/it\/glossary\/carestia\/","og_site_name":"xqthenews","article_modified_time":"2025-03-31T10:50:34+00:00","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Manuel Le\u00f3n Var\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/it\/glossary\/carestia\/","url":"https:\/\/xqthenews.com\/it\/glossary\/carestia\/","name":"Carestia - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"datePublished":"2025-03-31T10:43:14+00:00","dateModified":"2025-03-31T10:50:34+00:00","breadcrumb":{"@id":"https:\/\/xqthenews.com\/it\/glossary\/carestia\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/it\/glossary\/carestia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/it\/glossary\/carestia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Carestia"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/28840","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":1,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/28840\/revisions"}],"predecessor-version":[{"id":28841,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/28840\/revisions\/28841"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/media?parent=28840"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/coauthors?post=28840"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}