{"id":27937,"date":"2025-03-02T21:45:02","date_gmt":"2025-03-02T20:45:02","guid":{"rendered":"https:\/\/xqthenews.com\/glossary\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\/"},"modified":"2025-03-02T21:58:07","modified_gmt":"2025-03-02T20:58:07","slug":"commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo","status":"publish","type":"glossary","link":"https:\/\/xqthenews.com\/it\/glossary\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\/","title":{"rendered":"Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo: Conosciuta anche come Commissione Brundtland, &egrave; stata un&amp;#039;iniziativa avviata nel 1983 per promuovere lo sviluppo sostenibile, con l&amp;#039;obiettivo di creare societ&agrave; pi&ugrave; giuste dal punto di vista ambientale e sociale.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/la-carta-della-terra-e-gli-obiettivi-di-sviluppo-sostenibile-principi-per-un-nuovo-modo-di-pensare-e-obiettivi-per-una-nuova-direzione\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La Carta della Terra e gli Obiettivi di Sviluppo Sostenibile: principi per un nuovo modo di pensare e obiettivi per una nuova direzione&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo<\/a>: Conosciuta anche come Commissione Brundtland, &egrave; stata un&rsquo;iniziativa avviata nel 1983 per promuovere lo sviluppo sostenibile, con l&rsquo;obiettivo di creare societ&agrave; pi&ugrave; giuste dal punto di vista ambientale e sociale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo: Conosciuta anche come Commissione Brundtland, &egrave; stata un&amp;#039;iniziativa avviata nel 1983 per promuovere lo sviluppo sostenibile, con l&amp;#039;obiettivo di creare societ&agrave; pi&ugrave; giuste dal punto di vista ambientale e sociale.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/la-carta-della-terra-e-gli-obiettivi-di-sviluppo-sostenibile-principi-per-un-nuovo-modo-di-pensare-e-obiettivi-per-una-nuova-direzione\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La Carta della Terra e gli Obiettivi di Sviluppo Sostenibile: principi per un nuovo modo di pensare e obiettivi per una nuova direzione&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo<\/a>: Conosciuta anche come Commissione Brundtland, &egrave; stata un&rsquo;iniziativa avviata nel 1983 per promuovere lo sviluppo sostenibile, con l&rsquo;obiettivo di creare societ&agrave; pi&ugrave; giuste dal punto di vista ambientale e sociale.<\/p>\n","protected":false},"author":27,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[152],"class_list":["post-27937","glossary","type-glossary","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/it\/glossary\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo - xqthenews\" \/>\n<meta property=\"og:description\" content=\"Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo: Conosciuta anche come Commissione Brundtland, &egrave; stata un&rsquo;iniziativa avviata nel 1983 per promuovere lo sviluppo sostenibile, con l&rsquo;obiettivo di creare societ&agrave; pi&ugrave; giuste dal punto di vista ambientale e sociale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/it\/glossary\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-02T20:58:07+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Le\u00f3n Var\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\\\/\",\"name\":\"Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"datePublished\":\"2025-03-02T20:45:02+00:00\",\"dateModified\":\"2025-03-02T20:58:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/it\/glossary\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\/","og_locale":"it_IT","og_type":"article","og_title":"Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo - xqthenews","og_description":"Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo: Conosciuta anche come Commissione Brundtland, &egrave; stata un&rsquo;iniziativa avviata nel 1983 per promuovere lo sviluppo sostenibile, con l&rsquo;obiettivo di creare societ&agrave; pi&ugrave; giuste dal punto di vista ambientale e sociale.","og_url":"https:\/\/xqthenews.com\/it\/glossary\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\/","og_site_name":"xqthenews","article_modified_time":"2025-03-02T20:58:07+00:00","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Manuel Le\u00f3n Var\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/it\/glossary\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\/","url":"https:\/\/xqthenews.com\/it\/glossary\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\/","name":"Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"datePublished":"2025-03-02T20:45:02+00:00","dateModified":"2025-03-02T20:58:07+00:00","breadcrumb":{"@id":"https:\/\/xqthenews.com\/it\/glossary\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/it\/glossary\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/it\/glossary\/commissione-mondiale-delle-nazioni-unite-su-ambiente-e-sviluppo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Commissione Mondiale delle Nazioni Unite su Ambiente e Sviluppo"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/27937","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":1,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/27937\/revisions"}],"predecessor-version":[{"id":27938,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/27937\/revisions\/27938"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/media?parent=27937"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/coauthors?post=27937"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}