{"id":25286,"date":"2024-10-28T10:09:31","date_gmt":"2024-10-28T09:09:31","guid":{"rendered":"https:\/\/xqthenews.com\/glossary\/ablazione\/"},"modified":"2024-10-28T10:14:32","modified_gmt":"2024-10-28T09:14:32","slug":"ablazione","status":"publish","type":"glossary","link":"https:\/\/xqthenews.com\/it\/glossary\/ablazione\/","title":{"rendered":"Ablazione"},"content":{"rendered":"<p>L&rsquo;<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Ablazione&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;L&rsquo;ablazione &egrave; la rimozione parziale o totale di un organo o di un tessuto dal corpo, solitamente eseguita per ragioni mediche. Nel contesto della mutilazione genitale femminile, si riferisce alla rimozione di parti dei genitali femminili. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/fatou-nyang-non-tutti-i-leader-religiosi-sono-a-favore-della-mutilazione-genitale-femminile\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Fatou Nyang: &amp;#8220;Non tutti i leader religiosi sono a favore della mutilazione genitale femminile&amp;#8221;&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/ablazione\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">ablazione<\/a> &egrave; la rimozione parziale o totale di un organo o di un tessuto dal corpo, solitamente eseguita per ragioni mediche. Nel contesto della <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mutilazione genitale femminile&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;La mutilazione genitale femminile &egrave; l&rsquo;alterazione o la rimozione parziale o totale dei genitali esterni femminili, eseguita per motivi non medici, che causa danni fisici e psicologici duraturi.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/fatou-nyang-non-tutti-i-leader-religiosi-sono-a-favore-della-mutilazione-genitale-femminile\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Fatou Nyang: &amp;#8220;Non tutti i leader religiosi sono a favore della mutilazione genitale femminile&amp;#8221;&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mutilazione-genitale-femminile\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mutilazione genitale femminile<\/a>, si riferisce alla rimozione di parti dei genitali femminili. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;<a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Ablazione&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;L&rsquo;ablazione &egrave; la rimozione parziale o totale di un organo o di un tessuto dal corpo, solitamente eseguita per ragioni mediche. Nel contesto della mutilazione genitale femminile, si riferisce alla rimozione di parti dei genitali femminili. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/fatou-nyang-non-tutti-i-leader-religiosi-sono-a-favore-della-mutilazione-genitale-femminile\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Fatou Nyang: &amp;#8220;Non tutti i leader religiosi sono a favore della mutilazione genitale femminile&amp;#8221;&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/ablazione\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">ablazione<\/a> &egrave; la rimozione parziale o totale di un organo o di un tessuto dal corpo, solitamente eseguita per ragioni mediche. Nel contesto della <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Mutilazione genitale femminile&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;La mutilazione genitale femminile &egrave; l&rsquo;alterazione o la rimozione parziale o totale dei genitali esterni femminili, eseguita per motivi non medici, che causa danni fisici e psicologici duraturi.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/fatou-nyang-non-tutti-i-leader-religiosi-sono-a-favore-della-mutilazione-genitale-femminile\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Fatou Nyang: &amp;#8220;Non tutti i leader religiosi sono a favore della mutilazione genitale femminile&amp;#8221;&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/mutilazione-genitale-femminile\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">mutilazione genitale femminile<\/a>, si riferisce alla rimozione di parti dei genitali femminili.<\/p>\n","protected":false},"author":27,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[152],"class_list":["post-25286","glossary","type-glossary","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ablazione - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/it\/glossary\/ablazione\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ablazione - xqthenews\" \/>\n<meta property=\"og:description\" content=\"L&rsquo;ablazione &egrave; la rimozione parziale o totale di un organo o di un tessuto dal corpo, solitamente eseguita per ragioni mediche. Nel contesto della mutilazione genitale femminile, si riferisce alla rimozione di parti dei genitali femminili.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/it\/glossary\/ablazione\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-28T09:14:32+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Le\u00f3n Var\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/ablazione\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/ablazione\\\/\",\"name\":\"Ablazione - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"datePublished\":\"2024-10-28T09:09:31+00:00\",\"dateModified\":\"2024-10-28T09:14:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/ablazione\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/ablazione\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/ablazione\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ablazione\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ablazione - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/it\/glossary\/ablazione\/","og_locale":"it_IT","og_type":"article","og_title":"Ablazione - xqthenews","og_description":"L&rsquo;ablazione &egrave; la rimozione parziale o totale di un organo o di un tessuto dal corpo, solitamente eseguita per ragioni mediche. Nel contesto della mutilazione genitale femminile, si riferisce alla rimozione di parti dei genitali femminili.","og_url":"https:\/\/xqthenews.com\/it\/glossary\/ablazione\/","og_site_name":"xqthenews","article_modified_time":"2024-10-28T09:14:32+00:00","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Manuel Le\u00f3n Var\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/it\/glossary\/ablazione\/","url":"https:\/\/xqthenews.com\/it\/glossary\/ablazione\/","name":"Ablazione - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"datePublished":"2024-10-28T09:09:31+00:00","dateModified":"2024-10-28T09:14:32+00:00","breadcrumb":{"@id":"https:\/\/xqthenews.com\/it\/glossary\/ablazione\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/it\/glossary\/ablazione\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/it\/glossary\/ablazione\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Ablazione"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/25286","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":1,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/25286\/revisions"}],"predecessor-version":[{"id":25287,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/25286\/revisions\/25287"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/media?parent=25286"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/coauthors?post=25286"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}