{"id":24858,"date":"2024-10-14T08:59:02","date_gmt":"2024-10-14T07:59:02","guid":{"rendered":"https:\/\/xqthenews.com\/glossary\/advocacy-e-attivismo\/"},"modified":"2024-10-14T09:28:35","modified_gmt":"2024-10-14T08:28:35","slug":"advocacy-e-attivismo","status":"publish","type":"glossary","link":"https:\/\/xqthenews.com\/it\/glossary\/advocacy-e-attivismo\/","title":{"rendered":"Advocacy e attivismo"},"content":{"rendered":"<p class=\"wp-block-paragraph\"><a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Advocacy e attivismo&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Advocacy e attivismo: Sforzi per sostenere, raccomandare o implementare azioni legate a cause importanti, come la protezione dell&rsquo;ambiente e la giustizia sociale, spesso guidati dai giovani.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-ruolo-dei-giovani-nella-transizione-ecologica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il ruolo dei giovani nella transizione ecologica&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/advocacy-e-attivismo\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Advocacy e attivismo<\/a>: Sforzi per sostenere, raccomandare o implementare azioni legate a cause importanti, come la protezione dell&rsquo;ambiente e la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Giustizia sociale&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Il concetto di giustizia sociale &egrave; emerso a met&agrave; del XIX secolo per indicare la necessit&agrave; di raggiungere una distribuzione equa dei beni sociali. In una societ&agrave; dove esiste giustizia sociale, i diritti umani sono rispettati e le classi sociali pi&ugrave; svantaggiate hanno opportunit&agrave; di sviluppo. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;(Fonte: Conceito.de)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/giornalismo-ed-educazione-il-perche-delle-notizie-nellera-della-disinformazione\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Giornalismo ed educazione: il perch&eacute; delle notizie nell&amp;#8217;era della disinformazione&nbsp;&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-ruolo-dei-giovani-nella-transizione-ecologica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il ruolo dei giovani nella transizione ecologica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/la-carta-della-terra-e-gli-obiettivi-di-sviluppo-sostenibile-principi-per-un-nuovo-modo-di-pensare-e-obiettivi-per-una-nuova-direzione\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La Carta della Terra e gli Obiettivi di Sviluppo Sostenibile: principi per un nuovo modo di pensare e obiettivi per una nuova direzione&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/giustizia-sociale\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">giustizia sociale<\/a>, spesso guidati dai giovani.<\/p>\n","protected":false},"excerpt":{"rendered":"<p><a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Advocacy e attivismo&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Advocacy e attivismo: Sforzi per sostenere, raccomandare o implementare azioni legate a cause importanti, come la protezione dell&rsquo;ambiente e la giustizia sociale, spesso guidati dai giovani.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-ruolo-dei-giovani-nella-transizione-ecologica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il ruolo dei giovani nella transizione ecologica&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/advocacy-e-attivismo\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Advocacy e attivismo<\/a>: Sforzi per sostenere, raccomandare o implementare azioni legate a cause importanti, come la protezione dell&rsquo;ambiente e la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Giustizia sociale&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;Il concetto di giustizia sociale &egrave; emerso a met&agrave; del XIX secolo per indicare la necessit&agrave; di raggiungere una distribuzione equa dei beni sociali. In una societ&agrave; dove esiste giustizia sociale, i diritti umani sono rispettati e le classi sociali pi&ugrave; svantaggiate hanno opportunit&agrave; di sviluppo. &amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;(Fonte: Conceito.de)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/giornalismo-ed-educazione-il-perche-delle-notizie-nellera-della-disinformazione\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Giornalismo ed educazione: il perch&eacute; delle notizie nell&amp;#8217;era della disinformazione&nbsp;&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-ruolo-dei-giovani-nella-transizione-ecologica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il ruolo dei giovani nella transizione ecologica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/parita-di-genere-e-rafforzamento-dellazione-per-il-clima\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Parit&agrave; di genere e rafforzamento dell&amp;#8217;azione per il clima&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/la-carta-della-terra-e-gli-obiettivi-di-sviluppo-sostenibile-principi-per-un-nuovo-modo-di-pensare-e-obiettivi-per-una-nuova-direzione\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La Carta della Terra e gli Obiettivi di Sviluppo Sostenibile: principi per un nuovo modo di pensare e obiettivi per una nuova direzione&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/giustizia-sociale\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">giustizia sociale<\/a>, spesso guidati dai giovani.<\/p>\n","protected":false},"author":27,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[152],"class_list":["post-24858","glossary","type-glossary","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Advocacy e attivismo - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/it\/glossary\/advocacy-e-attivismo\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Advocacy e attivismo - xqthenews\" \/>\n<meta property=\"og:description\" content=\"Advocacy e attivismo: Sforzi per sostenere, raccomandare o implementare azioni legate a cause importanti, come la protezione dell&rsquo;ambiente e la giustizia sociale, spesso guidati dai giovani.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/it\/glossary\/advocacy-e-attivismo\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-14T08:28:35+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Le\u00f3n Var\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/advocacy-e-attivismo\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/advocacy-e-attivismo\\\/\",\"name\":\"Advocacy e attivismo - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"datePublished\":\"2024-10-14T07:59:02+00:00\",\"dateModified\":\"2024-10-14T08:28:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/advocacy-e-attivismo\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/advocacy-e-attivismo\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/advocacy-e-attivismo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Advocacy e attivismo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Advocacy e attivismo - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/it\/glossary\/advocacy-e-attivismo\/","og_locale":"it_IT","og_type":"article","og_title":"Advocacy e attivismo - xqthenews","og_description":"Advocacy e attivismo: Sforzi per sostenere, raccomandare o implementare azioni legate a cause importanti, come la protezione dell&rsquo;ambiente e la giustizia sociale, spesso guidati dai giovani.","og_url":"https:\/\/xqthenews.com\/it\/glossary\/advocacy-e-attivismo\/","og_site_name":"xqthenews","article_modified_time":"2024-10-14T08:28:35+00:00","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Manuel Le\u00f3n Var\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/it\/glossary\/advocacy-e-attivismo\/","url":"https:\/\/xqthenews.com\/it\/glossary\/advocacy-e-attivismo\/","name":"Advocacy e attivismo - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"datePublished":"2024-10-14T07:59:02+00:00","dateModified":"2024-10-14T08:28:35+00:00","breadcrumb":{"@id":"https:\/\/xqthenews.com\/it\/glossary\/advocacy-e-attivismo\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/it\/glossary\/advocacy-e-attivismo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/it\/glossary\/advocacy-e-attivismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Advocacy e attivismo"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/24858","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":1,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/24858\/revisions"}],"predecessor-version":[{"id":24859,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/24858\/revisions\/24859"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/media?parent=24858"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/coauthors?post=24858"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}