{"id":19282,"date":"2024-03-04T12:09:31","date_gmt":"2024-03-04T11:09:31","guid":{"rendered":"https:\/\/sad-borg.82-223-8-23.plesk.page\/glossary\/libido\/"},"modified":"2024-03-04T12:22:13","modified_gmt":"2024-03-04T11:22:13","slug":"libido","status":"publish","type":"glossary","link":"https:\/\/xqthenews.com\/it\/glossary\/libido\/","title":{"rendered":"Libido"},"content":{"rendered":"<p class=\"wp-block-paragraph\">&Eacute; la pulsione o il desiderio sessuale. &Egrave; l&rsquo;energia psichica associata agli istinti sessuali e alla ricerca di gratificazione sessuale.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&Eacute; la pulsione o il desiderio sessuale. &Egrave; l&rsquo;energia psichica associata agli istinti sessuali e alla ricerca di gratificazione sessuale.<\/p>\n","protected":false},"author":27,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[152],"class_list":["post-19282","glossary","type-glossary","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Libido - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/it\/glossary\/libido\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Libido - xqthenews\" \/>\n<meta property=\"og:description\" content=\"&Eacute; la pulsione o il desiderio sessuale. &Egrave; l&rsquo;energia psichica associata agli istinti sessuali e alla ricerca di gratificazione sessuale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/it\/glossary\/libido\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-04T11:22:13+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Le\u00f3n Var\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/libido\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/libido\\\/\",\"name\":\"Libido - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"datePublished\":\"2024-03-04T11:09:31+00:00\",\"dateModified\":\"2024-03-04T11:22:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/libido\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/libido\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/glossary\\\/libido\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Libido\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Libido - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/it\/glossary\/libido\/","og_locale":"it_IT","og_type":"article","og_title":"Libido - xqthenews","og_description":"&Eacute; la pulsione o il desiderio sessuale. &Egrave; l&rsquo;energia psichica associata agli istinti sessuali e alla ricerca di gratificazione sessuale.","og_url":"https:\/\/xqthenews.com\/it\/glossary\/libido\/","og_site_name":"xqthenews","article_modified_time":"2024-03-04T11:22:13+00:00","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Manuel Le\u00f3n Var\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/it\/glossary\/libido\/","url":"https:\/\/xqthenews.com\/it\/glossary\/libido\/","name":"Libido - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"datePublished":"2024-03-04T11:09:31+00:00","dateModified":"2024-03-04T11:22:13+00:00","breadcrumb":{"@id":"https:\/\/xqthenews.com\/it\/glossary\/libido\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/it\/glossary\/libido\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/it\/glossary\/libido\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Libido"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/19282","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":0,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/19282\/revisions"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/media?parent=19282"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/coauthors?post=19282"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}