{"id":18621,"date":"2024-02-19T13:11:22","date_gmt":"2024-02-19T12:11:22","guid":{"rendered":"https:\/\/sad-borg.82-223-8-23.plesk.page\/glossary\/discriminazione-strutturale\/"},"modified":"2024-02-19T13:23:02","modified_gmt":"2024-02-19T12:23:02","slug":"discriminazione-strutturale","status":"publish","type":"glossary","link":"https:\/\/xqthenews.com\/it\/glossary\/discriminazione-strutturale\/","title":{"rendered":"Discriminazione strutturale"},"content":{"rendered":"<p class=\"wp-block-paragraph\">&Egrave; la perpetuazione delle <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Disuguaglianze&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;La parola &amp;quot;disuguaglianza&rdquo; indica un tipo di differenza sociale nell&rsquo;accesso a risorse di varia natura da cui possono scaturire opportunit&agrave; di vita per ciascun individuo.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-parlamento-determinera-la-traiettoria-delleuropa-del-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il Parlamento determiner&agrave; la traiettoria dell&rsquo;Europa del 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/giornalismo-ed-educazione-il-perche-delle-notizie-nellera-della-disinformazione\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Giornalismo ed educazione: il perch&eacute; delle notizie nell&amp;#8217;era della disinformazione&nbsp;&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-ruolo-dei-giovani-nella-transizione-ecologica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il ruolo dei giovani nella transizione ecologica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/tassare-i-ricchi-liniziativa-dei-cittadini-europei-per-una-tassa-sui-ricchi-in-tutta-lue\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Tassare i ricchi: l&rsquo;Iniziativa dei Cittadini Europei per una tassa sui ricchi in tutta l&rsquo;UE&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/disuguaglianze\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">disuguaglianze<\/a> sistemiche nelle istituzioni sociali e nelle pratiche che marginalizzano certi gruppi.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&Egrave; la perpetuazione delle <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Disuguaglianze&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph {&amp;quot;translatedWithWPMLTM&amp;quot;:&amp;quot;1&amp;quot;} --&amp;gt;La parola &amp;quot;disuguaglianza&rdquo; indica un tipo di differenza sociale nell&rsquo;accesso a risorse di varia natura da cui possono scaturire opportunit&agrave; di vita per ciascun individuo.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/ce-ancora-tempo-per-salvare-il-pianeta\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&amp;#8217;&egrave; ancora tempo per salvare il pianeta?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-parlamento-determinera-la-traiettoria-delleuropa-del-2030\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il Parlamento determiner&agrave; la traiettoria dell&rsquo;Europa del 2030&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/giornalismo-ed-educazione-il-perche-delle-notizie-nellera-della-disinformazione\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Giornalismo ed educazione: il perch&eacute; delle notizie nell&amp;#8217;era della disinformazione&nbsp;&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/il-ruolo-dei-giovani-nella-transizione-ecologica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Il ruolo dei giovani nella transizione ecologica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/tassare-i-ricchi-liniziativa-dei-cittadini-europei-per-una-tassa-sui-ricchi-in-tutta-lue\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Tassare i ricchi: l&rsquo;Iniziativa dei Cittadini Europei per una tassa sui ricchi in tutta l&rsquo;UE&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/it\/glossary\/disuguaglianze\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">disuguaglianze<\/a> sistemiche nelle istituzioni sociali e nelle pratiche che marginalizzano certi gruppi.<\/p>\n","protected":false},"author":27,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[152],"class_list":["post-18621","glossary","type-glossary","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Discriminazione strutturale - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/es\/glossary\/discriminacion-estructural\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Discriminazione strutturale - xqthenews\" \/>\n<meta property=\"og:description\" content=\"&Egrave; la perpetuazione delle disuguaglianze sistemiche nelle istituzioni sociali e nelle pratiche che marginalizzano certi gruppi.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/es\/glossary\/discriminacion-estructural\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:modified_time\" content=\"2024-02-19T12:23:02+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Le\u00f3n Var\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/discriminacion-estructural\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/discriminacion-estructural\\\/\",\"name\":\"Discriminazione strutturale - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"datePublished\":\"2024-02-19T12:11:22+00:00\",\"dateModified\":\"2024-02-19T12:23:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/discriminacion-estructural\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/discriminacion-estructural\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/discriminacion-estructural\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Discriminazione strutturale\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Discriminazione strutturale - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/es\/glossary\/discriminacion-estructural\/","og_locale":"it_IT","og_type":"article","og_title":"Discriminazione strutturale - xqthenews","og_description":"&Egrave; la perpetuazione delle disuguaglianze sistemiche nelle istituzioni sociali e nelle pratiche che marginalizzano certi gruppi.","og_url":"https:\/\/xqthenews.com\/es\/glossary\/discriminacion-estructural\/","og_site_name":"xqthenews","article_modified_time":"2024-02-19T12:23:02+00:00","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"Manuel Le\u00f3n Var\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/es\/glossary\/discriminacion-estructural\/","url":"https:\/\/xqthenews.com\/es\/glossary\/discriminacion-estructural\/","name":"Discriminazione strutturale - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"datePublished":"2024-02-19T12:11:22+00:00","dateModified":"2024-02-19T12:23:02+00:00","breadcrumb":{"@id":"https:\/\/xqthenews.com\/es\/glossary\/discriminacion-estructural\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/es\/glossary\/discriminacion-estructural\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/es\/glossary\/discriminacion-estructural\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/it\/"},{"@type":"ListItem","position":2,"name":"Discriminazione strutturale"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/18621","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":0,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/glossary\/18621\/revisions"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/media?parent=18621"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/it\/wp-json\/wp\/v2\/coauthors?post=18621"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}