{"id":23626,"date":"2024-09-11T17:50:23","date_gmt":"2024-09-11T16:50:23","guid":{"rendered":"https:\/\/xqthenews.com\/?p=23295"},"modified":"2024-09-18T11:08:24","modified_gmt":"2024-09-18T10:08:24","slug":"xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental","status":"publish","type":"post","link":"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/","title":{"rendered":"XQ Video-Podcast. El impacto de las redes sociales: De la radicalizaci\u00f3n pol\u00edtica a la salud mental"},"content":{"rendered":"<p>Durante las pr&aacute;cticas XQ.EUJOY en Barcelona, la Fundaci&oacute; Periodisme Plural y Octaedro acogieron a tres j&oacute;venes periodistas de toda Europa. Dalila Scagliusi, Maria Antonietta Mastropasqua y Miguel Santos presentan un podcast en v&iacute;deo en el que analizan el impacto de los medios sociales en diversos sectores. Con el apoyo de Cal Smith y Luca Lamorte, fundadores de DIIGIMA, los periodistas abordan el tema desde una perspectiva amplia, explorando sus efectos en todos los &aacute;mbitos, desde la salud hasta su papel como punto de inflexi&oacute;n en las democracias modernas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>&iquest;Est&aacute; la humanidad programada para satisfacer el deseo de recibir notificaciones?<\/strong><\/h2>\n\n\n\n<p>Las redes sociales suponen &laquo;un problema de salud p&uacute;blica, especialmente entre adolescentes y j&oacute;venes, y un peligro para la democracia&raquo;, seg&uacute;n afirman los investigadores Cristina Fern&aacute;ndez Rovira y Santiago Giraldo Luque en su libro &laquo;Segrestats per les xarxes&raquo;. En una entrevista, el profesor Giraldo destaca la idea err&oacute;nea de que los j&oacute;venes pueden controlar el uso que hacen de las redes sociales, y se&ntilde;ala que muchos admiten ser adictos. Estas plataformas, en lugar de fomentar conexiones significativas, promueven relaciones superficiales y contribuyen a la ansiedad, los trastornos alimentarios, la baja autoestima, el insomnio y el estr&eacute;s. Adem&aacute;s, elevan la fama, la violencia, el odio y la pornograf&iacute;a como valores sociales. Los autores reclaman medidas de protecci&oacute;n, como el reconocimiento de los derechos digitales, los neuroderechos y los derechos de salud mental, haciendo hincapi&eacute; en el derecho de la humanidad a desconectar.<\/p>\n\n\n\n<p>El periodista Joan Cascante, experto en<em> influencers <\/em>pol&iacute;ticos y comunidades online de extrema derecha, subraya adem&aacute;s el impacto de las redes sociales en la comunicaci&oacute;n pol&iacute;tica. Explica que estas plataformas han capacitado a los <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Ciudadanos&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Un concepto que implica cuestiones relacionadas con los derechos y los deberes, as&iacute; como con las ideas de igualdad, diversidad y justicia social. No s&oacute;lo referido al acto de votar, el concepto de ciudadan&iacute;a incluye todo un conjunto de acciones practicadas por cada persona, con impacto en la vida de la comunidad (local, nacional, regional e internacional), inseparable del espacio p&uacute;blico en el que las personas pueden actuar juntas.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;(Fuente: CIG &ndash; Comiss&atilde;o para a Cidadania e Igualde de G&eacute;nero)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mensaje-en-una-botella-o-los-plasticos-que-nunca-desaparecen\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mensaje en una botella, o los pl&aacute;sticos que nunca desaparecen&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/apartheid-en-palestina-las-raices-profundas-de-la-guerra\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Apartheid en Palestina, las ra&iacute;ces profundas de la guerra&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/luchar-contra-el-cambio-climatico-tambien-es-combatir-la-desinformacion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Luchar contra el cambio clim&aacute;tico tambi&eacute;n es combatir la desinformaci&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/ciudadania\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">ciudadanos<\/a> para asumir un papel m&aacute;s activo en la difusi&oacute;n de informaci&oacute;n. Sin embargo, los algoritmos que personalizan la experiencia digital crean bucles de retroalimentaci&oacute;n, limitando la exposici&oacute;n a opiniones contrarias. Este entorno, especialmente en YouTube, ha impulsado el auge de los influenciadores pol&iacute;ticos de extrema derecha, que explotan los algoritmos de recomendaci&oacute;n de la plataforma para guiar a la audiencia de contenidos moderados a otros m&aacute;s extremos.<\/p>\n\n\n\n<p><\/p>\n\n\n<script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\nvar gform;gform||(document.addEventListener(\"gform_main_scripts_loaded\",function(){gform.scriptsLoaded=!0}),document.addEventListener(\"gform\/theme\/scripts_loaded\",function(){gform.themeScriptsLoaded=!0}),window.addEventListener(\"DOMContentLoaded\",function(){gform.domLoaded=!0}),gform={domLoaded:!1,scriptsLoaded:!1,themeScriptsLoaded:!1,isFormEditor:()=>\"function\"==typeof InitializeEditor,callIfLoaded:function(o){return!(!gform.domLoaded||!gform.scriptsLoaded||!gform.themeScriptsLoaded&&!gform.isFormEditor()||(gform.isFormEditor()&&console.warn(\"The use of gform.initializeOnLoaded() is deprecated in the form editor context and will be removed in Gravity Forms 3.1.\"),o(),0))},initializeOnLoaded:function(o){gform.callIfLoaded(o)||(document.addEventListener(\"gform_main_scripts_loaded\",()=>{gform.scriptsLoaded=!0,gform.callIfLoaded(o)}),document.addEventListener(\"gform\/theme\/scripts_loaded\",()=>{gform.themeScriptsLoaded=!0,gform.callIfLoaded(o)}),window.addEventListener(\"DOMContentLoaded\",()=>{gform.domLoaded=!0,gform.callIfLoaded(o)}))},hooks:{action:{},filter:{}},addAction:function(o,r,e,t){gform.addHook(\"action\",o,r,e,t)},addFilter:function(o,r,e,t){gform.addHook(\"filter\",o,r,e,t)},doAction:function(o){gform.doHook(\"action\",o,arguments)},applyFilters:function(o){return gform.doHook(\"filter\",o,arguments)},removeAction:function(o,r){gform.removeHook(\"action\",o,r)},removeFilter:function(o,r,e){gform.removeHook(\"filter\",o,r,e)},addHook:function(o,r,e,t,n){null==gform.hooks[o][r]&&(gform.hooks[o][r]=[]);var d=gform.hooks[o][r];null==n&&(n=r+\"_\"+d.length),gform.hooks[o][r].push({tag:n,callable:e,priority:t=null==t?10:t})},doHook:function(r,o,e){var t;if(e=Array.prototype.slice.call(e,1),null!=gform.hooks[r][o]&&((o=gform.hooks[r][o]).sort(function(o,r){return o.priority-r.priority}),o.forEach(function(o){\"function\"!=typeof(t=o.callable)&&(t=window[t]),\"action\"==r?t.apply(null,e):e[0]=t.apply(null,e)})),\"filter\"==r)return e[0]},removeHook:function(o,r,t,n){var e;null!=gform.hooks[o][r]&&(e=(e=gform.hooks[o][r]).filter(function(o,r,e){return!!(null!=n&&n!=o.tag||null!=t&&t!=o.priority)}),gform.hooks[o][r]=e)}});\n\/* ]]> *\/\n<\/script>\n\n                <div class=\"gf_browser_gecko gform_wrapper gravity-theme gform-theme--no-framework quiz_wrapper\" data-form-theme=\"gravity-theme\" data-form-index=\"0\" id=\"gform_wrapper_762\"><div id=\"gf_762\" class=\"gform_anchor\" tabindex=\"-1\"><\/div>\n                        <div class=\"gform_heading\">\n                            <h2 class=\"gform_title\">Cuestionario de comprensi&oacute;n lectora. XQ Video-Podcast. El impacto de las redes sociales: De la radicalizaci&oacute;n pol&iacute;tica a la salud mental<\/h2>\n                            <p class=\"gform_description\"><\/p>\n                        <\/div><form method=\"post\" enctype=\"multipart\/form-data\" id=\"gform_762\" class=\"quiz\" action=\"\/es\/wp-json\/wp\/v2\/posts\/23626#gf_762\" data-formid=\"762\" novalidate> \r\n <input type=\"hidden\" class=\"gforms-pum\" value='{\"closepopup\":false,\"closedelay\":0,\"openpopup\":false,\"openpopup_id\":0}'>\n        <div id=\"gf_progressbar_wrapper_762\" class=\"gf_progressbar_wrapper\" data-start-at-zero=\"\">\n        \t<p class=\"gf_progressbar_title\">Paso <span class=\"gf_step_current_page\">1<\/span> de <span class=\"gf_step_page_count\">3<\/span><span class=\"gf_step_page_name\"><\/span>\n        \t<\/p>\n            <div class=\"gf_progressbar gf_progressbar_blue\" aria-hidden=\"true\">\n                <div class=\"gf_progressbar_percentage percentbar_blue percentbar_33\" style=\"width:33%;\"><span>33%<\/span><\/div>\n            <\/div><\/div>\n                        <div class=\"gform-body gform_body\"><div id=\"gform_page_762_1\" class=\"gform_page \" data-js=\"page-field-id-0\">\n\t\t\t\t\t<div class=\"gform_page_fields\"><div id=\"gform_fields_762\" class=\"gform_fields top_label form_sublabel_below description_below validation_below\"><fieldset id=\"field_762_1\" class=\"gfield gfield--type-quiz gfield--type-choice gfield--input-type-radio field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gquiz-field \" data-field-class=\"gquiz-field\"><legend class=\"gfield_label gform-field-label\">&iquest;Cu&aacute;l es el tema principal del podcast de v&iacute;deo creado por los tres j&oacute;venes periodistas durante las pr&aacute;cticas de XQ.EUJOY?<\/legend><div class=\"ginput_container ginput_container_radio\"><div class=\"gfield_radio\" id=\"input_762_1\">\n\t\t\t<div class=\"gchoice gchoice_762_1_0\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_1\" type=\"radio\" value=\"gquiz1b2b27084\" id=\"choice_762_1_0\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_762_1_0\" id=\"label_762_1_0\" class=\"gform-field-label gform-field-label--type-inline\">El papel de los influenciadores pol&iacute;ticos de extrema derecha.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_762_1_1\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_1\" type=\"radio\" value=\"gquiz12c53da11\" id=\"choice_762_1_1\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_762_1_1\" id=\"label_762_1_1\" class=\"gform-field-label gform-field-label--type-inline\">El impacto de las redes sociales en diversos sectores.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_762_1_2\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_1\" type=\"radio\" value=\"gquiz1b6725f5d\" id=\"choice_762_1_2\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_762_1_2\" id=\"label_762_1_2\" class=\"gform-field-label gform-field-label--type-inline\">La historia de la democracia en Europa.<\/label>\n\t\t\t<\/div><\/div><\/div><\/fieldset><\/div>\n                    <\/div>\n                    <div class=\"gform-page-footer gform_page_footer top_label\">\n                         <input type=\"button\" id=\"gform_next_button_762_5\" class=\"gform_next_button gform-theme-button button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"next\" value=\"Siguiente \"> \n                    <\/div>\n                <\/div>\n                <div id=\"gform_page_762_2\" class=\"gform_page\" data-js=\"page-field-id-5\" style=\"display:none;\">\n                    <div class=\"gform_page_fields\">\n                        <div id=\"gform_fields_762_2\" class=\"gform_fields top_label form_sublabel_below description_below validation_below\"><fieldset id=\"field_762_3\" class=\"gfield gfield--type-quiz gfield--type-choice gfield--input-type-radio gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gquiz-field \" data-field-class=\"gquiz-field\"><legend class=\"gfield_label gform-field-label\">Seg&uacute;n el profesor Giraldo, &iquest;cu&aacute;l es un error com&uacute;n sobre los j&oacute;venes y las redes sociales?<\/legend><div class=\"ginput_container ginput_container_radio\"><div class=\"gfield_radio\" id=\"input_762_3\">\n\t\t\t<div class=\"gchoice gchoice_762_3_0\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_3\" type=\"radio\" value=\"gquiz3394e91f2\" id=\"choice_762_3_0\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_762_3_0\" id=\"label_762_3_0\" class=\"gform-field-label gform-field-label--type-inline\">Hacen un uso responsable de las redes sociales.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_762_3_1\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_3\" type=\"radio\" value=\"gquiz3b5aa3d2d\" id=\"choice_762_3_1\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_762_3_1\" id=\"label_762_3_1\" class=\"gform-field-label gform-field-label--type-inline\">No se ven afectados por la influencia negativa de las redes sociales.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_762_3_2\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_3\" type=\"radio\" value=\"gquiz3d1b23a18\" id=\"choice_762_3_2\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_762_3_2\" id=\"label_762_3_2\" class=\"gform-field-label gform-field-label--type-inline\">Creen que pueden controlar el uso que hacen de las redes sociales, pero a menudo no es as&iacute;.<\/label>\n\t\t\t<\/div><\/div><\/div><\/fieldset><\/div>\n                    <\/div>\n                    <div class=\"gform-page-footer gform_page_footer top_label\">\n                        <input type=\"button\" id=\"gform_previous_button_762_6\" class=\"gform_previous_button gform-theme-button gform-theme-button--secondary button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"previous\" value=\"Anterior\"> <input type=\"button\" id=\"gform_next_button_762_6\" class=\"gform_next_button gform-theme-button button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"next\" value=\"Siguiente \"> \n                    <\/div>\n                <\/div>\n                <div id=\"gform_page_762_3\" class=\"gform_page\" data-js=\"page-field-id-6\" style=\"display:none;\">\n                    <div class=\"gform_page_fields\">\n                        <div id=\"gform_fields_762_3\" class=\"gform_fields top_label form_sublabel_below description_below validation_below\"><fieldset id=\"field_762_4\" class=\"gfield gfield--type-quiz gfield--type-choice gfield--input-type-radio gfield--width-full field_sublabel_below gfield--no-description field_description_below field_validation_below gfield_visibility_visible gquiz-field \" data-field-class=\"gquiz-field\"><legend class=\"gfield_label gform-field-label\">&iquest;C&oacute;mo influyen los algoritmos de las redes sociales en la comunicaci&oacute;n pol&iacute;tica, seg&uacute;n Joan Cascante?<\/legend><div class=\"ginput_container ginput_container_radio\"><div class=\"gfield_radio\" id=\"input_762_4\">\n\t\t\t<div class=\"gchoice gchoice_762_4_0\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_4\" type=\"radio\" value=\"gquiz46a62d494\" id=\"choice_762_4_0\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_762_4_0\" id=\"label_762_4_0\" class=\"gform-field-label gform-field-label--type-inline\">Ayudan a exponer a los usuarios a diversos puntos de vista pol&iacute;ticos.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_762_4_1\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_4\" type=\"radio\" value=\"gquiz488c89c8f\" id=\"choice_762_4_1\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_762_4_1\" id=\"label_762_4_1\" class=\"gform-field-label gform-field-label--type-inline\">Crean bucles de retroalimentaci&oacute;n, limitando la exposici&oacute;n a diferentes perspectivas.<\/label>\n\t\t\t<\/div>\n\t\t\t<div class=\"gchoice gchoice_762_4_2\">\n\t\t\t\t\t<input class=\"gfield-choice-input\" name=\"input_4\" type=\"radio\" value=\"gquiz4054f68d8\" id=\"choice_762_4_2\" onchange=\"gformToggleRadioOther( this )\">\n\t\t\t\t\t<label for=\"choice_762_4_2\" id=\"label_762_4_2\" class=\"gform-field-label gform-field-label--type-inline\">No influyen en el contenido pol&iacute;tico.<\/label>\n\t\t\t<\/div><\/div><\/div><\/fieldset><\/div><\/div>\n        <div class=\"gform-page-footer gform_page_footer top_label\"><input type=\"submit\" id=\"gform_previous_button_762\" class=\"gform_previous_button gform-theme-button gform-theme-button--secondary button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"previous\" value=\"Anterior\"> <input type=\"submit\" id=\"gform_submit_button_762\" class=\"gform_button button\" onclick=\"gform.submission.handleButtonClick(this);\" data-submission-type=\"submit\" value=\"Enviar\"> \n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_submission_method\" data-js=\"gform_submission_method_762\" value=\"postback\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_theme\" data-js=\"gform_theme_762\" id=\"gform_theme_762\" value=\"gravity-theme\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_style_settings\" data-js=\"gform_style_settings_762\" id=\"gform_style_settings_762\" value='{\"inputPrimaryColor\":\"#204ce5\"}'>\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"is_submit_762\" value=\"1\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_submit\" value=\"762\">\n            \n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_currency\" data-currency=\"EUR\" value=\"pdWBMClVECkiKNvrhree8OXff2xqQkBtvpf9SaSnWmA22A5udcvZoDgOP\/w+K4\/jJnj\/XePQyZegxgLyF54f8gL34LLGflcv8xLycldHtHK9Rtw=\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"gform_unique_id\" value=\"\">\n            <input type=\"hidden\" class=\"gform_hidden\" name=\"state_762\" value=\"WyJbXSIsIjVlMjNlOGUzOTg5N2RmMzcwZmE1ODRlNDZjZGJmYjNkIl0=\">\n            <input type=\"hidden\" autocomplete=\"off\" class=\"gform_hidden\" name=\"gform_target_page_number_762\" id=\"gform_target_page_number_762\" value=\"2\">\n            <input type=\"hidden\" autocomplete=\"off\" class=\"gform_hidden\" name=\"gform_source_page_number_762\" id=\"gform_source_page_number_762\" value=\"1\">\n            <input type=\"hidden\" name=\"gform_field_values\" value=\"\">\n            \n        <\/div>\n             <\/div><\/div>\n                        <\/form>\n                        <\/div><script type=\"text\/javascript\">\n\/* <![CDATA[ *\/\n gform.initializeOnLoaded( function() {gformInitSpinner( 762, 'https:\/\/xqthenews.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery('#gform_ajax_frame_762').on('load',function(){var contents = jQuery(this).contents().find('*').html();var is_postback = contents.indexOf('GF_AJAX_POSTBACK') >= 0;if(!is_postback){return;}var form_content = jQuery(this).contents().find('#gform_wrapper_762');var is_confirmation = jQuery(this).contents().find('#gform_confirmation_wrapper_762').length > 0;var is_redirect = contents.indexOf('gformRedirect(){') >= 0;var is_form = form_content.length > 0 && ! is_redirect && ! is_confirmation;var mt = parseInt(jQuery('html').css('margin-top'), 10) + parseInt(jQuery('body').css('margin-top'), 10) + 100;if(is_form){jQuery('#gform_wrapper_762').html(form_content.html());if(form_content.hasClass('gform_validation_error')){jQuery('#gform_wrapper_762').addClass('gform_validation_error');} else {jQuery('#gform_wrapper_762').removeClass('gform_validation_error');}setTimeout( function() { \/* delay the scroll by 50 milliseconds to fix a bug in chrome *\/ jQuery(document).scrollTop(jQuery('#gform_wrapper_762').offset().top - mt); }, 50 );if(window['gformInitDatepicker']) {gformInitDatepicker();}if(window['gformInitPriceFields']) {gformInitPriceFields();}var current_page = jQuery('#gform_source_page_number_762').val();gformInitSpinner( 762, 'https:\/\/xqthenews.com\/wp-content\/plugins\/gravityforms\/images\/spinner.svg', true );jQuery(document).trigger('gform_page_loaded', [762, current_page]);window['gf_submitting_762'] = false;}else if(!is_redirect){var confirmation_content = jQuery(this).contents().find('.GF_AJAX_POSTBACK').html();if(!confirmation_content){confirmation_content = contents;}jQuery('#gform_wrapper_762').replaceWith(confirmation_content);jQuery(document).scrollTop(jQuery('#gf_762').offset().top - mt);jQuery(document).trigger('gform_confirmation_loaded', [762]);window['gf_submitting_762'] = false;wp.a11y.speak(jQuery('#gform_confirmation_message_762').text());}else{jQuery('#gform_762').append(contents);if(window['gformRedirect']) {gformRedirect();}}jQuery(document).trigger(\"gform_pre_post_render\", [{ formId: \"762\", currentPage: \"current_page\", abort: function() { this.preventDefault(); } }]);        if (event && event.defaultPrevented) {                return;        }        const gformWrapperDiv = document.getElementById( \"gform_wrapper_762\" );        if ( gformWrapperDiv ) {            const visibilitySpan = document.createElement( \"span\" );            visibilitySpan.id = \"gform_visibility_test_762\";            gformWrapperDiv.insertAdjacentElement( \"afterend\", visibilitySpan );        }        const visibilityTestDiv = document.getElementById( \"gform_visibility_test_762\" );        let postRenderFired = false;        function triggerPostRender() {            if ( postRenderFired ) {                return;            }            postRenderFired = true;            gform.core.triggerPostRenderEvents( 762, current_page );            if ( visibilityTestDiv ) {                visibilityTestDiv.parentNode.removeChild( visibilityTestDiv );            }        }        function debounce( func, wait, immediate ) {            var timeout;            return function() {                var context = this, args = arguments;                var later = function() {                    timeout = null;                    if ( !immediate ) func.apply( context, args );                };                var callNow = immediate && !timeout;                clearTimeout( timeout );                timeout = setTimeout( later, wait );                if ( callNow ) func.apply( context, args );            };        }        const debouncedTriggerPostRender = debounce( function() {            triggerPostRender();        }, 200 );        if ( visibilityTestDiv && visibilityTestDiv.offsetParent === null ) {            const observer = new MutationObserver( ( mutations ) => {                mutations.forEach( ( mutation ) => {                    if ( mutation.type === 'attributes' && visibilityTestDiv.offsetParent !== null ) {                        debouncedTriggerPostRender();                        observer.disconnect();                    }                });            });            observer.observe( document.body, {                attributes: true,                childList: false,                subtree: true,                attributeFilter: [ 'style', 'class' ],            });        } else {            triggerPostRender();        }    } );} ); \n\/* ]]> *\/\n<\/script>\n\n\n\n<p><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Las redes sociales est&aacute;n dando forma a las democracias modernas y afectando a la salud p&uacute;blica, especialmente entre los j&oacute;venes. En un podcast en v&iacute;deo, tres periodistas europeos analizan su amplio impacto, haci&eacute;ndose eco de las preocupaciones de los expertos sobre la adicci&oacute;n, los problemas de salud mental y el auge de los influencers pol&iacute;ticos radicales.<\/p>\n","protected":false},"author":15,"featured_media":23759,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"video","meta":{"_acf_changed":false,"footnotes":""},"categories":[361],"tags":[526],"coauthors":[72],"class_list":{"0":"post-23626","1":"post","2":"type-post","3":"status-publish","4":"format-video","5":"has-post-thumbnail","7":"category-sociedad-y-cultura","8":"tag-democracia","9":"post_format-post-format-video"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>XQ Video-Podcast. El impacto de las redes sociales: De la radicalizaci\u00f3n pol\u00edtica a la salud mental - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"XQ Video-Podcast. El impacto de las redes sociales: De la radicalizaci\u00f3n pol\u00edtica a la salud mental - xqthenews\" \/>\n<meta property=\"og:description\" content=\"Las redes sociales est&aacute;n dando forma a las democracias modernas y afectando a la salud p&uacute;blica, especialmente entre los j&oacute;venes. En un podcast en v&iacute;deo, tres periodistas europeos analizan su amplio impacto, haci&eacute;ndose eco de las preocupaciones de los expertos sobre la adicci&oacute;n, los problemas de salud mental y el auge de los influencers pol&iacute;ticos radicales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:published_time\" content=\"2024-09-11T16:50:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-18T10:08:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/video-podcast.png\" \/>\n\t<meta property=\"og:image:width\" content=\"600\" \/>\n\t<meta property=\"og:image:height\" content=\"336\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Redacci\u00f3n\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Redacci\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Redacci\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\\\/\"},\"author\":{\"name\":\"Redacci\u00f3n\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/f3be5e6d9c8154bf65749ee40ff13d40\"},\"headline\":\"XQ Video-Podcast. El impacto de las redes sociales: De la radicalizaci\u00f3n pol\u00edtica a la salud mental\",\"datePublished\":\"2024-09-11T16:50:23+00:00\",\"dateModified\":\"2024-09-18T10:08:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\\\/\"},\"wordCount\":388,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/video-podcast.png\",\"keywords\":[\"Democracia\"],\"articleSection\":[\"Sociedad y cultura\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/es\\\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\\\/\",\"name\":\"XQ Video-Podcast. El impacto de las redes sociales: De la radicalizaci\u00f3n pol\u00edtica a la salud mental - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/video-podcast.png\",\"datePublished\":\"2024-09-11T16:50:23+00:00\",\"dateModified\":\"2024-09-18T10:08:24+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/f3be5e6d9c8154bf65749ee40ff13d40\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/es\\\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/video-podcast.png\",\"contentUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/video-podcast.png\",\"width\":600,\"height\":336},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"XQ Video-Podcast. El impacto de las redes sociales: De la radicalizaci\u00f3n pol\u00edtica a la salud mental\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/f3be5e6d9c8154bf65749ee40ff13d40\",\"name\":\"Redacci\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/166fa34ade28f01051b021552fbb62c0491752a7b2fb97fc79a7952cb140f2e2?s=96&d=mm&r=gd91ac5233e8cbeeaec8eb828daaa977e\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/166fa34ade28f01051b021552fbb62c0491752a7b2fb97fc79a7952cb140f2e2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/166fa34ade28f01051b021552fbb62c0491752a7b2fb97fc79a7952cb140f2e2?s=96&d=mm&r=g\",\"caption\":\"Redacci\u00f3n\"},\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/author\\\/redaccion\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"XQ Video-Podcast. El impacto de las redes sociales: De la radicalizaci\u00f3n pol\u00edtica a la salud mental - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/","og_locale":"es_ES","og_type":"article","og_title":"XQ Video-Podcast. El impacto de las redes sociales: De la radicalizaci\u00f3n pol\u00edtica a la salud mental - xqthenews","og_description":"Las redes sociales est&aacute;n dando forma a las democracias modernas y afectando a la salud p&uacute;blica, especialmente entre los j&oacute;venes. En un podcast en v&iacute;deo, tres periodistas europeos analizan su amplio impacto, haci&eacute;ndose eco de las preocupaciones de los expertos sobre la adicci&oacute;n, los problemas de salud mental y el auge de los influencers pol&iacute;ticos radicales.","og_url":"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/","og_site_name":"xqthenews","article_published_time":"2024-09-11T16:50:23+00:00","article_modified_time":"2024-09-18T10:08:24+00:00","og_image":[{"width":600,"height":336,"url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/video-podcast.png","type":"image\/png"}],"author":"Redacci\u00f3n","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Redacci\u00f3n","Tiempo de lectura":"2 minutos","Written by":"Redacci\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/#article","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/"},"author":{"name":"Redacci\u00f3n","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/f3be5e6d9c8154bf65749ee40ff13d40"},"headline":"XQ Video-Podcast. El impacto de las redes sociales: De la radicalizaci\u00f3n pol\u00edtica a la salud mental","datePublished":"2024-09-11T16:50:23+00:00","dateModified":"2024-09-18T10:08:24+00:00","mainEntityOfPage":{"@id":"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/"},"wordCount":388,"commentCount":0,"image":{"@id":"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/video-podcast.png","keywords":["Democracia"],"articleSection":["Sociedad y cultura"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/","url":"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/","name":"XQ Video-Podcast. El impacto de las redes sociales: De la radicalizaci\u00f3n pol\u00edtica a la salud mental - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/#primaryimage"},"image":{"@id":"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/video-podcast.png","datePublished":"2024-09-11T16:50:23+00:00","dateModified":"2024-09-18T10:08:24+00:00","author":{"@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/f3be5e6d9c8154bf65749ee40ff13d40"},"breadcrumb":{"@id":"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/#primaryimage","url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/video-podcast.png","contentUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/video-podcast.png","width":600,"height":336},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/es\/xq-video-podcast-el-impacto-de-las-redes-sociales-de-la-radicalizacion-politica-a-la-salud-mental\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/es\/"},{"@type":"ListItem","position":2,"name":"XQ Video-Podcast. El impacto de las redes sociales: De la radicalizaci\u00f3n pol\u00edtica a la salud mental"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/f3be5e6d9c8154bf65749ee40ff13d40","name":"Redacci\u00f3n","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/166fa34ade28f01051b021552fbb62c0491752a7b2fb97fc79a7952cb140f2e2?s=96&d=mm&r=gd91ac5233e8cbeeaec8eb828daaa977e","url":"https:\/\/secure.gravatar.com\/avatar\/166fa34ade28f01051b021552fbb62c0491752a7b2fb97fc79a7952cb140f2e2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/166fa34ade28f01051b021552fbb62c0491752a7b2fb97fc79a7952cb140f2e2?s=96&d=mm&r=g","caption":"Redacci\u00f3n"},"url":"https:\/\/xqthenews.com\/es\/author\/redaccion\/"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/posts\/23626","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/users\/15"}],"replies":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/comments?post=23626"}],"version-history":[{"count":0,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/posts\/23626\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/media\/23759"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/media?parent=23626"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/categories?post=23626"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/tags?post=23626"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/coauthors?post=23626"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}