{"id":20362,"date":"2024-04-10T08:01:02","date_gmt":"2024-04-10T07:01:02","guid":{"rendered":"https:\/\/sad-borg.82-223-8-23.plesk.page\/?p=20362"},"modified":"2024-09-10T22:59:30","modified_gmt":"2024-09-10T21:59:30","slug":"discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social","status":"publish","type":"post","link":"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/","title":{"rendered":"Discapacidad: mejorar la inclusi\u00f3n y la integraci\u00f3n es un imperativo social"},"content":{"rendered":"<p>Para comprender bien la situaci&oacute;n de la que vamos a hablar, conviene aclarar dos conceptos clave del debate sobre la discapacidad, que son complementarios entre s&iacute;: el de integraci&oacute;n y el de inclusi&oacute;n.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Integraci&oacute;n e inclusividad: conceptos diferentes y complementarios &nbsp; &nbsp; &nbsp; <\/strong><\/h2>\n\n\n\n<p><a href=\"https:\/\/univmurcia-my.sharepoint.com\/personal\/pedro_gg_um_es\/Documents\/1.2024\/2.Octaedro_Periodismo\/2024\/Abril\/Secondo%20il%20pi%C3%B9%20autorevole%20dizionario%20della%20lingua%20italiana:\">Seg&uacute;n el diccionario m&aacute;s autorizado de la lengua italiana<\/a>: &laquo;A diferencia de la integraci&oacute;n, cuyo eje principal es el individuo como segmento de una totalidad org&aacute;nica claramente delimitada, la inclusividad postula la construcci&oacute;n de contextos sensibles a la diversidad, dentro de los cuales la acci&oacute;n social garantiza la igualdad de dignidad, poder y representaci&oacute;n para cada sujeto, en el pleno respeto de las orientaciones, capacidades y aptitudes individuales&raquo;.&nbsp;<\/p>\n\n\n\n<p>As&iacute;, <strong>la integraci&oacute;n<\/strong> implica reunir f&iacute;sicamente a las personas y se realiza en el conjunto de la sociedad, pero no siempre otorga las mismas posibilidades de ser y actuar.<\/p>\n\n\n\n<p>En cambio, <strong>la inclusi&oacute;n<\/strong> est&aacute; representada por un conjunto de acciones que permiten a todos, sin distinci&oacute;n de ning&uacute;n tipo, ser <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Ciudadanos&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Un concepto que implica cuestiones relacionadas con los derechos y los deberes, as&iacute; como con las ideas de igualdad, diversidad y justicia social. No s&oacute;lo referido al acto de votar, el concepto de ciudadan&iacute;a incluye todo un conjunto de acciones practicadas por cada persona, con impacto en la vida de la comunidad (local, nacional, regional e internacional), inseparable del espacio p&uacute;blico en el que las personas pueden actuar juntas.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;(Fuente: CIG &ndash; Comiss&atilde;o para a Cidadania e Igualde de G&eacute;nero)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mensaje-en-una-botella-o-los-plasticos-que-nunca-desaparecen\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mensaje en una botella, o los pl&aacute;sticos que nunca desaparecen&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/apartheid-en-palestina-las-raices-profundas-de-la-guerra\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Apartheid en Palestina, las ra&iacute;ces profundas de la guerra&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/luchar-contra-el-cambio-climatico-tambien-es-combatir-la-desinformacion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Luchar contra el cambio clim&aacute;tico tambi&eacute;n es combatir la desinformaci&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/ciudadania\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">ciudadanos<\/a> activos. No basta con integrar la diversidad sino, partiendo de la riqueza de las diferencias, darles la posibilidad de hacer y de existir.<\/p>\n\n\n\n<p>Para<a href=\"https:\/\/www.osservatoriodisabilita.gov.it\/media\/1347\/convention-on-the-rights-of-persons-with-disabilities-and-optional-protocol.pdf\"> lograr la plena inclusi&oacute;n, siguiendo lo indicado por la Convenci&oacute;n de la ONU sobre los Derechos de las Personas con Discapacidad<\/a>, debemos actuar en <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;sinergia&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Resultado obtenido por la combinaci&oacute;n positiva de varios componentes que conduce a una mejora global o a un resultado superior al que podr&iacute;a obtenerse considerando cada elemento por separado.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Discapacidad: mejorar la inclusi&oacute;n y la integraci&oacute;n es un imperativo social&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/capital-verde-europea-y-green-leaf-abiertas-las-candidaturas\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Capital Verde Europea y &laquo;Green Leaf&raquo;: abiertas las candidaturas&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/justicia-climatica-global-el-papel-de-los-jovenes-en-la-lucha-por-mas-financiacion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Justicia clim&aacute;tica global: el papel de los j&oacute;venes en la lucha por m&aacute;s financiaci&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/sinergia\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">sinergia<\/a> y la plena inclusi&oacute;n debe perseguirse con la intenci&oacute;n de situar la fragilidad en el centro de toda decisi&oacute;n presente y futura. Al hacerlo, nos convertiremos en una sociedad mejor y m&aacute;s justa con los m&aacute;s d&eacute;biles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Barreras sanitarias en Italia: la encuesta en hospitales y escuelas<\/strong><\/h2>\n\n\n\n<p>La accesibilidad a hospitales y escuelas es un derecho fundamental que deber&iacute;a garantizarse a todos, independientemente de sus capacidades f&iacute;sicas o cognitivas. Sin embargo, una mirada atenta a la realidad italiana revela un panorama preocupante: <strong>muchas instalaciones hospitalarias y escolares del pa&iacute;s no est&aacute;n adecuadamente equipadas <\/strong>para acoger y apoyar a las personas con discapacidad.<\/p>\n\n\n\n<p><a href=\"https:\/\/spescontraspem.it\/indagine-conoscitiva-sui-percorsi-ospedalieri-delle-persone-con-disabilita\/\">Seg&uacute;n un estudio realizado en 2016 por la organizaci&oacute;n sin &aacute;nimo de lucro &laquo;Spes contro spem&raquo;<\/a>, en colaboraci&oacute;n con el Observatorio Nacional de la Salud en las Regiones Italianas de la Universidad Cat&oacute;lica de Roma, el 78% de las instalaciones hospitalarias italianas no ofrecen espacios de asistencia a las personas con discapacidad intelectual, motriz y sensorial.<\/p>\n\n\n\n<p>Y lo que es a&uacute;n m&aacute;s preocupante, s&oacute;lo el 29% de los ambulatorios y pabellones del norte de Italia y el 6,5% del sur ofrecen itinerarios sanitarios espec&iacute;ficos para personas con discapacidades cognitivas.<\/p>\n\n\n\n<p>Esta <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;brecha&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;diferencia entre dos o m&aacute;s cosas o situaciones. Por ejemplo, puede indicar una disparidad econ&oacute;mica entre grupos sociales, una diferencia de rendimiento entre dos partes o una discrepancia entre las expectativas y la realidad.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/metaverso-que-retos-sociales-nos-esperan\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Metaverso, qu&eacute; retos sociales nos esperan&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/cop-28-y-la-participacion-de-los-jovenes-en-el-desafio-climatico\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;COP 28 y la participaci&oacute;n de los j&oacute;venes en el desaf&iacute;o clim&agrave;tico&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Discapacidad: mejorar la inclusi&oacute;n y la integraci&oacute;n es un imperativo social&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/somos-lo-que-votamos\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Somos lo que votamos&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-lucha-por-un-equilibrio-verde-en-un-mundo-de-facturas\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La lucha por un equilibrio verde en un mundo de facturas&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/brecha\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">brecha<\/a> pone de manifiesto una importante disparidad entre regiones y subraya la urgente necesidad de intervenciones espec&iacute;ficas para garantizar una atenci&oacute;n igualitaria e inclusiva para todos los <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Ciudadanos&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Un concepto que implica cuestiones relacionadas con los derechos y los deberes, as&iacute; como con las ideas de igualdad, diversidad y justicia social. No s&oacute;lo referido al acto de votar, el concepto de ciudadan&iacute;a incluye todo un conjunto de acciones practicadas por cada persona, con impacto en la vida de la comunidad (local, nacional, regional e internacional), inseparable del espacio p&uacute;blico en el que las personas pueden actuar juntas.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;(Fuente: CIG &ndash; Comiss&atilde;o para a Cidadania e Igualde de G&eacute;nero)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mensaje-en-una-botella-o-los-plasticos-que-nunca-desaparecen\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mensaje en una botella, o los pl&aacute;sticos que nunca desaparecen&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/apartheid-en-palestina-las-raices-profundas-de-la-guerra\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Apartheid en Palestina, las ra&iacute;ces profundas de la guerra&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/luchar-contra-el-cambio-climatico-tambien-es-combatir-la-desinformacion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Luchar contra el cambio clim&aacute;tico tambi&eacute;n es combatir la desinformaci&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/ciudadania\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">ciudadanos<\/a>.&nbsp; &nbsp;<\/p>\n\n\n\n<p>Las consecuencias de esta falta de accesibilidad son graves: las personas con discapacidad se enfrentan a importantes obst&aacute;culos para acceder a los servicios sanitarios, con largos tiempos de espera en las salas de urgencias y dificultades para someterse a procedimientos diagn&oacute;sticos y terap&eacute;uticos. <strong>Esto no s&oacute;lo compromete su bienestar f&iacute;sico, sino que tambi&eacute;n contribuye a aumentar su aislamiento social y su angustia emocional<\/strong>.<\/p>\n\n\n\n<p>Adem&aacute;s, esta situaci&oacute;n pone de manifiesto una profunda disparidad entre el norte y el sur de Italia, donde las personas con discapacidad est&aacute;n especialmente desfavorecidas a la hora de acceder a los servicios sanitarios.<\/p>\n\n\n\n<p>La falta de sensibilidad y de recursos por parte de los hospitales italianos ante las necesidades de los pacientes discapacitados es un problema complejo que requiere una acci&oacute;n urgente y coordinada. Es crucial que las instituciones sanitarias adopten pol&iacute;ticas y pr&aacute;cticas inclusivas que tengan en cuenta las diversas necesidades de los pacientes y garanticen una atenci&oacute;n personalizada y digna. Esto podr&iacute;a incluir:<\/p>\n\n\n\n<p>&ndash; La puesta en marcha de v&iacute;as prioritarias de atenci&oacute;n sanitaria para las personas con discapacidad;<\/p>\n\n\n\n<p>&ndash; La formaci&oacute;n del personal hospitalario en cuidados sensibles a las necesidades espec&iacute;ficas de los pacientes;<\/p>\n\n\n\n<p>-La instalaci&oacute;n de equipos y tecnolog&iacute;a accesibles.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La situaci&oacute;n en la escuela&nbsp; &nbsp; &nbsp; <\/strong><strong><\/strong>&nbsp; &nbsp; &nbsp; &nbsp;<\/h2>\n\n\n\n<p>Del mismo modo, la accesibilidad de las escuelas italianas representa un reto importante que Italia no est&aacute; abordando.<a href=\"https:\/\/www.istat.it\/it\/files\/2024\/02\/Statistica-report-alunni-con-disabilit%C3%A0-as.-22-23.pdf\"> Seg&uacute;n una encuesta realizada por el Instituto Nacional de Estad&iacute;stica (ISTAT), en el curso escolar 2022\/2023<\/a>, <strong>el 42% de las escuelas no ser&aacute;n accesibles para los alumnos con discapacidades motrices y sensoriales<\/strong>: faltan mapas t&aacute;ctiles e itinerarios adecuados para ciegos y deficientes visuales, mientras que la presencia de ayudas tecnol&oacute;gicas var&iacute;a mucho de una regi&oacute;n a otra.<\/p>\n\n\n\n<p>La encuesta aborda numerosas variables relativas tanto a la integraci&oacute;n como a la inclusi&oacute;n. Aunque <strong>ha aumentado el n&uacute;mero de alumnos discapacitados<\/strong> &ndash; 338.000 alumnos discapacitados que asisten a escuelas de todos los niveles, un 4,1% del total de alumnos matriculados, un +7% en comparaci&oacute;n con el curso anterior &ndash; <strong>en el 50% de las escuelas no hay ascensor<\/strong>, o lo hay pero no cumple las normas; tambi&eacute;n se se&ntilde;alan porcentajes elevados de aseos inadecuados (26%); las excursiones educativas que implican pernoctaci&oacute;n son muy poco frecuentes (32%).<\/p>\n\n\n\n<p>La oferta de profesores de apoyo est&aacute; mejorando (+10%). La proporci&oacute;n alumno-profesor, de 1,6, es mejor que la exigida por la ley, pero entre los profesores 1 de cada 3 no tiene formaci&oacute;n espec&iacute;fica y al 12% se les asigna tarde.<\/p>\n\n\n\n<p>La discontinuidad en la ense&ntilde;anza sigue siendo fuerte: el 60% de los alumnos discapacitados cambian de profesor de apoyo de un a&ntilde;o para otro, el 9% durante el mismo curso escolar. Esto crea obst&aacute;culos importantes para la educaci&oacute;n y la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Inclusi&oacute;n social&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Proceso cuyo objetivo es garantizar que todas las personas -independientemente de su edad, sexo, discapacidad, raza, etnia, origen, religi&oacute;n o situaci&oacute;n econ&oacute;mica o de otro tipo- tengan las mismas oportunidades de participar en todos los aspectos de la vida social, econ&oacute;mica y pol&iacute;tica. Este t&eacute;rmino subraya la importancia de crear una sociedad en la que todos los j&oacute;venes, independientemente de su origen, situaci&oacute;n socioecon&oacute;mica o identidad, tengan las mismas oportunidades y sean acogidos y valorados.&nbsp;&nbsp;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-estrategia-de-la-ue-para-la-juventud-participacion-de-los-jovenes-en-la-vida-democratica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La Estrategia de la UE para la Juventud: participaci&oacute;n de los j&oacute;venes en la vida democr&aacute;tica&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/inclusion-social\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">inclusi&oacute;n social<\/a> de los alumnos discapacitados y subraya la necesidad de redoblar los esfuerzos para garantizar la igualdad de acceso a la educaci&oacute;n para todos. &nbsp;<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Discapacidad e inclusi&oacute;n: Italia bajo el prisma de la OCDE<\/strong><\/h2>\n\n\n\n<p>En los &uacute;ltimos tiempos, los viejos retos a los que se enfrenta Italia han sido objeto de <strong>una investigaci&oacute;n sobre el estado de la reforma de la pol&iacute;tica en materia de discapacidad<\/strong>. Tal y como revela el informe de la Organizaci&oacute;n para la Cooperaci&oacute;n y el Desarrollo Econ&oacute;mico (<a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;OCDE&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La OCDE (Organizaci&oacute;n para la Cooperaci&oacute;n y el Desarrollo Econ&oacute;micos) es un organismo internacional que promueve pol&iacute;ticas para mejorar el bienestar econ&oacute;mico, social y ambiental en 38 pa&iacute;ses miembros.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/quiet-ambition-la-respuesta-de-los-jovenes-a-un-mercado-laboral-precario\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Quiet ambition: la respuesta de los j&oacute;venes a un mercado laboral precario&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\"  href=\"https:\/\/xqthenews.com\/es\/glossary\/ocde\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>OCDE<\/a>) titulado &laquo;<a href=\"https:\/\/www.oecd-ilibrary.org\/docserver\/66abbfe6-it.pdf?expires=1710260579&amp;id=id&amp;accname=guest&amp;checksum=8F17A9F0EAE94D954A14382EA5870F38\">Discapacidad, trabajo e inclusi&oacute;n en Italia: mejor evaluaci&oacute;n para una mejor atenci&oacute;n<\/a>&laquo;, existen tres problemas principales:<\/p>\n\n\n\n<p>&ndash; Las incoherencias con la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Convenci&oacute;n&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Evento o reuni&oacute;n organizada en la que personas con intereses comunes, como los c&oacute;mics, los videojuegos o la cultura pop, se re&uacute;nen para participar en actividades, conferencias y presentaciones.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/los-nuevos-senores-feudales-tecnologia-poder-y-politica-en-la-era-trump\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Los nuevos se&ntilde;ores feudales: tecnolog&iacute;a, poder y pol&iacute;tica en la era Trump&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/tdah-en-la-adolescencia-reconocer-y-afrontar-un-trastorno-complejo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;TDAH en la adolescencia: reconocer y afrontar un trastorno complejo&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/convencion\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">Convenci&oacute;n<\/a> de las Naciones Unidas sobre los Derechos de las Personas con Discapacidad.<\/p>\n\n\n\n<p>&ndash; La fragmentaci&oacute;n de la evaluaci&oacute;n y el apoyo a la discapacidad.<\/p>\n\n\n\n<p>&ndash; Las disparidades resultantes entre las regiones italianas en la prestaci&oacute;n de servicios y el uso de las prestaciones por discapacidad. &nbsp; &nbsp; &nbsp; &nbsp;<br>&nbsp;<strong>Los indicadores sociales y de empleo<\/strong> para las personas con discapacidad en Italia, por tanto, son ambivalentes y complejos de interpretar: aunque las brechas de empleo y pobreza entre las personas con y sin discapacidad son relativamente bajas e inferiores a la media de la <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;OCDE&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La OCDE (Organizaci&oacute;n para la Cooperaci&oacute;n y el Desarrollo Econ&oacute;micos) es un organismo internacional que promueve pol&iacute;ticas para mejorar el bienestar econ&oacute;mico, social y ambiental en 38 pa&iacute;ses miembros.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/quiet-ambition-la-respuesta-de-los-jovenes-a-un-mercado-laboral-precario\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Quiet ambition: la respuesta de los j&oacute;venes a un mercado laboral precario&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\"  href=\"https:\/\/xqthenews.com\/es\/glossary\/ocde\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>OCDE<\/a>, esto no se debe a unas tasas de empleo m&aacute;s altas o de pobreza m&aacute;s bajas entre las personas con discapacidad. M&aacute;s bien, estas brechas m&aacute;s bajas se deben a los bajos niveles de ingresos y empleo tambi&eacute;n para las personas sin discapacidad, lo que subraya la necesidad de nuevas reformas para mejorar los resultados sociales y laborales de todas las personas en Italia, incluidas las personas con discapacidad. &nbsp;<\/p>\n\n\n\n<p>Adem&aacute;s, aunque existen prestaciones y servicios para discapacitados, su utilizaci&oacute;n sigue siendo baja debido a la complejidad del sistema y a la falta de recursos. Muchas personas excluidas de las ayudas son especialmente vulnerables y se enfrentan a importantes obst&aacute;culos para acceder al empleo y a la integraci&oacute;n social.<\/p>\n\n\n\n<p>Tambi&eacute;n hay confusi&oacute;n y desigualdad causadas por las diferencias en la valoraci&oacute;n de la discapacidad, tanto entre las regiones como dentro de ellas. En la actualidad, <strong>la legislaci&oacute;n italiana prev&eacute; cinco evaluaciones diferentes del estado de discapacidad en paralelo<\/strong>, lo que hace que el sistema sea ineficaz y dif&iacute;cil de entender.<\/p>\n\n\n\n<p>La evaluaci&oacute;n de las necesidades, que determina el acceso a los servicios, <strong>var&iacute;a mucho entre las distintas zonas del pa&iacute;s, centr&aacute;ndose mucho en las necesidades reales de las personas discapacitadas<\/strong>. Sin embargo, las dos evaluaciones principales -la del grado de invalidez civil y la de las necesidades- est&aacute;n desconectadas entre s&iacute;.<\/p>\n\n\n\n<p>La reciente ley de habilitaci&oacute;n indica la necesidad de una reforma de la evaluaci&oacute;n de la discapacidad, con la integraci&oacute;n del<a href=\"https:\/\/www.who.int\/standards\/classifications\/international-classification-of-functioning-disability-and-health\/who-disability-assessment-schedule\"> Formulario de Evaluaci&oacute;n de la Discapacidad de la OMS (WHODAS)<\/a> para garantizar una evaluaci&oacute;n m&aacute;s precisa y multidimensional.<\/p>\n\n\n\n<p>Para que las pol&iacute;ticas en materia de discapacidad sean m&aacute;s eficientes y eficaces, el gobierno deber&iacute;a considerar varias acciones, como unificar las evaluaciones del estado de discapacidad, utilizar las puntuaciones del WHODAS para se&ntilde;alar las discrepancias entre las dimensiones m&eacute;dica y funcional de la discapacidad, reducir la discrecionalidad en la evaluaci&oacute;n de la discapacidad y reforzar los puntos &uacute;nicos de acceso para ayudar a las personas con discapacidad a navegar por el sistema.&nbsp;<\/p>\n\n\n\n<p>Adem&aacute;s, es esencial reducir las disparidades territoriales mejorando la capacidad de prestar servicios eficaces en las regiones del sur y dando prioridad a la integraci&oacute;n de las personas con discapacidad en el mercado laboral.&nbsp;&nbsp;<\/p>\n\n\n\n<p><strong>En conclusi&oacute;n<\/strong>, mejorar la accesibilidad y la inclusi&oacute;n no es s&oacute;lo un imperativo social, sino tambi&eacute;n una oportunidad para construir una sociedad m&aacute;s justa, <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Equitativa&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Equitativo significa justo, imparcial y tratando a todos por igual, considerando sus necesidades y circunstancias individuales para asegurar la igualdad de oportunidades.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/juventud-activismo-digital-y-la-era-de-la-conectividad\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Juventud, activismo digital y la era de la conectividad&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Discapacidad: mejorar la inclusi&oacute;n y la integraci&oacute;n es un imperativo social&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/cambio-climatico-y-genero-desigualdades-y-urgencia-de-politicas-inclusivas\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Cambio clim&aacute;tico y g&eacute;nero: desigualdades y urgencia de pol&iacute;ticas inclusivas&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-lucha-contra-el-racismo-medioambiental-y-la-busqueda-de-la-justicia-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La lucha contra el racismo medioambiental y la b&uacute;squeda de la justicia clim&aacute;tica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/justicia-climatica-global-el-papel-de-los-jovenes-en-la-lucha-por-mas-financiacion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Justicia clim&aacute;tica global: el papel de los j&oacute;venes en la lucha por m&aacute;s financiaci&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/equitativa\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">equitativa<\/a> e integradora para todos sus <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Ciudadanos&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Un concepto que implica cuestiones relacionadas con los derechos y los deberes, as&iacute; como con las ideas de igualdad, diversidad y justicia social. No s&oacute;lo referido al acto de votar, el concepto de ciudadan&iacute;a incluye todo un conjunto de acciones practicadas por cada persona, con impacto en la vida de la comunidad (local, nacional, regional e internacional), inseparable del espacio p&uacute;blico en el que las personas pueden actuar juntas.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;(Fuente: CIG &ndash; Comiss&atilde;o para a Cidadania e Igualde de G&eacute;nero)&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mensaje-en-una-botella-o-los-plasticos-que-nunca-desaparecen\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mensaje en una botella, o los pl&aacute;sticos que nunca desaparecen&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/apartheid-en-palestina-las-raices-profundas-de-la-guerra\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Apartheid en Palestina, las ra&iacute;ces profundas de la guerra&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/luchar-contra-el-cambio-climatico-tambien-es-combatir-la-desinformacion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Luchar contra el cambio clim&aacute;tico tambi&eacute;n es combatir la desinformaci&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/ciudadania\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">ciudadanos<\/a>. Es hora de que Italia se comprometa seriamente a superar las barreras materiales y culturales que a&uacute;n persisten y a crear un futuro en el que cada individuo tenga la oportunidad de desarrollar todo su potencial, independientemente de sus capacidades f&iacute;sicas o cognitivas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Todav&iacute;a se habla demasiado poco de los derechos de las personas discapacitadas, sobre todo en los pa&iacute;ses del sur de Europa. Italia est&aacute; tan lejos del objetivo de una verdadera inclusi&oacute;n que la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;OCDE&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La OCDE (Organizaci&oacute;n para la Cooperaci&oacute;n y el Desarrollo Econ&oacute;micos) es un organismo internacional que promueve pol&iacute;ticas para mejorar el bienestar econ&oacute;mico, social y ambiental en 38 pa&iacute;ses miembros.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/quiet-ambition-la-respuesta-de-los-jovenes-a-un-mercado-laboral-precario\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Quiet ambition: la respuesta de los j&oacute;venes a un mercado laboral precario&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/ocde\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">OCDE<\/a> la ha reprendido severamente. Falta de infraestructuras sanitarias, educativas y de acceso al trabajo<\/p>\n","protected":false},"author":55,"featured_media":20526,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[343,229],"tags":[87],"coauthors":[217],"class_list":{"0":"post-20362","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-derechos-humanos","8":"category-igualdad","9":"tag-igualdad"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Discapacidad: mejorar la inclusi\u00f3n y la integraci\u00f3n es un imperativo social - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Discapacidad: mejorar la inclusi\u00f3n y la integraci\u00f3n es un imperativo social - xqthenews\" \/>\n<meta property=\"og:description\" content=\"Todav&iacute;a se habla demasiado poco de los derechos de las personas discapacitadas, sobre todo en los pa&iacute;ses del sur de Europa. Italia est&aacute; tan lejos del objetivo de una verdadera inclusi&oacute;n que la OCDE la ha reprendido severamente. Falta de infraestructuras sanitarias, educativas y de acceso al trabajo\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:published_time\" content=\"2024-04-10T07:01:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-10T21:59:30+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/04\/imagen-portada-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"478\" \/>\n\t<meta property=\"og:image:height\" content=\"318\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Valentina Isernia\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Valentina Isernia\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Valentina Isernia\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\\\/\"},\"author\":{\"name\":\"Valentina Isernia\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/a4acc80e0ac8a376ae6d9e223a081d5d\"},\"headline\":\"Discapacidad: mejorar la inclusi\u00f3n y la integraci\u00f3n es un imperativo social\",\"datePublished\":\"2024-04-10T07:01:02+00:00\",\"dateModified\":\"2024-09-10T21:59:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\\\/\"},\"wordCount\":1661,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/imagen-portada-1.jpg\",\"keywords\":[\"Igualdad\"],\"articleSection\":[\"Derechos humanos\",\"Igualdad\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/es\\\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\\\/\",\"name\":\"Discapacidad: mejorar la inclusi\u00f3n y la integraci\u00f3n es un imperativo social - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/imagen-portada-1.jpg\",\"datePublished\":\"2024-04-10T07:01:02+00:00\",\"dateModified\":\"2024-09-10T21:59:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/a4acc80e0ac8a376ae6d9e223a081d5d\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/es\\\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/imagen-portada-1.jpg\",\"contentUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/04\\\/imagen-portada-1.jpg\",\"width\":478,\"height\":318},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Discapacidad: mejorar la inclusi\u00f3n y la integraci\u00f3n es un imperativo social\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/a4acc80e0ac8a376ae6d9e223a081d5d\",\"name\":\"Valentina Isernia\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/valentina-isernia_avatar_1-96x96.jpg0b33b4124730ea5ac8a5dcb54c77abac\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/valentina-isernia_avatar_1-96x96.jpg\",\"contentUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/valentina-isernia_avatar_1-96x96.jpg\",\"caption\":\"Valentina Isernia\"},\"description\":\"Valentina Isernia es periodista, gestora de redes sociales y analista de contenidos de radio y televisi\u00f3n. Tras una larga experiencia en la redacci\u00f3n de \\\"Il Tacco d'Italia\\\", se gradu\u00f3 con las m\u00e1ximas calificaciones en la Universidad \\\"La Sapienza\\\" de Roma en el M\u00e1ster de Industria Cultural y Comunicaci\u00f3n Digital con una tesis sobre fantas\u00eda. En 2020 fund\u00f3 la revista semestral Fantasy Era, publicada por IdeaDinamica Scarl.\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/author\\\/valetinaisernia\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Discapacidad: mejorar la inclusi\u00f3n y la integraci\u00f3n es un imperativo social - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/","og_locale":"es_ES","og_type":"article","og_title":"Discapacidad: mejorar la inclusi\u00f3n y la integraci\u00f3n es un imperativo social - xqthenews","og_description":"Todav&iacute;a se habla demasiado poco de los derechos de las personas discapacitadas, sobre todo en los pa&iacute;ses del sur de Europa. Italia est&aacute; tan lejos del objetivo de una verdadera inclusi&oacute;n que la OCDE la ha reprendido severamente. Falta de infraestructuras sanitarias, educativas y de acceso al trabajo","og_url":"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/","og_site_name":"xqthenews","article_published_time":"2024-04-10T07:01:02+00:00","article_modified_time":"2024-09-10T21:59:30+00:00","og_image":[{"width":478,"height":318,"url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/04\/imagen-portada-1.jpg","type":"image\/jpeg"}],"author":"Valentina Isernia","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Valentina Isernia","Tiempo de lectura":"8 minutos","Written by":"Valentina Isernia"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/#article","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/"},"author":{"name":"Valentina Isernia","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/a4acc80e0ac8a376ae6d9e223a081d5d"},"headline":"Discapacidad: mejorar la inclusi\u00f3n y la integraci\u00f3n es un imperativo social","datePublished":"2024-04-10T07:01:02+00:00","dateModified":"2024-09-10T21:59:30+00:00","mainEntityOfPage":{"@id":"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/"},"wordCount":1661,"commentCount":0,"image":{"@id":"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/04\/imagen-portada-1.jpg","keywords":["Igualdad"],"articleSection":["Derechos humanos","Igualdad"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/","url":"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/","name":"Discapacidad: mejorar la inclusi\u00f3n y la integraci\u00f3n es un imperativo social - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/#primaryimage"},"image":{"@id":"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/04\/imagen-portada-1.jpg","datePublished":"2024-04-10T07:01:02+00:00","dateModified":"2024-09-10T21:59:30+00:00","author":{"@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/a4acc80e0ac8a376ae6d9e223a081d5d"},"breadcrumb":{"@id":"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/#primaryimage","url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/04\/imagen-portada-1.jpg","contentUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/04\/imagen-portada-1.jpg","width":478,"height":318},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/es\/discapacidad-mejorar-la-inclusion-y-la-integracion-es-un-imperativo-social\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/es\/"},{"@type":"ListItem","position":2,"name":"Discapacidad: mejorar la inclusi\u00f3n y la integraci\u00f3n es un imperativo social"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/a4acc80e0ac8a376ae6d9e223a081d5d","name":"Valentina Isernia","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/valentina-isernia_avatar_1-96x96.jpg0b33b4124730ea5ac8a5dcb54c77abac","url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/valentina-isernia_avatar_1-96x96.jpg","contentUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/09\/valentina-isernia_avatar_1-96x96.jpg","caption":"Valentina Isernia"},"description":"Valentina Isernia es periodista, gestora de redes sociales y analista de contenidos de radio y televisi\u00f3n. Tras una larga experiencia en la redacci\u00f3n de \"Il Tacco d'Italia\", se gradu\u00f3 con las m\u00e1ximas calificaciones en la Universidad \"La Sapienza\" de Roma en el M\u00e1ster de Industria Cultural y Comunicaci\u00f3n Digital con una tesis sobre fantas\u00eda. En 2020 fund\u00f3 la revista semestral Fantasy Era, publicada por IdeaDinamica Scarl.","url":"https:\/\/xqthenews.com\/es\/author\/valetinaisernia\/"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/posts\/20362","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/users\/55"}],"replies":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/comments?post=20362"}],"version-history":[{"count":0,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/posts\/20362\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/media\/20526"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/media?parent=20362"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/categories?post=20362"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/tags?post=20362"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/coauthors?post=20362"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}