{"id":19010,"date":"2024-02-28T08:10:18","date_gmt":"2024-02-28T07:10:18","guid":{"rendered":"https:\/\/sad-borg.82-223-8-23.plesk.page\/?p=19010"},"modified":"2024-09-10T23:00:18","modified_gmt":"2024-09-10T22:00:18","slug":"los-dibujos-de-la-guerra-de-ucrania","status":"publish","type":"post","link":"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/","title":{"rendered":"Los dibujos de la guerra de Ucrania"},"content":{"rendered":"<p>El refr&aacute;n &ldquo;una imagen vale m&aacute;s que mil palabras&rdquo; puede aplicarse tambi&eacute;n a los dibujos de los m&aacute;s peque&ntilde;os. Un dibujo puede evocar m&aacute;s de mil palabras y emociones. Las im&aacute;genes hablan y los dibujos tambi&eacute;n lo hacen. En un mundo en el que muchas veces los mayores hablan en nombre de los m&aacute;s peque&ntilde;os, o en el que &eacute;stos todav&iacute;a no tienen suficientes herramientas para expresar la complejidad de sus emociones, existen t&eacute;cnicas que ayudan a descifrar los sentimientos. N&uacute;ria Casanovas, psic&oacute;loga especializada en infancia y familia, dedica su carrera a analizar e interpretar los dibujos de los ni&ntilde;os. De hecho, tambi&eacute;n ha escrito <a href=\"https:\/\/www.casadellibro.com\/libro-guia-practica-para-la-interpretacion-de-dibujos-analisis-e-inter-pretacion-de-dibujos-libres\/9788492785285\/2219984\">un libro<\/a> que funciona como peque&ntilde;a gu&iacute;a de iniciaci&oacute;n a esta rama de la psicolog&iacute;a.<\/p>\n\n\n\n<p>Habitualmente, los m&aacute;s peque&ntilde;os cargan tambi&eacute;n con las consecuencias de los actos de los adultos, y muchas veces no somos conscientes de c&oacute;mo pueden afectarles. En Ucrania, la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a> se inici&oacute; hace ya casi dos a&ntilde;os. Un conflicto armado que, de momento y seg&uacute;n cifras de la Organizaci&oacute;n de las Naciones Unidas (<a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;ONU&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La ONU (Organizaci&oacute;n de las Naciones Unidas) es una entidad internacional fundada en 1945 para promover la cooperaci&oacute;n global y la paz, compuesta por 193 estados miembros&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mensaje-en-una-botella-o-los-plasticos-que-nunca-desaparecen\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mensaje en una botella, o los pl&aacute;sticos que nunca desaparecen&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/apartheid-en-palestina-las-raices-profundas-de-la-guerra\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Apartheid en Palestina, las ra&iacute;ces profundas de la guerra&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-destruccion-de-gaza-el-ultimo-capitulo-de-cien-anos-de-odio\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La destrucci&oacute;n de Gaza, el &uacute;ltimo cap&iacute;tulo de cien a&ntilde;os de odio&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/israel-una-potencia-militarista-y-probada-en-combate\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Israel, una potencia militarista y &amp;quot;probada en combate&rdquo;&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-oms-denuncia-mas-de-230-ataques-israelies-a-la-atencion-sanitaria-palestina\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La OMS denuncia m&aacute;s de 230 ataques israel&iacute;es a la atenci&oacute;n sanitaria palestina&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\"  href=\"https:\/\/xqthenews.com\/es\/glossary\/onu\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>ONU<\/a>), se ha cobrado miles de vidas (hay 24.900 v&iacute;ctimas civiles registradas), ha causado una destrucci&oacute;n incalculable y ha dejado casi 18 millones de personas en situaci&oacute;n de necesitar <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Ayuda humanitaria&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La &amp;quot;Ayuda humanitaria&amp;quot; es asistencia proporcionada a personas afectadas por crisis o desastres, con el objetivo de aliviar su sufrimiento y mejorar las condiciones de vida.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-oms-denuncia-mas-de-230-ataques-israelies-a-la-atencion-sanitaria-palestina\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La OMS denuncia m&aacute;s de 230 ataques israel&iacute;es a la atenci&oacute;n sanitaria palestina&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/onu-organizacion-de-las-naciones-unidas\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  ONU &amp;#8211; Organizaci&oacute;n de las Naciones Unidas&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/ayuda-humanitaria-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Ayuda humanitaria&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Los dibujos de la guerra de Ucrania&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ante-lo-inesperado-cronica-de-la-segunda-jornada-del-foro-de-mujeres-periodistas-del-mediterraneo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ante lo inesperado: cr&oacute;nica de la segunda jornada del Foro de Mujeres Periodistas del Mediterr&aacute;neo.&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/ayuda-humanitaria\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">ayuda humanitaria<\/a>.<\/p>\n\n\n\n<p>Si estas cifras no fueran suficientemente abrumadoras podr&iacute;amos a&ntilde;adir que, en la actualidad, hay 1.060 ataques verificados contra estructuras sanitarias, que el 30% de los puestos de trabajo anteriores a la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a> han sido suprimidos y que casi 10 millones de personas, incluidos 7,8 millones de ni&ntilde;os, corren el riesgo de sufrir un trastorno de estr&eacute;s post-traum&aacute;tico agudo.<\/p>\n\n\n\n<p>Hemos tenido acceso a los dibujos de ni&ntilde;os de distintas edades, residentes en Kiev, de antes y durante la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a>. Sus historias son distintas, pero comparten un rasgo com&uacute;n: est&aacute;n viviendo su ni&ntilde;ez en <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a>. En Kiev, las alarmas antia&eacute;reas suenan a diario y forman parte de la banda sonora del d&iacute;a a d&iacute;a. Cuando saltan las alarmas se evacuan los centros comerciales de grandes superficies y los edificios administrativos, y los maestros llevan &mdash;obligatoriamente, en cumplimiento de la normativa&mdash; a los ni&ntilde;os a los refugios del s&oacute;tano de las escuelas, para resguardarse. All&iacute; siguen con las clases hasta que suena la alarma de cierre, que indica el fin del peligro.<\/p>\n\n\n\n<p>Estos ni&ntilde;os, que no han abandonado Kiev en ning&uacute;n momento, han vivido la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a> desde su inicio. Durante los primeros meses del conflicto no asist&iacute;an a clase, porque las escuelas funcionaban como refugios para desplazados internos de las zonas m&aacute;s afectadas. Han vivido ataques a&eacute;reos, bombardeos masivos y las consecuencias de la destrucci&oacute;n de instalaciones el&eacute;ctricas, que les dejaron sin luz, sin agua y sin calefacci&oacute;n.<\/p>\n\n\n\n<p>Seg&uacute;n N&uacute;ria Casanovas, la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a> puede afectar a los ni&ntilde;os a todos los niveles: emocional, neurol&oacute;gico o de relaci&oacute;n con los dem&aacute;s, porque los lleva a vivir situaciones en las que pierden la sensaci&oacute;n de protecci&oacute;n y confianza, hecho que tambi&eacute;n puede influir en su aprendizaje.<\/p>\n\n\n\n<p>&ldquo;El cuerpo, a veces, prioriza la supervivencia, y por eso debe dedicar mucha energ&iacute;a a digerir y a gestionar el estr&eacute;s vivido&rdquo;, argumenta la psic&oacute;loga. &ldquo;Esto interfiere en los procesos de aprendizaje y en las capacidades cognitivas; las situaciones traum&aacute;ticas incluso pueden crear disociaci&oacute;n&rdquo;.<\/p>\n\n\n\n<p>Pero, como todo, la situaci&oacute;n de <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a> puede afectar de forma diferente a cada ni&ntilde;o, ya que son muchas las variables que hay que tener en cuenta, como el apoyo familiar, las capacidades en el &aacute;mbito de la inteligencia, los recursos emocionales o la historia precedente, alerta la psic&oacute;loga. &ldquo;Sin embargo, lo que s&iacute; se observa a veces es que, a corto plazo, los ni&ntilde;os peque&ntilde;os parecen sufrir menos la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a> porque son m&aacute;s resilientes y en muchos casos siguen haciendo vida normal&rdquo;. &ldquo;Las consecuencias de estas situaciones traum&aacute;ticas vividas en la primera infancia pueden convertirse en un factor de dificultad emocional a largo plazo, si no se trabaja posteriormente&rdquo;. Es importante que los ni&ntilde;os est&eacute;n acompa&ntilde;ados de profesionales para que, en un futuro, no sufran estas consecuencias. En este sentido, es necesario trabajar estos duelos, igual que la sensaci&oacute;n de seguridad o de protecci&oacute;n. En otros casos, tambi&eacute;n es necesario trabajar los traumas creados por la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a>, y &eacute;stos s&iacute; requieren profesionales especializados. No debe ser un tratamiento inmediato, porque hay ni&ntilde;os que tienen una capacidad de <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Resiliencia&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La resiliencia es la capacidad de recuperarse frente a la adversidad, adaptarse a situaciones dif&iacute;ciles y salir fortalecido de ellas.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/luchar-contra-el-cambio-climatico-tambien-es-combatir-la-desinformacion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Luchar contra el cambio clim&aacute;tico tambi&eacute;n es combatir la desinformaci&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/movimientos-juveniles-en-europa-en-busca-de-respuestas-a-la-crisis-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Movimientos juveniles en Europa en busca de respuestas a la crisis clim&aacute;tica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/cop-28-y-la-participacion-de-los-jovenes-en-el-desafio-climatico\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;COP 28 y la participaci&oacute;n de los j&oacute;venes en el desaf&iacute;o clim&agrave;tico&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Los dibujos de la guerra de Ucrania&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mitigar-y-adaptarse-un-analisis-de-el-balance-mundial\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mitigar y adaptarse. Un an&aacute;lisis de El Balance Mundial&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/resiliencia\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">resiliencia<\/a> muy fuerte e incluso, con el apoyo del padre, de la madre o de la escuela, logran salir adelante.<\/p>\n\n\n\n<p>Tal y como explica Casanovas, a pesar de que algunos ni&ntilde;os son muy resilientes, los adultos pueden transmitirles&nbsp; la sensaci&oacute;n de estr&eacute;s. &ldquo;Aunque no est&eacute;n en la zona caliente de la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a> ni vean directamente una bomba, s&iacute; sienten ese estr&eacute;s de su entorno, que les hace experimentar una sensaci&oacute;n de sufrimiento&rdquo;. &ldquo;El ni&ntilde;o lo vive de forma indirecta&rdquo;.<\/p>\n\n\n\n<p>Para poder ayudar a los ni&ntilde;os a canalizar una situaci&oacute;n como la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a>, N&uacute;ria Casanovas explica que lo primero es detectar c&oacute;mo les est&aacute; afectando. A&ntilde;ade que, en edades en las que todav&iacute;a no saben expresarse tan bien como quisieran, el an&aacute;lisis de los dibujos es una buena herramienta para conocer el estado de salud mental del ni&ntilde;o o la ni&ntilde;a.<\/p>\n\n\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"725\" height=\"1024\" src=\"https:\/\/sad-borg.82-223-8-23.plesk.page\/wp-content\/uploads\/2024\/02\/1.-%D0%92%D0%B0%D1%80%D1%8F-4-%D1%80%D0%BE%D0%BA%D0%B8-1-725x1024.jpg\" alt=\"\" class=\"wp-image-19050\" style=\"width:502px;height:auto\" srcset=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/1.-&#1042;&#1072;&#1088;&#1103;-4-&#1088;&#1086;&#1082;&#1080;-1-725x1024.jpg 725w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/1.-&#1042;&#1072;&#1088;&#1103;-4-&#1088;&#1086;&#1082;&#1080;-1-212x300.jpg 212w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/1.-&#1042;&#1072;&#1088;&#1103;-4-&#1088;&#1086;&#1082;&#1080;-1-768x1085.jpg 768w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/1.-&#1042;&#1072;&#1088;&#1103;-4-&#1088;&#1086;&#1082;&#1080;-1-1087x1536.jpg 1087w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/1.-&#1042;&#1072;&#1088;&#1103;-4-&#1088;&#1086;&#1082;&#1080;-1-1449x2048.jpg 1449w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/1.-&#1042;&#1072;&#1088;&#1103;-4-&#1088;&#1086;&#1082;&#1080;-1-1080x1526.jpg 1080w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/1.-&#1042;&#1072;&#1088;&#1103;-4-&#1088;&#1086;&#1082;&#1080;-1-1280x1808.jpg 1280w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/1.-&#1042;&#1072;&#1088;&#1103;-4-&#1088;&#1086;&#1082;&#1080;-1-980x1385.jpg 980w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/1.-&#1042;&#1072;&#1088;&#1103;-4-&#1088;&#1086;&#1082;&#1080;-1-480x678.jpg 480w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/1.-&#1042;&#1072;&#1088;&#1103;-4-&#1088;&#1086;&#1082;&#1080;-1-scaled.jpg 1812w\" sizes=\"(max-width: 725px) 100vw, 725px\"\/><figcaption class=\"wp-element-caption\">1. Varia, 4 a&ntilde;os<\/figcaption><\/figure>\n<\/div>\n\n\n<p>El primer dibujo es el de <strong>Varia<\/strong>, de 4 a&ntilde;os. Despu&eacute;s de analizarlo, N&uacute;ria concluye que el tipo de gotas que hace denotan que es un ni&ntilde;o muy sensible, muy emocional. La lluvia aparece en la esquina derecha, lo que significa que Varia se proyecta en el futuro; &ldquo;significa que la soluci&oacute;n para este ni&ntilde;o, cuando se sienta mal o se estrese, ser&aacute; pensar en qu&eacute; le ir&aacute; bien en el futuro, pues eso le ayudar&aacute; a sentirse mejor&rdquo;, argumenta la psic&oacute;loga. &ldquo;El otro dibujo, el de la casa, es positivo porque el sol est&aacute; dibujado a la izquierda, y esto normalmente nos habla de <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Resiliencia&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La resiliencia es la capacidad de recuperarse frente a la adversidad, adaptarse a situaciones dif&iacute;ciles y salir fortalecido de ellas.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/luchar-contra-el-cambio-climatico-tambien-es-combatir-la-desinformacion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Luchar contra el cambio clim&aacute;tico tambi&eacute;n es combatir la desinformaci&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/movimientos-juveniles-en-europa-en-busca-de-respuestas-a-la-crisis-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Movimientos juveniles en Europa en busca de respuestas a la crisis clim&aacute;tica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/cop-28-y-la-participacion-de-los-jovenes-en-el-desafio-climatico\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;COP 28 y la participaci&oacute;n de los j&oacute;venes en el desaf&iacute;o clim&agrave;tico&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Los dibujos de la guerra de Ucrania&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mitigar-y-adaptarse-un-analisis-de-el-balance-mundial\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mitigar y adaptarse. Un an&aacute;lisis de El Balance Mundial&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/resiliencia\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">resiliencia<\/a>; al mismo tiempo, el tipo de casa que dibuja significa que mantiene mucha fuerza interior, por su temperamento, a pesar de los tiempos dif&iacute;ciles que le ha tocado vivir&rdquo;.<\/p>\n\n\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/sad-borg.82-223-8-23.plesk.page\/wp-content\/uploads\/2024\/02\/2.-%D0%92%D1%96%D0%BE%D0%BB%D0%B5%D1%82%D1%82%D0%B0-4-%D1%80%D0%BE%D0%BA%D1%96%D0%B2-1-724x1024.jpg\" alt=\"\" class=\"wp-image-19046\" style=\"width:493px;height:auto\" srcset=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/2.-&#1042;&#1110;&#1086;&#1083;&#1077;&#1090;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1110;&#1074;-1-724x1024.jpg 724w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/2.-&#1042;&#1110;&#1086;&#1083;&#1077;&#1090;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1110;&#1074;-1-212x300.jpg 212w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/2.-&#1042;&#1110;&#1086;&#1083;&#1077;&#1090;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1110;&#1074;-1-768x1086.jpg 768w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/2.-&#1042;&#1110;&#1086;&#1083;&#1077;&#1090;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1110;&#1074;-1-1086x1536.jpg 1086w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/2.-&#1042;&#1110;&#1086;&#1083;&#1077;&#1090;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1110;&#1074;-1-1448x2048.jpg 1448w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/2.-&#1042;&#1110;&#1086;&#1083;&#1077;&#1090;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1110;&#1074;-1-1080x1527.jpg 1080w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/2.-&#1042;&#1110;&#1086;&#1083;&#1077;&#1090;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1110;&#1074;-1-1280x1810.jpg 1280w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/2.-&#1042;&#1110;&#1086;&#1083;&#1077;&#1090;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1110;&#1074;-1-980x1386.jpg 980w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/2.-&#1042;&#1110;&#1086;&#1083;&#1077;&#1090;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1110;&#1074;-1-480x679.jpg 480w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/2.-&#1042;&#1110;&#1086;&#1083;&#1077;&#1090;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1110;&#1074;-1-scaled.jpg 1810w\" sizes=\"(max-width: 724px) 100vw, 724px\"\/><figcaption class=\"wp-element-caption\">2. Violetta, 4 a&ntilde;os<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Como podemos ver, el dibujo de la casa que ha hecho <strong>Violetta<\/strong> es parecido al de Varia, lo que denota mucha fuerza y &#8203;&#8203;mucha <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Resiliencia&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La resiliencia es la capacidad de recuperarse frente a la adversidad, adaptarse a situaciones dif&iacute;ciles y salir fortalecido de ellas.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/luchar-contra-el-cambio-climatico-tambien-es-combatir-la-desinformacion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Luchar contra el cambio clim&aacute;tico tambi&eacute;n es combatir la desinformaci&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/movimientos-juveniles-en-europa-en-busca-de-respuestas-a-la-crisis-climatica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Movimientos juveniles en Europa en busca de respuestas a la crisis clim&aacute;tica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/cop-28-y-la-participacion-de-los-jovenes-en-el-desafio-climatico\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;COP 28 y la participaci&oacute;n de los j&oacute;venes en el desaf&iacute;o clim&agrave;tico&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Los dibujos de la guerra de Ucrania&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mitigar-y-adaptarse-un-analisis-de-el-balance-mundial\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mitigar y adaptarse. Un an&aacute;lisis de El Balance Mundial&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/resiliencia\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">resiliencia<\/a>. &ldquo;Adem&aacute;s, la puerta &mdash;que tiene mucha presencia en la casa&mdash; habla de una buena capacidad de comunicaci&oacute;n y de interacci&oacute;n con los dem&aacute;s&rdquo;.<\/p>\n\n\n\n<p>Violetta, por el contrario, no dibuja ning&uacute;n paraguas para protegerse de la lluvia, y &ldquo;esto indica que necesita alg&uacute;n recurso para hacer frente al estr&eacute;s como, por ejemplo, relajarse o aprender a manejar sus pensamientos. Asimismo, esta proyecci&oacute;n de la figura humana bajo la lluvia en el lado derecho de la hoja indica que presenta una tendencia a pensar en el futuro como recurso para sentirse mejor ante situaciones estresantes&rdquo;.<\/p>\n\n\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/sad-borg.82-223-8-23.plesk.page\/wp-content\/uploads\/2024\/02\/3.-%D0%94%D0%B0%D0%B2%D1%96%D0%B4-5-%D1%80%D0%BE%D0%BA%D1%96%D0%B2-724x1024.jpg\" alt=\"\" class=\"wp-image-19042\" style=\"width:456px;height:auto\" srcset=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/3.-&#1044;&#1072;&#1074;&#1110;&#1076;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-724x1024.jpg 724w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/3.-&#1044;&#1072;&#1074;&#1110;&#1076;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-212x300.jpg 212w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/3.-&#1044;&#1072;&#1074;&#1110;&#1076;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-768x1086.jpg 768w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/3.-&#1044;&#1072;&#1074;&#1110;&#1076;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-1086x1536.jpg 1086w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/3.-&#1044;&#1072;&#1074;&#1110;&#1076;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-1448x2048.jpg 1448w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/3.-&#1044;&#1072;&#1074;&#1110;&#1076;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-1080x1527.jpg 1080w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/3.-&#1044;&#1072;&#1074;&#1110;&#1076;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-1280x1810.jpg 1280w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/3.-&#1044;&#1072;&#1074;&#1110;&#1076;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-980x1386.jpg 980w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/3.-&#1044;&#1072;&#1074;&#1110;&#1076;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-480x679.jpg 480w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/3.-&#1044;&#1072;&#1074;&#1110;&#1076;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-scaled.jpg 1810w\" sizes=\"(max-width: 724px) 100vw, 724px\"\/><figcaption class=\"wp-element-caption\">3. David, 5 a&ntilde;os<\/figcaption><\/figure>\n<\/div>\n\n\n<p>El siguiente dibujo, el de <strong>David<\/strong>, de 5 a&ntilde;os, evidencia algo de malestar emocional. &ldquo;Ya vemos que la figura humana est&aacute; dibujada m&aacute;s con cuchillos. Esto habla m&aacute;s de una tensi&oacute;n a nivel emocional que est&aacute; expresada desde el dibujo&rdquo;. Las manos &mdash;que hablan de la relaci&oacute;n con la familia&mdash; son rojas y est&aacute;n apretadas; por tanto, pueden expresar que hay tensi&oacute;n a nivel familiar o que los padres est&aacute;n m&aacute;s tensos&rdquo;.<\/p>\n\n\n\n<p>En el dibujo de abajo, el &aacute;rbol de la derecha, que es muy grande, muestra una necesidad de apoyarse en la madre. Al mismo tiempo, tiene las orejas muy grandes, lo que indica que es un ni&ntilde;o muy sensible a lo que siente, y por tanto, hay que decirle las cosas de una manera muy positiva. Al mismo tiempo, Casanovas se&ntilde;ala que quiz&aacute;s se deber&iacute;a evitar decirle cosas que pretenden los mayores o cosas que le puedan preocupar demasiado.<\/p>\n\n\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"725\" height=\"1024\" src=\"https:\/\/sad-borg.82-223-8-23.plesk.page\/wp-content\/uploads\/2024\/02\/4.-%D0%97%D0%BB%D0%B0%D1%82%D0%B0-4-%D1%80%D0%BE%D0%BA%D0%B8-725x1024.jpg\" alt=\"\" class=\"wp-image-19038\" style=\"width:464px;height:auto\" srcset=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/4.-&#1047;&#1083;&#1072;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1080;-725x1024.jpg 725w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/4.-&#1047;&#1083;&#1072;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1080;-212x300.jpg 212w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/4.-&#1047;&#1083;&#1072;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1080;-768x1085.jpg 768w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/4.-&#1047;&#1083;&#1072;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1080;-1088x1536.jpg 1088w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/4.-&#1047;&#1083;&#1072;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1080;-1450x2048.jpg 1450w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/4.-&#1047;&#1083;&#1072;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1080;-1080x1525.jpg 1080w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/4.-&#1047;&#1083;&#1072;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1080;-1280x1807.jpg 1280w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/4.-&#1047;&#1083;&#1072;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1080;-980x1384.jpg 980w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/4.-&#1047;&#1083;&#1072;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1080;-480x678.jpg 480w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/4.-&#1047;&#1083;&#1072;&#1090;&#1072;-4-&#1088;&#1086;&#1082;&#1080;-scaled.jpg 1813w\" sizes=\"(max-width: 725px) 100vw, 725px\"\/><figcaption class=\"wp-element-caption\">4. Zlata, 4 a&ntilde;os<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Igual que el dibujo de David, el de <strong>Zlata<\/strong> denota una necesidad de la figura materna, que se representa mediante el &aacute;rbol grande a la izquierda. La casa tiene una ventana en la parte de arriba, el tejado y la redonda, que est&aacute; vinculada a una necesidad de conciencia. &ldquo;Por tanto, Zlata necesita ser muy consciente del porqu&eacute; de las cosas y de qu&eacute; puede hacer y qu&eacute; no. Sin embargo, dibuja la puerta alejada del suelo, y eso significa que siente que necesita protecci&oacute;n&rdquo;.<\/p>\n\n\n\n<p>En la parte inferior del dibujo destaca un arco iris sobre la figura humana, y eso es un signo de transformaci&oacute;n. &ldquo;Este ni&ntilde;o est&aacute; viendo que las cosas est&aacute;n cambiando hacia mejor&rdquo;.<\/p>\n\n\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"762\" height=\"1024\" src=\"https:\/\/sad-borg.82-223-8-23.plesk.page\/wp-content\/uploads\/2024\/02\/5.-%D0%97%D0%BE%D1%80%D1%8F%D0%BD%D0%B0-6-%D1%80%D0%BE%D0%BA%D1%96%D0%B2-762x1024.jpg\" alt=\"\" class=\"wp-image-19034\" style=\"width:464px;height:auto\" srcset=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/5.-&#1047;&#1086;&#1088;&#1103;&#1085;&#1072;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-762x1024.jpg 762w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/5.-&#1047;&#1086;&#1088;&#1103;&#1085;&#1072;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-223x300.jpg 223w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/5.-&#1047;&#1086;&#1088;&#1103;&#1085;&#1072;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-768x1032.jpg 768w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/5.-&#1047;&#1086;&#1088;&#1103;&#1085;&#1072;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-1143x1536.jpg 1143w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/5.-&#1047;&#1086;&#1088;&#1103;&#1085;&#1072;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-1524x2048.jpg 1524w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/5.-&#1047;&#1086;&#1088;&#1103;&#1085;&#1072;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-1080x1452.jpg 1080w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/5.-&#1047;&#1086;&#1088;&#1103;&#1085;&#1072;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-1280x1720.jpg 1280w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/5.-&#1047;&#1086;&#1088;&#1103;&#1085;&#1072;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-980x1317.jpg 980w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/5.-&#1047;&#1086;&#1088;&#1103;&#1085;&#1072;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-480x645.jpg 480w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/5.-&#1047;&#1086;&#1088;&#1103;&#1085;&#1072;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-scaled.jpg 1905w\" sizes=\"(max-width: 762px) 100vw, 762px\"\/><figcaption class=\"wp-element-caption\">5. Zoriana, 6 a&ntilde;os<\/figcaption><\/figure>\n<\/div>\n\n\n<p>En el dibujo de <strong>Zoriana<\/strong> destaca una hierba muy larga, tan alta como las piernas, y eso significa que proyecta su necesidad de sentir ternura y mucho positivismo en la comunicaci&oacute;n. La figura de abajo aguanta una especie de globo, que denota la necesidad de control, es decir, ser&iacute;a interesante dejar que esta ni&ntilde;a decida cosas, para evitar que sienta esa impotencia. &ldquo;El globo tambi&eacute;n hace referencia a la necesidad de reencontrar a la ni&ntilde;a interior; indica que Zoriana tiene la necesidad de preservar esta vida de ni&ntilde;a, que juega a pesar de lo seria que es la situaci&oacute;n que la rodea&rdquo;.<\/p>\n\n\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"730\" height=\"1024\" src=\"https:\/\/sad-borg.82-223-8-23.plesk.page\/wp-content\/uploads\/2024\/02\/6.-%D0%9E%D1%80%D0%B5%D1%81%D1%82-6-%D1%80%D0%BE%D0%BA%D1%96%D0%B2-0001-730x1024.jpg\" alt=\"\" class=\"wp-image-19030\" style=\"width:463px;height:auto\" srcset=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/6.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0001-730x1024.jpg 730w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/6.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0001-214x300.jpg 214w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/6.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0001-768x1077.jpg 768w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/6.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0001-1095x1536.jpg 1095w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/6.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0001-1460x2048.jpg 1460w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/6.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0001-1080x1515.jpg 1080w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/6.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0001-1280x1795.jpg 1280w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/6.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0001-980x1374.jpg 980w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/6.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0001-480x673.jpg 480w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/6.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0001.jpg 1777w\" sizes=\"(max-width: 730px) 100vw, 730px\"\/><figcaption class=\"wp-element-caption\">6. Orest, 6 a&ntilde;os<\/figcaption><\/figure>\n<\/div>\n\n\n<p>El dibujo de <strong>Orest<\/strong> es bastante positivo, pues la figura humana es m&aacute;s grande que la casa. A la derecha del tejado hay dos l&iacute;neas; una de ellas, distorsionada, puede indicar que el ni&ntilde;o siente que se est&aacute; fragilizando la protecci&oacute;n. Normalmente, el lado derecho se vincula al padre, de modo que una posibilidad es que Orest sienta una potencial desprotecci&oacute;n por parte del padre; puede que porque se haya ido a la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a>, o bien porque tema que deba marcharse en un futuro. Dibujar un &aacute;rbol a cada lado de la casa explica que est&aacute; desarrollando los recursos necesarios para sentirse m&aacute;s protegido.<\/p>\n\n\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"721\" height=\"1024\" src=\"https:\/\/sad-borg.82-223-8-23.plesk.page\/wp-content\/uploads\/2024\/02\/7.-%D0%9E%D1%80%D0%B5%D1%81%D1%82-6-%D1%80%D0%BE%D0%BA%D1%96%D0%B2-0002-721x1024.jpg\" alt=\"\" class=\"wp-image-19026\" style=\"width:463px;height:auto\" srcset=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/7.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0002-721x1024.jpg 721w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/7.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0002-211x300.jpg 211w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/7.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0002-768x1091.jpg 768w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/7.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0002-1081x1536.jpg 1081w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/7.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0002-1442x2048.jpg 1442w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/7.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0002-1080x1534.jpg 1080w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/7.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0002-1280x1818.jpg 1280w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/7.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0002-980x1392.jpg 980w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/7.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0002-480x682.jpg 480w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/7.-&#1054;&#1088;&#1077;&#1089;&#1090;-6-&#1088;&#1086;&#1082;&#1110;&#1074;-0002.jpg 1746w\" sizes=\"(max-width: 721px) 100vw, 721px\"\/><figcaption class=\"wp-element-caption\">7. Orest, 6 a&ntilde;os<\/figcaption><\/figure>\n<\/div>\n\n\n<p>El otro dibujo de esta figura humana con la cabeza y los pies amarillos bajo la lluvia es interesante, porque contiene un muy buen paraguas, y por tanto, indica que Orest tiene la capacidad de poner en acci&oacute;n cosas con las que se siente protegido. S&iacute; habr&iacute;a que destacar una nube, que denota la sensaci&oacute;n del ni&ntilde;o de &ldquo;que todo me pasa a m&iacute;, todo dentro de m&iacute; se cae. Tambi&eacute;n debe remarcarse que sus recursos son eficaces y el hecho de que el personaje no tenga cabello, indica que la situaci&oacute;n que vive est&aacute; afectando su autoestima&rdquo;. Tambi&eacute;n vemos que dibuja el sol a la derecha, junto a la nube. Esto significa que a pesar de la presencia de dificultades y el estr&eacute;s que pueda estar viviendo, tambi&eacute;n es capaz de ver que hay cosas positivas.<\/p>\n\n\n\n<p><\/p>\n\n\n<div class=\"wp-block-image is-style-rounded\">\n<figure class=\"aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" width=\"724\" height=\"1024\" src=\"https:\/\/sad-borg.82-223-8-23.plesk.page\/wp-content\/uploads\/2024\/02\/8.-%D0%A0%D1%96%D1%82%D0%B0-5-%D1%80%D0%BE%D0%BA%D1%96%D0%B2-724x1024.jpg\" alt=\"\" class=\"wp-image-19022\" style=\"width:464px;height:auto\" srcset=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/8.-&#1056;&#1110;&#1090;&#1072;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-724x1024.jpg 724w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/8.-&#1056;&#1110;&#1090;&#1072;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-212x300.jpg 212w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/8.-&#1056;&#1110;&#1090;&#1072;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-768x1086.jpg 768w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/8.-&#1056;&#1110;&#1090;&#1072;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-1086x1536.jpg 1086w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/8.-&#1056;&#1110;&#1090;&#1072;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-1448x2048.jpg 1448w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/8.-&#1056;&#1110;&#1090;&#1072;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-1080x1527.jpg 1080w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/8.-&#1056;&#1110;&#1090;&#1072;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-1280x1810.jpg 1280w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/8.-&#1056;&#1110;&#1090;&#1072;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-980x1386.jpg 980w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/8.-&#1056;&#1110;&#1090;&#1072;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-480x679.jpg 480w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/8.-&#1056;&#1110;&#1090;&#1072;-5-&#1088;&#1086;&#1082;&#1110;&#1074;-scaled.jpg 1810w\" sizes=\"(max-width: 724px) 100vw, 724px\"\/><figcaption class=\"wp-element-caption\">8. Rita, 5 a&ntilde;os<\/figcaption><\/figure>\n<\/div>\n\n\n<p>Por &uacute;ltimo, en el dibujo de <strong>Rita<\/strong>, de 5 a&ntilde;os, destaca la falta de recursos: &ldquo;la persona bajo la lluvia no tiene paraguas, y aunque parece una ni&ntilde;a contenta y sensible &mdash;por las pesta&ntilde;as y ojos rosas que dibuja&mdash;, esta falta de herramienta de protecci&oacute;n en el dibujo denota una necesidad de recursos para aferrarse a una situaci&oacute;n dif&iacute;cil en la vida real&rdquo;.<\/p>\n\n\n\n<p>&ldquo;En el dibujo del &aacute;rbol destaca &mdash;por el tipo de copa y las tachaduras&mdash; que quiz&aacute;s sufre preocupaciones a nivel mental, ya que la copa est&aacute; vinculada al nivel mental de la persona&rdquo;. &ldquo;La casa tambi&eacute;n es rosa, igual que la cara de abajo, por tanto, a pesar de las preocupaciones y tensiones, hay un aspecto dulce que es importante y eso ser&iacute;a positivo&rdquo;, concluye la psic&oacute;loga.<\/p>\n\n\n\n<p>&ldquo;En estos dibujos, uno de los aspectos importantes en las representaciones de personas bajo la lluvia es ver si llevan o no paraguas. La mayor&iacute;a de los personajes no lo llevan, o es poco funcional, y esto sugiere que los personajes no se acaban de sentir bien protegidos&rdquo;. &ldquo;Esto significa que son ni&ntilde;os que no tienen recursos o defensas para protegerse de situaciones de dificultad&rdquo;.<\/p>\n\n\n\n<p>&ldquo;Si son ni&ntilde;os de la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a>, pese a su capacidad, han tenido una situaci&oacute;n de la que no han podido escapar: est&aacute;n afectados s&iacute; o s&iacute; por situaciones estresantes&rdquo;.<\/p>\n\n\n\n<p>Sin embargo, Casanovas se&ntilde;ala que los dibujos son bastante positivos, quiz&aacute;s por la zona donde residen estos ni&ntilde;os. La psic&oacute;loga enfatiza que hizo un an&aacute;lisis de diferentes dibujos de ni&ntilde;os provenientes de Ucrania que contaban con la ayuda de la Cruz Roja aqu&iacute;, en Catalu&ntilde;a, y que &ldquo;esos dibujos canalizaban situaciones extremadamente traum&aacute;ticas&rdquo;. &ldquo;Se ve&iacute;an ni&ntilde;os rotos, gente con sangre, gente muerta, cad&aacute;veres y metralletas. Y entonces es cuando el dibujo permite encauzar lo que a veces el ni&ntilde;o no explica, porque no quiere o no puede&rdquo;.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>N&uacute;ria Casanovas, psic&oacute;loga, analiza los dibujos de siete ni&ntilde;os que han vivido la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a> en Kiev, la capital de Ucrania, que lleva m&aacute;s de un a&ntilde;o bajo amenaza de ser invadida por las tropas de Vladimir Putin.<\/p>\n","protected":false},"author":50,"featured_media":19011,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[349,343],"tags":[85],"coauthors":[206],"class_list":{"0":"post-19010","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-conflictos-de-guerra","8":"category-derechos-humanos","9":"tag-ucrania"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Los dibujos de la guerra de Ucrania - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Los dibujos de la guerra de Ucrania - xqthenews\" \/>\n<meta property=\"og:description\" content=\"N&uacute;ria Casanovas, psic&oacute;loga, analiza los dibujos de siete ni&ntilde;os que han vivido la guerra en Kiev, la capital de Ucrania, que lleva m&aacute;s de un a&ntilde;o bajo amenaza de ser invadida por las tropas de Vladimir Putin.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-28T07:10:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-10T22:00:18+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/PORTADA.-Los-dibujos.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1170\" \/>\n\t<meta property=\"og:image:height\" content=\"530\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Gabarr\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Gabarr\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Andrea Gabarr\u00f3\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/los-dibujos-de-la-guerra-de-ucrania\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/los-dibujos-de-la-guerra-de-ucrania\\\/\"},\"author\":{\"name\":\"Andrea Gabarr\u00f3\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/85154df4aac7f0ce5bd2db8c552b66d4\"},\"headline\":\"Los dibujos de la guerra de Ucrania\",\"datePublished\":\"2024-02-28T07:10:18+00:00\",\"dateModified\":\"2024-09-10T22:00:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/los-dibujos-de-la-guerra-de-ucrania\\\/\"},\"wordCount\":2222,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/los-dibujos-de-la-guerra-de-ucrania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/PORTADA.-Los-dibujos.jpg\",\"keywords\":[\"Ucrania\"],\"articleSection\":[\"Conflictos de guerra\",\"Derechos humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/es\\\/los-dibujos-de-la-guerra-de-ucrania\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/los-dibujos-de-la-guerra-de-ucrania\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/los-dibujos-de-la-guerra-de-ucrania\\\/\",\"name\":\"Los dibujos de la guerra de Ucrania - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/los-dibujos-de-la-guerra-de-ucrania\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/los-dibujos-de-la-guerra-de-ucrania\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/PORTADA.-Los-dibujos.jpg\",\"datePublished\":\"2024-02-28T07:10:18+00:00\",\"dateModified\":\"2024-09-10T22:00:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/85154df4aac7f0ce5bd2db8c552b66d4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/los-dibujos-de-la-guerra-de-ucrania\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/es\\\/los-dibujos-de-la-guerra-de-ucrania\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/los-dibujos-de-la-guerra-de-ucrania\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/PORTADA.-Los-dibujos.jpg\",\"contentUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/PORTADA.-Los-dibujos.jpg\",\"width\":1170,\"height\":530},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/los-dibujos-de-la-guerra-de-ucrania\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Los dibujos de la guerra de Ucrania\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/85154df4aac7f0ce5bd2db8c552b66d4\",\"name\":\"Andrea Gabarr\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771828b8a100ec5d002be00040bf2cbdca4c619f8d1096207e8e363ae96f4068?s=96&d=mm&r=g4e009d12e278bad1648bf6a377de823b\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771828b8a100ec5d002be00040bf2cbdca4c619f8d1096207e8e363ae96f4068?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771828b8a100ec5d002be00040bf2cbdca4c619f8d1096207e8e363ae96f4068?s=96&d=mm&r=g\",\"caption\":\"Andrea Gabarr\u00f3\"},\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/author\\\/andreagabarro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Los dibujos de la guerra de Ucrania - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/","og_locale":"es_ES","og_type":"article","og_title":"Los dibujos de la guerra de Ucrania - xqthenews","og_description":"N&uacute;ria Casanovas, psic&oacute;loga, analiza los dibujos de siete ni&ntilde;os que han vivido la guerra en Kiev, la capital de Ucrania, que lleva m&aacute;s de un a&ntilde;o bajo amenaza de ser invadida por las tropas de Vladimir Putin.","og_url":"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/","og_site_name":"xqthenews","article_published_time":"2024-02-28T07:10:18+00:00","article_modified_time":"2024-09-10T22:00:18+00:00","og_image":[{"width":1170,"height":530,"url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/PORTADA.-Los-dibujos.jpg","type":"image\/jpeg"}],"author":"Andrea Gabarr\u00f3","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andrea Gabarr\u00f3","Tiempo de lectura":"11 minutos","Written by":"Andrea Gabarr\u00f3"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/#article","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/"},"author":{"name":"Andrea Gabarr\u00f3","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/85154df4aac7f0ce5bd2db8c552b66d4"},"headline":"Los dibujos de la guerra de Ucrania","datePublished":"2024-02-28T07:10:18+00:00","dateModified":"2024-09-10T22:00:18+00:00","mainEntityOfPage":{"@id":"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/"},"wordCount":2222,"commentCount":0,"image":{"@id":"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/PORTADA.-Los-dibujos.jpg","keywords":["Ucrania"],"articleSection":["Conflictos de guerra","Derechos humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/","url":"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/","name":"Los dibujos de la guerra de Ucrania - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/#primaryimage"},"image":{"@id":"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/PORTADA.-Los-dibujos.jpg","datePublished":"2024-02-28T07:10:18+00:00","dateModified":"2024-09-10T22:00:18+00:00","author":{"@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/85154df4aac7f0ce5bd2db8c552b66d4"},"breadcrumb":{"@id":"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/#primaryimage","url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/PORTADA.-Los-dibujos.jpg","contentUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/PORTADA.-Los-dibujos.jpg","width":1170,"height":530},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/es\/los-dibujos-de-la-guerra-de-ucrania\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/es\/"},{"@type":"ListItem","position":2,"name":"Los dibujos de la guerra de Ucrania"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/85154df4aac7f0ce5bd2db8c552b66d4","name":"Andrea Gabarr\u00f3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/771828b8a100ec5d002be00040bf2cbdca4c619f8d1096207e8e363ae96f4068?s=96&d=mm&r=g4e009d12e278bad1648bf6a377de823b","url":"https:\/\/secure.gravatar.com\/avatar\/771828b8a100ec5d002be00040bf2cbdca4c619f8d1096207e8e363ae96f4068?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/771828b8a100ec5d002be00040bf2cbdca4c619f8d1096207e8e363ae96f4068?s=96&d=mm&r=g","caption":"Andrea Gabarr\u00f3"},"url":"https:\/\/xqthenews.com\/es\/author\/andreagabarro\/"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/posts\/19010","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/comments?post=19010"}],"version-history":[{"count":0,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/posts\/19010\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/media\/19011"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/media?parent=19010"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/categories?post=19010"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/tags?post=19010"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/coauthors?post=19010"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}