{"id":17554,"date":"2024-02-07T08:10:44","date_gmt":"2024-02-07T07:10:44","guid":{"rendered":"https:\/\/sad-borg.82-223-8-23.plesk.page\/?p=17554"},"modified":"2024-09-10T22:59:58","modified_gmt":"2024-09-10T21:59:58","slug":"la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible","status":"publish","type":"post","link":"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/","title":{"rendered":"La \u2018orfandad social\u2019, un mal end\u00e9mico de Ucrania que la guerra ha hecho visible"},"content":{"rendered":"<p class=\"wp-block-paragraph\">A la delicada condici&oacute;n de la orfandad en Ucrania, con un sistema de orfanatos post-sovi&eacute;tico en lenta reforma, se le a&ntilde;ade el complicado estatus del &ldquo;hu&eacute;rfano social&rdquo;. Los hu&eacute;rfanos sociales son aquellos ni&ntilde;os que no cuentan con sus figuras paternas debido a la negligencia de estas y no por su fallecimiento. Problemas de abuso de alcohol, con la justicia o una econom&iacute;a cada vez m&aacute;s debilitada son algunos de los motivos por los que los ni&ntilde;os son sustra&iacute;dos de las manos de sus progenitores por los servicios sociales. Un problema end&eacute;mico que, con el conflicto armado iniciado en 2014, parece ser cada vez m&aacute;s evidente.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Diez cabezas montan de regreso a casa en la parte trasera de una furgoneta conducida por una mujer pelirroja y de cabello corto. Una cruz colgada del retrovisor central es zarandeada al ritmo de la carretera y, de fondo, los hits musicales que emite el programa de las 17:00 h. Debajo, una insignia azul y amarilla mostrada con orgullo. Atr&aacute;s, Veronika, vestida de rosa de la cabeza a los pies, sonr&iacute;e p&iacute;cara mientras cuenta lo que ha hecho en el colegio a su hermana mayor, Marichka, en cuyo regazo est&aacute; sentada para dejar lugar a los invitados que hoy vienen a merendar a su hogar. Sasha y Sashko, ambos de 13 a&ntilde;os, musitan en ucraniano el plan de esta tarde, mientras que Maksym, de rostro travieso, mira por la ventana en busca de alg&uacute;n lugar que le indique que ya est&aacute; cerca de poder volver a corretear. Los diez hermanos comparten an&eacute;cdotas y roces del d&iacute;a a d&iacute;a en la parte trasera del veh&iacute;culo. No se trata de una <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Adaptaci&oacute;n&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Proceso de ajuste al cambio clim&aacute;tico actual o previsto y a sus efectos. Implica tomar medidas para reducir la vulnerabilidad y aumentar la resistencia de los sistemas humanos y naturales.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/luchar-contra-el-cambio-climatico-tambien-es-combatir-la-desinformacion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Luchar contra el cambio clim&aacute;tico tambi&eacute;n es combatir la desinformaci&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-inteligencia-artificial-esta-cambiando-la-informacion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La inteligencia artificial est&aacute; cambiando la informaci&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/cop-28-y-la-participacion-de-los-jovenes-en-el-desafio-climatico\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;COP 28 y la participaci&oacute;n de los j&oacute;venes en el desaf&iacute;o clim&agrave;tico&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/se-conocen-y-combaten-las-especies-exoticas-invasoras\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Se conocen y combaten las especies ex&oacute;ticas invasoras&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La &lsquo;orfandad social&rsquo;, un mal end&eacute;mico de Ucrania que la guerra ha hecho visible&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/adaptacion\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">adaptaci&oacute;n<\/a> ucraniana de Los Serrano, sino de la Foster Family que Katarina Dolgova ha ido formando a lo largo de los a&ntilde;os.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los t&eacute;rminos &ldquo;foster care&rdquo; o &ldquo;fostering&rdquo;, se traducen como &ldquo;cuidado de crianza&rdquo; o &ldquo;acogida&rdquo; y se utilizan en Estados Unidos y Europa para referirse al cuidado que se brinda a una ni&ntilde;a o ni&ntilde;o en contextos familiares sin relaci&oacute;n de parentesco, usualmente de manera temporal (aunque puede ser de largo plazo). Es una colocaci&oacute;n administrada y regulada por el Estado, que se da en el lapso de espera para alcanzar opciones permanentes de vida c&oacute;mo el retorno a su familia de origen, la adopci&oacute;n o alcanzar la mayor&iacute;a de edad. Este concepto ha cobrado especial protagonismo en el pa&iacute;s en los &uacute;ltimos a&ntilde;os, puesto que el gobierno ucraniano ha tomado medidas para reformar el sistema de bienestar infantil, con el objetivo de pasar del cuidado institucional al cuidado familiar. Seg&uacute;n la psic&oacute;loga sanitaria&nbsp;&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">especializada en terapia familiar y gesti&oacute;n emocional, Blanca In&eacute;s Santa Mar&iacute;a, la acogida en una familia dota a los ni&ntilde;os la vivencia de que existen otras realidades fuera de la suya. &ldquo;Les proporciona otra oportunidad de experimentar la familia, de ver otro tipo de relaciones, interacciones y din&aacute;micas familiares m&aacute;s sanas; otro tipo de lenguajes del amor&rdquo;, explica Santa Maria. Muchas veces las familias de las cuales provienen estos ni&ntilde;os son muy desestructuradas, con &ldquo;much&iacute;simos problemas y un alto &iacute;ndice de agresividad y emocionabilidad alterada: much&iacute;sima expresi&oacute;n emocional muy intensa -gritos, insultos, agresiones verbales, f&iacute;sicas, rotura de mobiliario, etc- &ldquo;, prosigue la psic&oacute;loga. Es por eso que, acorde a lo que cuenta Blanca In&eacute;s, darles m&aacute;s recursos para salir adelante es darles &ldquo;otra oportunidad de vida&rdquo;. Pese a todos los beneficios que presenta la acogida respecto al modelo tradicional de orfanatos, el progreso ha sido lento y a&uacute;n quedan muchos desaf&iacute;os por abordar.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Esta profesora de teolog&iacute;a e historia hace unos a&ntilde;os decidi&oacute; que quer&iacute;a ser madre de acogida e inici&oacute; todos los tr&aacute;mites con servicios sociales para poder conseguirlo. Su hermana mayor tambi&eacute;n fue una ni&ntilde;a de acogida y en estos ni&ntilde;os la ve reflejada. &ldquo;Desde peque&ntilde;a me han gustado los ni&ntilde;os, siempre estaba haciendo de canguro a los hijos de los vecinos, es algo que siempre he disfrutado mucho&rdquo;, relata Katarina. Otro de los motivos por los que decidi&oacute; crear una Foster Family es que, siendo directora de un orfanato se dio cuenta de que, en realidad, los ni&ntilde;os hu&eacute;rfanos no eran tan dif&iacute;ciles de tratar. &ldquo;Vi que los ni&ntilde;os ser&aacute;n aquello que los adultos les permitan ser&rdquo;, explica Dolgova. &ldquo;Me di cuenta de que el sistema de cuidado institucional fallaba y cu&aacute;n necesario era para el futuro de los ni&ntilde;os tener la oportunidad de experimentar la vida dentro de una familia&rdquo;, prosigue.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Katarina Dolgova cuenta c&oacute;mo ha acabado teniendo diez ni&ntilde;os bajo su <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Tutela&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La tutela es la responsabilidad legal de cuidar y tomar decisiones para el bienestar de un menor cuando los padres no pueden hacerlo. Incluye custodia y protecci&oacute;n.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La &lsquo;orfandad social&rsquo;, un mal end&eacute;mico de Ucrania que la guerra ha hecho visible&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/in-crescita-i-rapporti-sessuali-a-rischio-tra-adolescenti\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;In crescita i rapporti sessuali a rischio tra adolescenti.&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/tutela\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">tutela<\/a> en la actualidad y quince desde que empez&oacute; como madre de acogida: &ldquo;los primeros ni&ntilde;os los saqu&eacute; del orfanato donde trabajaba. Eran ni&ntilde;os bastante dif&iacute;ciles, pero estaba orgullosa de ellos y quer&iacute;a demostrarles que pod&iacute;an cambiar&rdquo;, relata la maestra. &ldquo;He sufrido mucho por esos ni&ntilde;os, pero ahora puedo decir que no le tengo miedo a nada&rdquo;; prosigue. Explica que a los m&aacute;s mayores les est&aacute; yendo bien: uno de ellos est&aacute; apunto de graduarse, tiene trabajo y se casa en oto&ntilde;o. A menudo recibe visitas de sus hijos adoptivos y la ayudan en aquello que requiere. Poco tiempo despu&eacute;s de mudarse a Lviv, la hicieron madre de dos ni&ntilde;os m&aacute;s: Yeyhen y su hermana mayor, Marta. &ldquo;Simplemente los acept&eacute;, me los encomendaron y yo, que creo en Dios, s&eacute; que si permite algo es porque lo necesito; y as&iacute; fue&rdquo;, explica con serenidad Dolgova. M&aacute;s tarde recibi&oacute; a Solomiya, cuya cuidadora -su abuela- enferm&oacute; y no pod&iacute;a hacerse cargo de ella, y tambi&eacute;n a Sasha. Este &uacute;ltimo ten&iacute;a 5 a&ntilde;os de edad y Katarina dud&oacute; en recibirlo por la delicada situaci&oacute;n de su madre, que estaba en la c&aacute;rcel y pens&oacute; que&nbsp; cuando saliera se lo llevar&iacute;a&nbsp; de vuelta y ser&iacute;a un escenario muy complicado.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"644\" height=\"424\" src=\"https:\/\/sad-borg.82-223-8-23.plesk.page\/wp-content\/uploads\/2024\/02\/FOTO-1.png\" alt=\"\" class=\"wp-image-17560\" srcset=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/FOTO-1.png 644w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/FOTO-1-300x198.png 300w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/FOTO-1-480x316.png 480w\" sizes=\"(max-width: 644px) 100vw, 644px\"\/><figcaption class=\"wp-element-caption\">Veronika, Marishcka, Maksym, Yura, Sasha, Sashko, Volodia, Ivan, Solomiya y Stepan camino a casa en la parte trasera de la furgoneta de Katarina. | David Melero.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En aquel momento ella ya ten&iacute;a siete ni&ntilde;os a su cargo y necesitaba acoger unos cuantos m&aacute;s para conseguir calificarse como hogar de acogida. &ldquo;Ped&iacute; a los servicios sociales que me dieran ni&ntilde;os m&aacute;s peque&ntilde;os, s&oacute;lo ten&iacute;a adolescentes&rdquo;, relata ri&eacute;ndose. As&iacute; que llegaron tres ni&ntilde;os m&aacute;s a su vida: Marichka, de siete a&ntilde;os, Sashko, de seis, y Volodia, de cuatro. Adriana se fue de la fam&iacute;lia y lleg&oacute; Tanya y as&iacute; vivieron unos cinco a&ntilde;os, hasta que Mykhailo se march&oacute; y consecutivamente, Tanya. En un a&ntilde;o y medio recibi&oacute; a Veronika y Maksym, de tres y cuatro a&ntilde;os, cuyo hermano mayor ya viv&iacute;a con Katarina. &laquo;Luego descubr&iacute; que Marichka, Sasha y Volodya ten&iacute;an dos hermanos m&aacute;s y empezamos a monitorear el proceso de acogida: establecimos contacto con ellos, los ni&ntilde;os visitaban a sus hermanos en un orfanato&rdquo;, cuenta Katarina. Finalmente, cuando obtuvieron el estatus legal de ni&ntilde;os privados de sus padres Stepan y Marta pudieron unirse a la familia.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La situaci&oacute;n de la infancia en Ucrania<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La situaci&oacute;n de la infancia en Ucrania es poco com&uacute;n, con el mayor n&uacute;mero de ni&ntilde;os internados en Europa en una vasta red, opaca y a menudo disfuncional de orfanatos, internados o instituciones para discapacitados. Alrededor de<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">160.000 ni&ntilde;os y ni&ntilde;as viven bajo la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Tutela&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La tutela es la responsabilidad legal de cuidar y tomar decisiones para el bienestar de un menor cuando los padres no pueden hacerlo. Incluye custodia y protecci&oacute;n.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La &lsquo;orfandad social&rsquo;, un mal end&eacute;mico de Ucrania que la guerra ha hecho visible&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/in-crescita-i-rapporti-sessuali-a-rischio-tra-adolescenti\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;In crescita i rapporti sessuali a rischio tra adolescenti.&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/tutela\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">tutela<\/a> del Estado en Ucrania y, seg&uacute;n confirma la Organizaci&oacute;n de las Naciones Unidas, casi 100.000 estaban repartidos en los m&aacute;s de 600 orfanatos del pa&iacute;s cuando estall&oacute; la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a>. La <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;ONU&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La ONU (Organizaci&oacute;n de las Naciones Unidas) es una entidad internacional fundada en 1945 para promover la cooperaci&oacute;n global y la paz, compuesta por 193 estados miembros&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mensaje-en-una-botella-o-los-plasticos-que-nunca-desaparecen\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mensaje en una botella, o los pl&aacute;sticos que nunca desaparecen&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/apartheid-en-palestina-las-raices-profundas-de-la-guerra\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Apartheid en Palestina, las ra&iacute;ces profundas de la guerra&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-destruccion-de-gaza-el-ultimo-capitulo-de-cien-anos-de-odio\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La destrucci&oacute;n de Gaza, el &uacute;ltimo cap&iacute;tulo de cien a&ntilde;os de odio&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/israel-una-potencia-militarista-y-probada-en-combate\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Israel, una potencia militarista y &amp;quot;probada en combate&rdquo;&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-oms-denuncia-mas-de-230-ataques-israelies-a-la-atencion-sanitaria-palestina\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La OMS denuncia m&aacute;s de 230 ataques israel&iacute;es a la atenci&oacute;n sanitaria palestina&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\"  href=\"https:\/\/xqthenews.com\/es\/glossary\/onu\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>ONU<\/a> adem&aacute;s alerta en su &uacute;ltimo informe que la mitad de estos menores tienen alg&uacute;n tipo de discapacidad. Tambi&eacute;n, y seg&uacute;n el Fondo de las Naciones Unidas para la Infancia (UNICEF), muchos de estos ni&ntilde;os son considerados hu&eacute;rfanos sociales, aquellos ni&ntilde;os que han sido separados de sus padres debido a la pobreza, la negligencia o el abuso, en lugar de la muerte de sus padres.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Hab&iacute;a &laquo;decenas de miles de ni&ntilde;os viviendo en estas instituciones antes de la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a>, es enorme&raquo;, alertaba hace unos a&ntilde;os en una rueda de prensa Genevi&egrave;ve Colas, coordinadora del colectivo Juntos contra la Trata de Seres Humanos para C&aacute;ritas Francia. Un estudio llevado a cabo en 2016 por la organizaci&oacute;n Hope and Homes for Children concluy&oacute; que existe una fallida en el amplio sistema de orfanatos y otras instituciones de Ucrania para proteger a los ni&ntilde;os vulnerables. La investigaci&oacute;n, que recopila datos de 663 orfanatos ucranianos, denuncia que, en un pa&iacute;s con una de las tasas m&aacute;s altas de cuidado institucional en Europa, existe un sistema &ldquo;estancado&rdquo; con directores que recategorizan sus instituciones en un proceso de &laquo;reforma ficticia&rdquo;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La auditor&iacute;a integral del sistema monitorizada por Hope and Homes for Children en 2016 ten&iacute;a como finalidad comprender c&oacute;mo y por qu&eacute; los ni&ntilde;os son enviados a instituciones, las condiciones que experimentan y el impacto que esto tiene en su desarrollo y sus oportunidades de vida. Despu&eacute;s de realizar el estudio, las declaraciones de la organizaci&oacute;n son poco esperanzadoras: &ldquo;la protecci&oacute;n de la infancia en Ucrania todav&iacute;a depende de una extensa red institucional, del tama&ntilde;o de una ciudad, donde los ni&ntilde;os viven aislados del resto de la sociedad, condenados a regulaciones arbitrarias y rutinas impersonales&rdquo;, escriben en un art&iacute;culo los miembros de esta organizaci&oacute;n. &laquo;En t&eacute;rminos de la actitud hacia los ni&ntilde;os y la comprensi&oacute;n de sus necesidades, poco ha cambiado en el sistema de protecci&oacute;n infantil de Ucrania desde la &eacute;poca sovi&eacute;tica&raquo;, dec&iacute;a en 2016 la Directora de la organizaci&oacute;n en Ucrania, Halyna Postoliuk.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sad-borg.82-223-8-23.plesk.page\/wp-content\/uploads\/2024\/02\/Foto-2-1024x683.jpg\" alt=\"\" class=\"wp-image-17564\" srcset=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-2-1024x683.jpg 1024w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-2-300x200.jpg 300w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-2-768x512.jpg 768w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-2-1536x1024.jpg 1536w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-2-2048x1365.jpg 2048w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-2-1080x720.jpg 1080w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-2-1280x854.jpg 1280w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-2-980x653.jpg 980w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-2-480x320.jpg 480w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"\/><figcaption class=\"wp-element-caption\">Katarina sosteniendo orgullosa y sonriente un retrato que le ha hecho su hija de acogida Marishka. | David Melero.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Desafortunadamente, la situaci&oacute;n no ha variado mucho desde la realizaci&oacute;n del estudio. En Ucrania, los orfanatos se denominan &laquo;internados&raquo; y suelen ser instituciones administradas por el gobierno que albergan a ni&ntilde;os que han quedado hu&eacute;rfanos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los ni&ntilde;os en internados pueden vivir en habitaciones estilo dormitorio con diversos otros ni&ntilde;os, o en grupos m&aacute;s peque&ntilde;os de estilo familiar, aunque estos &uacute;ltimos son la excepci&oacute;n. Por lo general, reciben necesidades b&aacute;sicas como alimentos, ropa y atenci&oacute;n m&eacute;dica, pero la calidad de estos servicios puede variar en funci&oacute;n de las condiciones del centro. Normalmente los internados disponen de recursos y personal limitados, lo que puede afectar la calidad de la atenci&oacute;n y el apoyo que reciben los ni&ntilde;os. Pueden asistir a la escuela en las instalaciones o en las escuelas cercanas.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>Adicciones, abusos o inestabilidad econ&oacute;mica: algunas de las causas por las que tantos ni&ntilde;os quedan hu&eacute;rfanos a&uacute;n teniendo padres<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Seg&uacute;n un informe del Fondo de las Naciones Unidas para la Infancia (UNICEF), a partir de 2021, se estima que hab&iacute;a 100.000 ni&ntilde;os viviendo en cuidado institucional en Ucrania, y alrededor del 75% de ellos eran hu&eacute;rfanos sociales.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La cruda infancia de ni&ntilde;os cuyos padres sufren alcoholismo en una regi&oacute;n tan convulsa como la del Donbass -zona de Ucrania oriental fronteriza con Rusia que, desde el inicio de la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a> del Donbass en 2014 y a ra&iacute;z del inicio de la invasi&oacute;n rusa el a&ntilde;o pasado, es una zona fragmentada y actualmente bajo dominio ruso- queda plasmada en A House Made of Splinters, un documental del cineasta dan&eacute;s Simon Lereng. &ldquo;Nuestra idea era visibilizar a unos ni&ntilde;os que de por s&iacute; ya estaban en el escal&oacute;n m&aacute;s bajo de una sociedad totalmente devastada debido a las heridas del conflicto entre Rusia y Ucrania&rdquo;, expres&oacute; Lereng en una entrevista con EFE. La mayor&iacute;a de los ni&ntilde;os que aparecen en el documental se encontraban en situaci&oacute;n de vulnerabilidad, despu&eacute;s de que los servicios sociales retiraran su custodia a unos padres que padec&iacute;an de alcoholismo y no pod&iacute;an encargarse de sus cuidados. Las historias de Eva, Sasha, Polina y Kolya -los peque&ntilde;os del orfanato que componen el hilo argumental del documental- son las historias de los casi 100.000 ni&ntilde;os ucranianos que se encuentran bajo la <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Tutela&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La tutela es la responsabilidad legal de cuidar y tomar decisiones para el bienestar de un menor cuando los padres no pueden hacerlo. Incluye custodia y protecci&oacute;n.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La &lsquo;orfandad social&rsquo;, un mal end&eacute;mico de Ucrania que la guerra ha hecho visible&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/it\/in-crescita-i-rapporti-sessuali-a-rischio-tra-adolescenti\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;In crescita i rapporti sessuali a rischio tra adolescenti.&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/tutela\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">tutela<\/a> del estado. Un n&uacute;mero que, seguramente, vaya en aumento en los a&ntilde;os venideros debido al conflicto armado actual.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&laquo;Ha habido algunas mejoras fragmentadas, pero en general los gobiernos no han sentado las bases necesarias para prevenir la desintegraci&oacute;n familiar y garantizar un enfoque integrado de la protecci&oacute;n de los derechos del ni&ntilde;o.&rdquo;, declara la Directora de Hope and Homes for Children en Ucrania, Halyna Postoliuk. La atenci&oacute;n institucional sigue siendo la respuesta m&aacute;s com&uacute;n de las autoridades a los ni&ntilde;os cuyas propias familias tienen dificultades para cuidarlos, en gran parte debido a la pobreza y la discapacidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As&iacute; pues, uno de los principales problemas en Ucrania es la desprotecci&oacute;n de la infancia que, al fin y al cabo, constituir&aacute; el futuro del pa&iacute;s. La problem&aacute;tica de los hu&eacute;rfanos sociales en Ucrania puede deberse a m&uacute;ltiples factores. Sofia Vasylechko, educadora social en el orfanato Orphans Care Center, destaca los siguientes como los m&aacute;s substanciales:<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Una de las principales razones es la inestabilidad econ&oacute;mica y social que ha experimentado Ucrania desde que se independiz&oacute; de la Uni&oacute;n Sovi&eacute;tica en 1991. Esta inestabilidad ha llevado a altos niveles de pobreza, desempleo y desigualdad social, lo que ha dificultado que muchas familias puedan salir adelante. Adem&aacute;s, el conflicto en curso en el este de Ucrania tambi&eacute;n ha tenido un impacto significativo en el n&uacute;mero de hu&eacute;rfanos sociales. Desde que comenz&oacute; el conflicto en 2014, miles de personas han sido asesinadas y muchas m&aacute;s han sido desplazadas de sus hogares, lo que ha provocado un aumento en el n&uacute;mero de ni&ntilde;os que se han quedado sin padres o cuidadores. Otros factores que han contribuido a la gran cantidad de hu&eacute;rfanos sociales en Ucrania, comenta Sof&iacute;a, incluyen el inadecuado sistema de protecci&oacute;n infantil del pa&iacute;s, la falta de acceso a la educaci&oacute;n y la atenci&oacute;n m&eacute;dica, y una alta <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Prevalencia&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Prevalencia se refiere a la proporci&oacute;n de individuos que presentan una caracter&iacute;stica espec&iacute;fica en una poblaci&oacute;n en un momento dado.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La &lsquo;orfandad social&rsquo;, un mal end&eacute;mico de Ucrania que la guerra ha hecho visible&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-soledad-no-deseada-impacta-contra-los-jovenes\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La soledad no deseada impacta contra los j&oacute;venes&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-estrategia-de-la-ue-para-la-juventud-participacion-de-los-jovenes-en-la-vida-democratica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La Estrategia de la UE para la Juventud: participaci&oacute;n de los j&oacute;venes en la vida democr&aacute;tica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/maria-calado-el-inicio-de-los-trastornos-de-conducta-alimentaria-se-esta-adelantando-hay-mas-casos-de-ninas\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mar&iacute;a Calado: &amp;quot;El inicio de los trastornos de conducta alimentaria se est&aacute; adelantando; hay m&aacute;s casos de ni&ntilde;as&rdquo;&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/bullying-y-ciberbullying-las-herramientas-para-prevenirlo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Bullying y ciberbullying: las herramientas para prevenirlo&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/prevalencia\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">prevalencia<\/a> de abuso de sustancias y violencia dom&eacute;stica.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>La delicada situaci&oacute;n burocr&aacute;tica de los hu&eacute;rfanos sociales<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">Katarina explica que para poder ser tutora de acogida hay que pasar por un proceso, inscrito dentro de un programa del gobierno para mejorar la situaci&oacute;n de la infancia en Ucrania camino a la desinstitucionalizaci&oacute;n. Mediante este, el estado paga una cierta cantidad para ayudar a criar a cada ni&ntilde;o y tambi&eacute;n da dinero para el mantenimiento de la casa. En el proceso investigan distintos aspectos de la vida del solicitante: formaci&oacute;n, salud f&iacute;sica y mental, estado econ&oacute;mico, etc. Adem&aacute;s, lo someten a distintos tests y entrevistas.&nbsp;<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sad-borg.82-223-8-23.plesk.page\/wp-content\/uploads\/2024\/02\/Foto-3-1024x683.jpg\" alt=\"\" class=\"wp-image-17568\" srcset=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-3-1024x683.jpg 1024w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-3-300x200.jpg 300w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-3-768x512.jpg 768w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-3-1536x1024.jpg 1536w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-3-2048x1365.jpg 2048w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-3-1080x720.jpg 1080w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-3-1280x854.jpg 1280w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-3-980x653.jpg 980w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-3-480x320.jpg 480w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"\/><figcaption class=\"wp-element-caption\">Sasha y Saschko deleitan a sus invitados de la tarde con un surtido de frutas, galletas, caf&eacute; y bombones preparado por ellos mismos bajo las &oacute;rdenes de Katarina, su madre de acogida. | David Melero.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Existe adem&aacute;s otro obst&aacute;culo para que un ni&ntilde;o cuyos padres siguen vivos pueda acceder a un hogar de acogida: los padres de estos tienen que estar oficialmente privados de sus <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Derechos paternos&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Derechos paternos son privilegios y responsabilidades legales que los padres tienen sobre sus hijos, incluyendo cuidado, crianza y toma de decisiones.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La &lsquo;orfandad social&rsquo;, un mal end&eacute;mico de Ucrania que la guerra ha hecho visible&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/derechos-paternos\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">derechos paternos<\/a>, proceso largo y delicado. Cabe se&ntilde;alar tambi&eacute;n que, seg&uacute;n Blanca In&eacute;s Santa Mar&iacute;a, el hecho de privar a los padres de sus hijos puede ser muy frustrante y pueden tener trastornos del estado de &aacute;nimo derivados de la situaci&oacute;n o agravar la situaci&oacute;n previa que padec&iacute;an estas personas: igual una madre que sufr&iacute;a problemas de alcoholismo y le quitan a sus hijos bebe a&uacute;n m&aacute;s. &rdquo;La vivencia compartida de la mayor&iacute;a de padres a los que se les priva de sus hijos es que son malos padres y eso es doloroso para cualquier padre, independientemente del motivo por el que no est&eacute;n preparados para serlo y que ellos sepan que es mejor para sus hijos estar lejos de ellos&rdquo;, cuenta Santa Maria.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>&iquest; Qu&eacute; papel tienen las figuras materna y paterna en el desarrollo de un individuo?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La familia para los hijos es el n&uacute;cleo donde se establecen los v&iacute;nculos afectivos desde etapas m&aacute;s tempranas. Habitualmente, los v&iacute;nculos que se establecen con la familia de origen, tienen una repercusi&oacute;n que se refleja a lo largo de toda la vida. La familia es un lugar donde los hijos establecen un v&iacute;nculo afectivo dependiente que busca la supervivencia y un desarrollo adecuado. Adem&aacute;s, la familia ofrece una fuente de apoyo emocional que necesitan para un crecimiento psicol&oacute;gicamente sano. El modelo que ofrece la familia es vital para proporcionarles la confianza y seguridad en s&iacute; mismos que se va a reflejar durante el resto de su vida adulta. (Palacios y Rodrigo, 1998). Esther C&agrave;ceres, psic&oacute;loga sanitaria, destaca la importancia de la primera infancia y el tipo de v&iacute;nculo paternofilial que se establece en esta, porque, seg&uacute;n la terapeuta, &ldquo;es a trav&eacute;s del v&iacute;nculo y la socializaci&oacute;n primaria -sobretodo con aquellos que ejercen la funci&oacute;n paterna y materna- que se desarrolla la personalidad del ni&ntilde;o&rdquo;. A&ntilde;ade que &ldquo;se calcula que la personalidad de los individuos se cristaliza un 65% hasta los siete a&ntilde;os&rdquo;. A todo esto, Blanca In&eacute;s Santa Maria, psic&oacute;loga sanitaria especializada en terapia familiar, explica que el apego es la forma que tenemos de vincularnos y de relacionarnos con los dem&aacute;s, &ldquo;por lo tanto, influye mucho en la socializaci&oacute;n y la autoestima&rdquo;, prosigue. Amplia que &ldquo;la relaci&oacute;n que construimos con nuestros padres y el tipo de apego que tenemos hacia ellos condiciona el resto de nuestra vida: nuestra salud mental, f&iacute;sica, emocional y nuestra esfera social&rdquo;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem&aacute;s, vivir en un internado puede ser un desaf&iacute;o para los ni&ntilde;os, ya que pueden experimentar sentimientos de aislamiento y falta de apoyo emocional, por no mencionar el impacto emocional que puede significar la muerte o separaci&oacute;n de sus progenitores. Los expertos han demostrado que los ni&ntilde;os en internados tienen m&aacute;s probabilidades de experimentar retrasos en el desarrollo y problemas de salud mental, como depresi&oacute;n y ansiedad. &ldquo;Otro problema a&ntilde;adido para estos ni&ntilde;os es que, normalmente, &nbsp; no aprenden a desarrollarse socialmente como cualquier otro&rdquo;, relata la educadora social Sofia Vasylechko. &ldquo;Es solo que no saben qu&eacute; hacer, d&oacute;nde vivir, c&oacute;mo cocinar, administrar su econom&iacute;a o lidiar con los servicios p&uacute;blicos y muchas veces terminan robando para tener un lugar seguro en el que estar&rdquo;, prosigue Vasylechko. Hennadiy Melnychuk, graduado hace 6 a&ntilde;os de un internado en la regi&oacute;n de Lviv y ahora empleado de la ONG Care in Action, se considera &ldquo;afortunado&rdquo; por haber encontrado su camino en la vida, ya que, como relata, &ldquo;como ni&ntilde;os est&aacute;bamos completamente solos, es muy dif&iacute;cil la vida despu&eacute;s de la instituci&oacute;n, la mayor&iacute;a no puede adaptarse a la vida <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Independencia&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Condici&oacute;n de autonom&iacute;a de un Estado o una persona, consistente en ser libre para decidir su actuaci&oacute;n y su vida sin intervenci&oacute;n de nadie.&amp;lt;br \/&amp;gt;Los mambises pelearon valientemente por nuestra independencia. &amp;lt;br \/&amp;gt;Tamara siempre actu&oacute; con mucha independencia por la educaci&oacute;n que le dieron sus padres. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/fatah\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Fatah&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-destruccion-de-gaza-el-ultimo-capitulo-de-cien-anos-de-odio\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La destrucci&oacute;n de Gaza, el &uacute;ltimo cap&iacute;tulo de cien a&ntilde;os de odio&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/israel-una-potencia-militarista-y-probada-en-combate\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Israel, una potencia militarista y &amp;quot;probada en combate&rdquo;&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/freelance\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Freelance&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/independencia\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">independiente<\/a>&rdquo;. &ldquo;Te acostumbras a tener todo listo y programado, todo se decide por nosotros, porque, para la gran mayor&iacute;a de profesores no eres nadie y no tienes nombre&rdquo;, relata el joven. El problema llega cuando sales: no sabes c&oacute;mo ganarte la vida. &laquo;Es por eso que muchos comienzan a robar, jugar y consumir alcohol o drogas&rdquo;, explica Hennadiy.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\"><strong>&iquest;Cu&aacute;les pueden ser las consecuencias de vivir la orfandad en un internado?<\/strong><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En un <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Reportaje&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Relato detallado de hechos reales, a menudo basado en la experiencia directa o en una investigaci&oacute;n en profundidad, para describir situaciones, acontecimientos o realidades sociales.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/comics-y-novelas-graficas-entre-el-poder-educativo-y-la-memoria-historica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&oacute;mics y novelas gr&aacute;ficas: entre el poder educativo y la memoria hist&oacute;rica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-ciudad-de-bari-protagonista-del-periodismo-europeo-en-2025\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La ciudad de Bari, protagonista del periodismo europeo en 2025&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/reportaje\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">reportaje<\/a> de Los &Aacute;ngeles Times titulado Estos son los efectos a largo plazo de separar a los ni&ntilde;os de sus padres en la frontera de EE.UU., seg&uacute;n expertos &ndash; en el cual se examinan las consecuencias que tiene para los ni&ntilde;os ser separados de sus padres debido a migraciones, guerras o hambrunas,- se apunta a una firme conclusi&oacute;n: separar a los ni&ntilde;os de sus padres es perjudicial para la salud f&iacute;sica y mental de los peque&ntilde;os. Hay una raz&oacute;n por la cual la infancia en humanos dura tanto: &ldquo;el cerebro de un ni&ntilde;o demora en madurar hacia la adultez&rdquo;, afirma en el art&iacute;culo el profesor de psicolog&iacute;a de la Universidad de Columbia Nim Tottenham, un experto en desarrollo emocional.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las psic&oacute;logas Esther C&agrave;ceres y Blanca In&eacute;s Santa Mar&iacute;a coinciden en que aquellos ni&ntilde;os que han tenido una figura de cuidador que ha ejercido el rol materno -el primer v&iacute;nculo y funci&oacute;n m&aacute;s demandada por los infantes en los primeros a&ntilde;os de vida- &ldquo;sea esta la de sus padres, abuelos o t&iacute;os&rdquo;, tienen &ldquo;una estructura ps&iacute;quica y de personalidad medianamente estable&rdquo;. Apuntan, por el contrario, que &ldquo;las estad&iacute;sticas indican que los ni&ntilde;os que han sufrido una ausencia de esta figura durante los primeros a&ntilde;os sufren grandes dificultades a nivel de desarrollo motor, cognitivo y, en a&ntilde;os futuros, otras &aacute;reas, como la ps&iacute;quica, intelectual o f&iacute;sica&rdquo;. Melissa Healy, la autora del <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Reportaje&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Relato detallado de hechos reales, a menudo basado en la experiencia directa o en una investigaci&oacute;n en profundidad, para describir situaciones, acontecimientos o realidades sociales.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/comics-y-novelas-graficas-entre-el-poder-educativo-y-la-memoria-historica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&oacute;mics y novelas gr&aacute;ficas: entre el poder educativo y la memoria hist&oacute;rica&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-ciudad-de-bari-protagonista-del-periodismo-europeo-en-2025\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La ciudad de Bari, protagonista del periodismo europeo en 2025&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/reportaje\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">reportaje<\/a> del Los &Aacute;ngeles Times, recoge las siguientes declaraciones de Tottenham: &ldquo;ese adulto que est&aacute; all&iacute; habitualmente proporciona un enorme efecto de amortiguaci&oacute;n del estr&eacute;s sobre el cerebro de un menor, en un momento en que &eacute;ste a&uacute;n no lo ha desarrollado para s&iacute; mismo&rdquo;. Cuando se retira repentinamente esa amortiguaci&oacute;n confiable y la orientaci&oacute;n de un padre, puede provocarse un cortocircuito en el aprendizaje que moldea y da forma al cerebro, consider&oacute; el experto. Adem&aacute;s, explica que &ldquo;los cerebros de los ni&ntilde;os que han experimentado tal situaci&oacute;n parecen volverse h&iacute;per vigilantes frente a las amenazas, un sello distintivo del <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Trastorno de estr&eacute;s postraum&aacute;tico&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;El trastorno de estr&eacute;s postraum&aacute;tico (TEPT) es una afecci&oacute;n mental que ocurre despu&eacute;s de experimentar o presenciar un evento traum&aacute;tico, causando s&iacute;ntomas como flashbacks, pesadillas y ansiedad.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La &lsquo;orfandad social&rsquo;, un mal end&eacute;mico de Ucrania que la guerra ha hecho visible&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/trastorno-de-estres-postraumatico\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">trastorno de estr&eacute;s postraum&aacute;tico<\/a>. Las regiones del cerebro que gobiernan el comportamiento de recompensa no responden normalmente, algo que los vuelve vulnerables a la depresi&oacute;n, la ansiedad y el abuso de sustancias. Sumado a ello, las estructuras corticales necesarias para la atenci&oacute;n, la planificaci&oacute;n, el juicio y el control emocional no se desarrollan adecuadamente&rdquo;.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Cuando se le pregunta a Hennadiy por sus recuerdos del internado, este cuenta que &eacute;l no tiene unos recuerdos malos, aunque tampoco excelentes. Remarca, por eso, su fortuna, puesto que &ldquo;estaba en uno bastante bueno&rdquo;, hecho que comprende despu&eacute;s de hablar con graduados de diferentes partes de Ucrania. Define los orfanatos como &ldquo;escuelas de supervivencia&rdquo; en las que era extremadamente importante c&oacute;mo te posicionaras para &ldquo;establecer tu autoridad frente a profesores, compa&ntilde;eros&rdquo;, explica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg&uacute;n Stepan Vovk, quien pas&oacute; por una familia de acogida, &ldquo;estar en una familia de acogida donde te tratan como a un ni&ntilde;o amado, es una alegr&iacute;a de todos los ni&ntilde;os, el valor de la vida en un orfanato de estilo familiar no se puede subestimar.&rdquo; Narra c&oacute;mo vivir en una foster family le ense&ntilde;&oacute; a &ldquo;vivir de manera <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Independencia&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Condici&oacute;n de autonom&iacute;a de un Estado o una persona, consistente en ser libre para decidir su actuaci&oacute;n y su vida sin intervenci&oacute;n de nadie.&amp;lt;br \/&amp;gt;Los mambises pelearon valientemente por nuestra independencia. &amp;lt;br \/&amp;gt;Tamara siempre actu&oacute; con mucha independencia por la educaci&oacute;n que le dieron sus padres. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/fatah\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Fatah&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-destruccion-de-gaza-el-ultimo-capitulo-de-cien-anos-de-odio\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La destrucci&oacute;n de Gaza, el &uacute;ltimo cap&iacute;tulo de cien a&ntilde;os de odio&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/israel-una-potencia-militarista-y-probada-en-combate\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Israel, una potencia militarista y &amp;quot;probada en combate&rdquo;&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/freelance\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Freelance&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/independencia\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">independiente<\/a>, honesta y organizada.&rdquo; Admite, emocionado, que para &eacute;l los hermanos con los que comparti&oacute; familia de acogida son m&aacute;s cercanos que sus hermanos biol&oacute;gicos, y que todav&iacute;a va a visitarlos con frecuencia. &ldquo;Siempre est&aacute;n dispuestos a escuchar, ayudar, comprometerse, lo que es un signo definitivo de una familia&rdquo;, prosigue.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/sad-borg.82-223-8-23.plesk.page\/wp-content\/uploads\/2024\/02\/Foto-4-1024x683.jpg\" alt=\"\" class=\"wp-image-17572\" srcset=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-4-1024x683.jpg 1024w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-4-300x200.jpg 300w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-4-768x512.jpg 768w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-4-1536x1024.jpg 1536w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-4-2048x1365.jpg 2048w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-4-1080x720.jpg 1080w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-4-1280x854.jpg 1280w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-4-980x653.jpg 980w, https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Foto-4-480x320.jpg 480w\" sizes=\"(max-width: 1024px) 100vw, 1024px\"\/><figcaption class=\"wp-element-caption\">Kataryna con su hija de acogida. | David Melero.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">En esta casa, los ni&ntilde;os y ni&ntilde;as reciben una educaci&oacute;n similar a la que recibir&iacute;an en cualquier otra familia sana. A diferencia de los centros de acogida o los orfanatos, aqu&iacute; conviven diez ni&ntilde;os con una sola referente: Kataryna. Los ni&ntilde;os tienen la oportunidad de practicar sus deportes favoritos, tocar instrumentos y disfrutar de otros hobbies. La <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Atm&oacute;sfera&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La atm&oacute;sfera es la capa de gases que rodea un cuerpo celeste, como la Tierra, proporcionando aire, regulando el clima y protegiendo la vida de la radiaci&oacute;n solar y los meteoritos.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-educacion-ambiental-como-paradigma-de-la-prevencion-de-incendios-rurales\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La educaci&oacute;n ambiental como paradigma de la prevenci&oacute;n de incendios rurales&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/fenomenos-hidrometeorologicos\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Fen&oacute;menos hidrometeorol&oacute;gicos&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/chorro-polar\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Chorro polar&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/la-dana-de-un-otono-en-el-mediterraneo-tras-la-tormenta-no-llega-la-calma\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;La DANA de un oto&ntilde;o en el Mediterr&aacute;neo: tras la tormenta, no llega la calma&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/comics-y-novelas-graficas-entre-el-poder-educativo-y-la-memoria-historica\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;C&oacute;mics y novelas gr&aacute;ficas: entre el poder educativo y la memoria hist&oacute;rica&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/atmosfera\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">atm&oacute;sfera<\/a> en la casa es c&aacute;lida y acogedora, lo que contribuye a un ambiente de aprendizaje saludable para los ni&ntilde;os. Kataryna se asegura de que cada ni&ntilde;o reciba atenci&oacute;n personalizada y se sienta valorado como individuo. Es un lugar donde los ni&ntilde;os pueden sentirse seguros, felices y apoyados en su crecimiento personal y acad&eacute;mico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&ldquo;Estoy agradecido con las autoridades locales por dar a los ni&ntilde;os la oportunidad de vivir en orfanatos de estilo familiar donde se aseguran todas las condiciones necesarias, donde los ni&ntilde;os son amados y educados, donde los padres-cuidadores aceptan a los hu&eacute;rfanos como sus propios hijos&rdquo;, dice Stepan. &ldquo;A todo aquel que est&eacute; dudando sobre si acoger yo le dir&iacute;a que no dude&rdquo;, sentencia Katarina. &ldquo;Es algo grande, te da mucha fuerza, te hace crecer, te llena de amor y todos necesitamos amor&rdquo;, explica. Cuenta tambi&eacute;n que estos ni&ntilde;os la convirtieron en una persona menos dura y ego&iacute;sta. Cuando se les pregunta por su experiencia, tanto Stephan como Katarina muestran su agradecimiento infinito por haber podido experimentar el amor tan de cerca y hacer de unos desconocidos su familia para siempre. &ldquo;Aprend&iacute; a vivir y ser feliz, pese a los desaf&iacute;os; gracias a ellos he pasado los momentos m&aacute;s felices de mi vida&rdquo;, relata con voz entrecortada Katarina mientras que apapacha dulcemente a Veronika entre sus brazos, quien parece haber estado hecha para ser amada por ella.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Guerra&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;Hostilidad, conflicto armado entre dos o m&aacute;s naciones libres o entre facciones de un mismo Estado. Trae consigo muertes y destrucci&oacute;n de recursos y propiedades y su fin es imponer la voluntad de los vencedores sobre los vencidos.&amp;lt;br \/&amp;gt;Con las guerras, muchos pa&iacute;ses quedaron arruinados y endeudados. &lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ucrania-la-herida-en-el-corazon-de-europa\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ucrania, la herida en el coraz&oacute;n de Europa&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/mayo-del-68-cuando-los-jovenes-lograron-sacudir-la-historia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Mayo del 68, cuando los j&oacute;venes lograron sacudir la historia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/que-es-el-fascismo\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Qu&eacute; es el fascismo?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/por-que-el-futbol-es-un-fenomeno-global\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;&iquest;Por qu&eacute; el f&uacute;tbol es un fen&oacute;meno global?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/generacion-y-los-primeros-jovenes-que-viviran-peor-que-sus-padres-2\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Generaci&oacute;n Y, los primeros j&oacute;venes que vivir&aacute;n peor que sus padres&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/guerra\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">guerra<\/a> ha puesto todas las miradas sobre Ucrania. Y m&aacute;s all&aacute; de la tragedia del conflicto, emergen problemas end&eacute;micos de la sociedad. Uno de los m&aacute;s graves es la &lsquo;orfandad social&rsquo;, los m&aacute;s de cien mil menores acogidos en instituciones heredadas del sistema &lsquo;post-sovi&eacute;tico&rsquo;<\/p>\n","protected":false},"author":50,"featured_media":17555,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[349,343],"tags":[85],"coauthors":[206],"class_list":["post-17554","post","type-post","status-publish","format-standard","has-post-thumbnail","category-conflictos-de-guerra","category-derechos-humanos","tag-ucrania"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La \u2018orfandad social\u2019, un mal end\u00e9mico de Ucrania que la guerra ha hecho visible - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La \u2018orfandad social\u2019, un mal end\u00e9mico de Ucrania que la guerra ha hecho visible - xqthenews\" \/>\n<meta property=\"og:description\" content=\"La guerra ha puesto todas las miradas sobre Ucrania. Y m&aacute;s all&aacute; de la tragedia del conflicto, emergen problemas end&eacute;micos de la sociedad. Uno de los m&aacute;s graves es la &lsquo;orfandad social&rsquo;, los m&aacute;s de cien mil menores acogidos en instituciones heredadas del sistema &lsquo;post-sovi&eacute;tico&rsquo;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:published_time\" content=\"2024-02-07T07:10:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-09-10T21:59:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Portada-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1707\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Andrea Gabarr\u00f3\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"Andrea Gabarr\u00f3\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"21 minutos\" \/>\n\t<meta name=\"twitter:label3\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data3\" content=\"Andrea Gabarr\u00f3\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\\\/\"},\"author\":{\"name\":\"Andrea Gabarr\u00f3\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/85154df4aac7f0ce5bd2db8c552b66d4\"},\"headline\":\"La \u2018orfandad social\u2019, un mal end\u00e9mico de Ucrania que la guerra ha hecho visible\",\"datePublished\":\"2024-02-07T07:10:44+00:00\",\"dateModified\":\"2024-09-10T21:59:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\\\/\"},\"wordCount\":4302,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Portada-scaled.jpg\",\"keywords\":[\"Ucrania\"],\"articleSection\":[\"Conflictos de guerra\",\"Derechos humanos\"],\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/es\\\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\\\/\",\"name\":\"La \u2018orfandad social\u2019, un mal end\u00e9mico de Ucrania que la guerra ha hecho visible - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Portada-scaled.jpg\",\"datePublished\":\"2024-02-07T07:10:44+00:00\",\"dateModified\":\"2024-09-10T21:59:58+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/85154df4aac7f0ce5bd2db8c552b66d4\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/es\\\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\\\/#primaryimage\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Portada-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/xqthenews.com\\\/wp-content\\\/uploads\\\/2024\\\/02\\\/Portada-scaled.jpg\",\"width\":2560,\"height\":1707},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La \u2018orfandad social\u2019, un mal end\u00e9mico de Ucrania que la guerra ha hecho visible\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#\\\/schema\\\/person\\\/85154df4aac7f0ce5bd2db8c552b66d4\",\"name\":\"Andrea Gabarr\u00f3\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771828b8a100ec5d002be00040bf2cbdca4c619f8d1096207e8e363ae96f4068?s=96&d=mm&r=g4e009d12e278bad1648bf6a377de823b\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771828b8a100ec5d002be00040bf2cbdca4c619f8d1096207e8e363ae96f4068?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/771828b8a100ec5d002be00040bf2cbdca4c619f8d1096207e8e363ae96f4068?s=96&d=mm&r=g\",\"caption\":\"Andrea Gabarr\u00f3\"},\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/author\\\/andreagabarro\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La \u2018orfandad social\u2019, un mal end\u00e9mico de Ucrania que la guerra ha hecho visible - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/","og_locale":"es_ES","og_type":"article","og_title":"La \u2018orfandad social\u2019, un mal end\u00e9mico de Ucrania que la guerra ha hecho visible - xqthenews","og_description":"La guerra ha puesto todas las miradas sobre Ucrania. Y m&aacute;s all&aacute; de la tragedia del conflicto, emergen problemas end&eacute;micos de la sociedad. Uno de los m&aacute;s graves es la &lsquo;orfandad social&rsquo;, los m&aacute;s de cien mil menores acogidos en instituciones heredadas del sistema &lsquo;post-sovi&eacute;tico&rsquo;","og_url":"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/","og_site_name":"xqthenews","article_published_time":"2024-02-07T07:10:44+00:00","article_modified_time":"2024-09-10T21:59:58+00:00","og_image":[{"width":2560,"height":1707,"url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Portada-scaled.jpg","type":"image\/jpeg"}],"author":"Andrea Gabarr\u00f3","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"Andrea Gabarr\u00f3","Tiempo de lectura":"21 minutos","Written by":"Andrea Gabarr\u00f3"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/#article","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/"},"author":{"name":"Andrea Gabarr\u00f3","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/85154df4aac7f0ce5bd2db8c552b66d4"},"headline":"La \u2018orfandad social\u2019, un mal end\u00e9mico de Ucrania que la guerra ha hecho visible","datePublished":"2024-02-07T07:10:44+00:00","dateModified":"2024-09-10T21:59:58+00:00","mainEntityOfPage":{"@id":"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/"},"wordCount":4302,"commentCount":0,"image":{"@id":"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Portada-scaled.jpg","keywords":["Ucrania"],"articleSection":["Conflictos de guerra","Derechos humanos"],"inLanguage":"es","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/","url":"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/","name":"La \u2018orfandad social\u2019, un mal end\u00e9mico de Ucrania que la guerra ha hecho visible - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/#primaryimage"},"image":{"@id":"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/#primaryimage"},"thumbnailUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Portada-scaled.jpg","datePublished":"2024-02-07T07:10:44+00:00","dateModified":"2024-09-10T21:59:58+00:00","author":{"@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/85154df4aac7f0ce5bd2db8c552b66d4"},"breadcrumb":{"@id":"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/#primaryimage","url":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Portada-scaled.jpg","contentUrl":"https:\/\/xqthenews.com\/wp-content\/uploads\/2024\/02\/Portada-scaled.jpg","width":2560,"height":1707},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/es\/la-orfandad-social-un-mal-endemico-de-ucrania-que-la-guerra-ha-hecho-visible\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/es\/"},{"@type":"ListItem","position":2,"name":"La \u2018orfandad social\u2019, un mal end\u00e9mico de Ucrania que la guerra ha hecho visible"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/xqthenews.com\/es\/#\/schema\/person\/85154df4aac7f0ce5bd2db8c552b66d4","name":"Andrea Gabarr\u00f3","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/771828b8a100ec5d002be00040bf2cbdca4c619f8d1096207e8e363ae96f4068?s=96&d=mm&r=g4e009d12e278bad1648bf6a377de823b","url":"https:\/\/secure.gravatar.com\/avatar\/771828b8a100ec5d002be00040bf2cbdca4c619f8d1096207e8e363ae96f4068?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/771828b8a100ec5d002be00040bf2cbdca4c619f8d1096207e8e363ae96f4068?s=96&d=mm&r=g","caption":"Andrea Gabarr\u00f3"},"url":"https:\/\/xqthenews.com\/es\/author\/andreagabarro\/"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/posts\/17554","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/users\/50"}],"replies":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/comments?post=17554"}],"version-history":[{"count":0,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/posts\/17554\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/media\/17555"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/media?parent=17554"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/categories?post=17554"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/tags?post=17554"},{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/coauthors?post=17554"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}