{"id":28458,"date":"2025-03-18T11:46:28","date_gmt":"2025-03-18T10:46:28","guid":{"rendered":"https:\/\/xqthenews.com\/?post_type=glossary&#038;p=28458"},"modified":"2025-03-18T11:46:31","modified_gmt":"2025-03-18T10:46:31","slug":"abolicion","status":"publish","type":"glossary","link":"https:\/\/xqthenews.com\/es\/glossary\/abolicion\/","title":{"rendered":"Abolici\u00f3n"},"content":{"rendered":"<p>La <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Abolici&oacute;n&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La abolici&oacute;n es la supresi&oacute;n o eliminaci&oacute;n total de una ley, pr&aacute;ctica o sistema. En el feminismo, suele referirse a la eliminaci&oacute;n de la prostituci&oacute;n o de normas que perpet&uacute;an desigualdades y opresiones.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/el-8-m-denuncia-la-discriminacion-invisible-de-los-cuidados\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;El 8-M denuncia la discriminaci&oacute;n invisible de los cuidados&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/abolicion\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">abolici&oacute;n<\/a> es la supresi&oacute;n o eliminaci&oacute;n total de una ley, pr&aacute;ctica o sistema. En el <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Feminismo&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Movimiento social y pol&iacute;tico que lucha por la igualdad de derechos entre hombres y mujeres y se opone a la discriminaci&oacute;n por raz&oacute;n de sexo.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/accion-empatia-y-responsabilidad-colectiva\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Acci&oacute;n, empat&iacute;a y responsabilidad colectiva&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/abolicion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Abolici&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/el-8-m-denuncia-la-discriminacion-invisible-de-los-cuidados\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;El 8-M denuncia la discriminaci&oacute;n invisible de los cuidados&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/feminismo\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">feminismo<\/a>, suele referirse a la eliminaci&oacute;n de la prostituci&oacute;n o de normas que perpet&uacute;an desigualdades y opresiones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Abolici&oacute;n&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La abolici&oacute;n es la supresi&oacute;n o eliminaci&oacute;n total de una ley, pr&aacute;ctica o sistema. En el feminismo, suele referirse a la eliminaci&oacute;n de la prostituci&oacute;n o de normas que perpet&uacute;an desigualdades y opresiones.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/el-8-m-denuncia-la-discriminacion-invisible-de-los-cuidados\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;El 8-M denuncia la discriminaci&oacute;n invisible de los cuidados&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/abolicion\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">abolici&oacute;n<\/a> es la supresi&oacute;n o eliminaci&oacute;n total de una ley, pr&aacute;ctica o sistema. En el <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Feminismo&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Movimiento social y pol&iacute;tico que lucha por la igualdad de derechos entre hombres y mujeres y se opone a la discriminaci&oacute;n por raz&oacute;n de sexo.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/accion-empatia-y-responsabilidad-colectiva\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Acci&oacute;n, empat&iacute;a y responsabilidad colectiva&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/abolicion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Abolici&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/el-8-m-denuncia-la-discriminacion-invisible-de-los-cuidados\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;El 8-M denuncia la discriminaci&oacute;n invisible de los cuidados&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/feminismo\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">feminismo<\/a>, suele referirse a la eliminaci&oacute;n de la prostituci&oacute;n o de normas que perpet&uacute;an desigualdades y opresiones.<\/p>\n","protected":false},"author":27,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[152],"class_list":["post-28458","glossary","type-glossary","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Abolici\u00f3n - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/es\/glossary\/abolicion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Abolici\u00f3n - xqthenews\" \/>\n<meta property=\"og:description\" content=\"La abolici&oacute;n es la supresi&oacute;n o eliminaci&oacute;n total de una ley, pr&aacute;ctica o sistema. En el feminismo, suele referirse a la eliminaci&oacute;n de la prostituci&oacute;n o de normas que perpet&uacute;an desigualdades y opresiones.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/es\/glossary\/abolicion\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-18T10:46:31+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Manuel Le\u00f3n Var\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/abolicion\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/abolicion\\\/\",\"name\":\"Abolici\u00f3n - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"datePublished\":\"2025-03-18T10:46:28+00:00\",\"dateModified\":\"2025-03-18T10:46:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/abolicion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/abolicion\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/abolicion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Abolici\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Abolici\u00f3n - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/es\/glossary\/abolicion\/","og_locale":"es_ES","og_type":"article","og_title":"Abolici\u00f3n - xqthenews","og_description":"La abolici&oacute;n es la supresi&oacute;n o eliminaci&oacute;n total de una ley, pr&aacute;ctica o sistema. En el feminismo, suele referirse a la eliminaci&oacute;n de la prostituci&oacute;n o de normas que perpet&uacute;an desigualdades y opresiones.","og_url":"https:\/\/xqthenews.com\/es\/glossary\/abolicion\/","og_site_name":"xqthenews","article_modified_time":"2025-03-18T10:46:31+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto","Written by":"Manuel Le\u00f3n Var\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/es\/glossary\/abolicion\/","url":"https:\/\/xqthenews.com\/es\/glossary\/abolicion\/","name":"Abolici\u00f3n - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"datePublished":"2025-03-18T10:46:28+00:00","dateModified":"2025-03-18T10:46:31+00:00","breadcrumb":{"@id":"https:\/\/xqthenews.com\/es\/glossary\/abolicion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/es\/glossary\/abolicion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/es\/glossary\/abolicion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/es\/"},{"@type":"ListItem","position":2,"name":"Abolici\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary\/28458","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":1,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary\/28458\/revisions"}],"predecessor-version":[{"id":28459,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary\/28458\/revisions\/28459"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/media?parent=28458"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/coauthors?post=28458"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}