{"id":27170,"date":"2025-01-20T14:02:01","date_gmt":"2025-01-20T13:02:01","guid":{"rendered":"https:\/\/xqthenews.com\/?post_type=glossary&#038;p=27170"},"modified":"2025-01-20T14:02:03","modified_gmt":"2025-01-20T13:02:03","slug":"holopresencia","status":"publish","type":"glossary","link":"https:\/\/xqthenews.com\/es\/glossary\/holopresencia\/","title":{"rendered":"Holopresencia"},"content":{"rendered":"<p>La <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Holopresencia&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La holopresencia es una tecnolog&iacute;a avanzada para crear la ilusi&oacute;n de la presencia f&iacute;sica de personas, objetos o entornos en un lugar distinto del real, utilizando t&eacute;cnicas de holograf&iacute;a y realidad aumentada. Se basa en la proyecci&oacute;n tridimensional de im&aacute;genes hologr&aacute;ficas que simulan de forma realista movimientos, sonidos e interacciones, permitiendo experiencias inmersivas e interactivas a distancia.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/innovacion-en-la-ensenanza-del-periodismo-gracias-a-los-hologramas\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Innovaci&oacute;n en la ense&ntilde;anza del periodismo gracias a los hologramas&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/holopresencia\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">holopresencia<\/a> es una tecnolog&iacute;a avanzada para crear la ilusi&oacute;n de la presencia f&iacute;sica de personas, objetos o entornos en un lugar distinto del real, utilizando t&eacute;cnicas de holograf&iacute;a y <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Realidad Aumentada&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La realidad aumentada o RA consiste en mejorar (aumentar) la percepci&oacute;n del mundo real mediante informaci&oacute;n perceptiva generada por ordenador. A trav&eacute;s de unas gafas de RA, la realidad aumentada superpone contenidos digitales a entornos y objetos reales.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/metaverso-que-retos-sociales-nos-esperan\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Metaverso, qu&eacute; retos sociales nos esperan&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/holopresencia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Holopresencia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/innovacion-en-la-ensenanza-del-periodismo-gracias-a-los-hologramas\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Innovaci&oacute;n en la ense&ntilde;anza del periodismo gracias a los hologramas&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/realidad-aumentada\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">realidad aumentada<\/a>. Se basa en la proyecci&oacute;n tridimensional de im&aacute;genes hologr&aacute;ficas que simulan de forma realista movimientos, sonidos e interacciones, permitiendo experiencias inmersivas e interactivas a distancia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Holopresencia&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La holopresencia es una tecnolog&iacute;a avanzada para crear la ilusi&oacute;n de la presencia f&iacute;sica de personas, objetos o entornos en un lugar distinto del real, utilizando t&eacute;cnicas de holograf&iacute;a y realidad aumentada. Se basa en la proyecci&oacute;n tridimensional de im&aacute;genes hologr&aacute;ficas que simulan de forma realista movimientos, sonidos e interacciones, permitiendo experiencias inmersivas e interactivas a distancia.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/innovacion-en-la-ensenanza-del-periodismo-gracias-a-los-hologramas\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Innovaci&oacute;n en la ense&ntilde;anza del periodismo gracias a los hologramas&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/holopresencia\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">holopresencia<\/a> es una tecnolog&iacute;a avanzada para crear la ilusi&oacute;n de la presencia f&iacute;sica de personas, objetos o entornos en un lugar distinto del real, utilizando t&eacute;cnicas de holograf&iacute;a y <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Realidad Aumentada&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;La realidad aumentada o RA consiste en mejorar (aumentar) la percepci&oacute;n del mundo real mediante informaci&oacute;n perceptiva generada por ordenador. A trav&eacute;s de unas gafas de RA, la realidad aumentada superpone contenidos digitales a entornos y objetos reales.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/metaverso-que-retos-sociales-nos-esperan\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Metaverso, qu&eacute; retos sociales nos esperan&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/holopresencia\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Holopresencia&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/innovacion-en-la-ensenanza-del-periodismo-gracias-a-los-hologramas\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Innovaci&oacute;n en la ense&ntilde;anza del periodismo gracias a los hologramas&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/realidad-aumentada\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">realidad aumentada<\/a>. Se basa en la proyecci&oacute;n tridimensional de im&aacute;genes hologr&aacute;ficas que simulan de forma realista movimientos, sonidos e interacciones, permitiendo experiencias inmersivas e interactivas<\/p>\n","protected":false},"author":27,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[152],"class_list":["post-27170","glossary","type-glossary","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Holopresencia - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/es\/glossary\/holopresencia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Holopresencia - xqthenews\" \/>\n<meta property=\"og:description\" content=\"La holopresencia es una tecnolog&iacute;a avanzada para crear la ilusi&oacute;n de la presencia f&iacute;sica de personas, objetos o entornos en un lugar distinto del real, utilizando t&eacute;cnicas de holograf&iacute;a y realidad aumentada. Se basa en la proyecci&oacute;n tridimensional de im&aacute;genes hologr&aacute;ficas que simulan de forma realista movimientos, sonidos e interacciones, permitiendo experiencias inmersivas e interactivas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/es\/glossary\/holopresencia\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:modified_time\" content=\"2025-01-20T13:02:03+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Manuel Le\u00f3n Var\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/holopresencia\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/holopresencia\\\/\",\"name\":\"Holopresencia - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"datePublished\":\"2025-01-20T13:02:01+00:00\",\"dateModified\":\"2025-01-20T13:02:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/holopresencia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/holopresencia\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/holopresencia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Holopresencia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Holopresencia - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/es\/glossary\/holopresencia\/","og_locale":"es_ES","og_type":"article","og_title":"Holopresencia - xqthenews","og_description":"La holopresencia es una tecnolog&iacute;a avanzada para crear la ilusi&oacute;n de la presencia f&iacute;sica de personas, objetos o entornos en un lugar distinto del real, utilizando t&eacute;cnicas de holograf&iacute;a y realidad aumentada. Se basa en la proyecci&oacute;n tridimensional de im&aacute;genes hologr&aacute;ficas que simulan de forma realista movimientos, sonidos e interacciones, permitiendo experiencias inmersivas e interactivas","og_url":"https:\/\/xqthenews.com\/es\/glossary\/holopresencia\/","og_site_name":"xqthenews","article_modified_time":"2025-01-20T13:02:03+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto","Written by":"Manuel Le\u00f3n Var\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/es\/glossary\/holopresencia\/","url":"https:\/\/xqthenews.com\/es\/glossary\/holopresencia\/","name":"Holopresencia - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"datePublished":"2025-01-20T13:02:01+00:00","dateModified":"2025-01-20T13:02:03+00:00","breadcrumb":{"@id":"https:\/\/xqthenews.com\/es\/glossary\/holopresencia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/es\/glossary\/holopresencia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/es\/glossary\/holopresencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/es\/"},{"@type":"ListItem","position":2,"name":"Holopresencia"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary\/27170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":1,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary\/27170\/revisions"}],"predecessor-version":[{"id":27171,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary\/27170\/revisions\/27171"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/media?parent=27170"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/coauthors?post=27170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}