{"id":25335,"date":"2024-10-28T13:05:57","date_gmt":"2024-10-28T12:05:57","guid":{"rendered":"https:\/\/xqthenews.com\/?post_type=glossary&#038;p=25335"},"modified":"2024-10-28T13:05:58","modified_gmt":"2024-10-28T12:05:58","slug":"enfermedades-de-transmision-sexual-ets","status":"publish","type":"glossary","link":"https:\/\/xqthenews.com\/es\/glossary\/enfermedades-de-transmision-sexual-ets\/","title":{"rendered":"Enfermedades de transmisi\u00f3n sexual (ETS)"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Son infecciones que se transmiten de una persona a otra a trav&eacute;s de las relaciones sexuales. Ejemplos de estas enfermedades son el <a class=\"glossaryLink\"  aria-describedby=\"tt\"  data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;VIH&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;VIH es el Virus de Inmunodeficiencia Humana, que ataca el sistema inmunol&oacute;gico y puede llevar al SIDA si no se trata. Se transmite por contacto sangu&iacute;neo, sexual y de madre a hijo durante el embarazo, parto o lactancia.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/el-efecto-popper-sobre-la-droga-que-dura-lo-que-un-tiktok\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;El efecto popper: sobre la droga que dura lo que un TikTok&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/el-arcoiris-empieza-por-l\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;El arco&iacute;ris empieza por L&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/enfermedades-de-transmision-sexual-ets\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Enfermedades de transmisi&oacute;n sexual (ETS)&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/aumentan-las-relaciones-sexuales-de-riesgo-entre-adolescentes\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Aumentan las relaciones sexuales de riesgo entre adolescentes&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/relacoes-sexuais-de-risco-entre-adolescentes-estao-a-aumentar\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Rela&ccedil;&otilde;es sexuais de risco entre adolescentes est&atilde;o a aumentar&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\"  href=\"https:\/\/xqthenews.com\/es\/glossary\/vih\/\"  data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex='0' role='link'>VIH<\/a>, la s&iacute;filis, la gonorrea y la clamidia.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Son infecciones que se transmiten de una persona a otra a trav&eacute;s de las relaciones sexuales. Ejemplos de estas enfermedades son el <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;VIH&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;VIH es el Virus de Inmunodeficiencia Humana, que ataca el sistema inmunol&oacute;gico y puede llevar al SIDA si no se trata. Se transmite por contacto sangu&iacute;neo, sexual y de madre a hijo durante el embarazo, parto o lactancia.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/el-efecto-popper-sobre-la-droga-que-dura-lo-que-un-tiktok\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;El efecto popper: sobre la droga que dura lo que un TikTok&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/el-arcoiris-empieza-por-l\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;El arco&iacute;ris empieza por L&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/enfermedades-de-transmision-sexual-ets\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Enfermedades de transmisi&oacute;n sexual (ETS)&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/aumentan-las-relaciones-sexuales-de-riesgo-entre-adolescentes\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Aumentan las relaciones sexuales de riesgo entre adolescentes&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/pt-pt\/relacoes-sexuais-de-risco-entre-adolescentes-estao-a-aumentar\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Rela&ccedil;&otilde;es sexuais de risco entre adolescentes est&atilde;o a aumentar&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/vih\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">VIH<\/a>, la s&iacute;filis, la gonorrea y la clamidia.<\/p>\n","protected":false},"author":27,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[152],"class_list":["post-25335","glossary","type-glossary","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enfermedades de transmisi\u00f3n sexual (ETS) - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/es\/glossary\/enfermedades-de-transmision-sexual-ets\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enfermedades de transmisi\u00f3n sexual (ETS) - xqthenews\" \/>\n<meta property=\"og:description\" content=\"Son infecciones que se transmiten de una persona a otra a trav&eacute;s de las relaciones sexuales. Ejemplos de estas enfermedades son el VIH, la s&iacute;filis, la gonorrea y la clamidia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/es\/glossary\/enfermedades-de-transmision-sexual-ets\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:modified_time\" content=\"2024-10-28T12:05:58+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data2\" content=\"Manuel Le\u00f3n Var\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/enfermedades-de-transmision-sexual-ets\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/enfermedades-de-transmision-sexual-ets\\\/\",\"name\":\"Enfermedades de transmisi\u00f3n sexual (ETS) - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"datePublished\":\"2024-10-28T12:05:57+00:00\",\"dateModified\":\"2024-10-28T12:05:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/enfermedades-de-transmision-sexual-ets\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/enfermedades-de-transmision-sexual-ets\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/enfermedades-de-transmision-sexual-ets\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enfermedades de transmisi\u00f3n sexual (ETS)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enfermedades de transmisi\u00f3n sexual (ETS) - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/es\/glossary\/enfermedades-de-transmision-sexual-ets\/","og_locale":"es_ES","og_type":"article","og_title":"Enfermedades de transmisi\u00f3n sexual (ETS) - xqthenews","og_description":"Son infecciones que se transmiten de una persona a otra a trav&eacute;s de las relaciones sexuales. Ejemplos de estas enfermedades son el VIH, la s&iacute;filis, la gonorrea y la clamidia.","og_url":"https:\/\/xqthenews.com\/es\/glossary\/enfermedades-de-transmision-sexual-ets\/","og_site_name":"xqthenews","article_modified_time":"2024-10-28T12:05:58+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto","Written by":"Manuel Le\u00f3n Var\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/es\/glossary\/enfermedades-de-transmision-sexual-ets\/","url":"https:\/\/xqthenews.com\/es\/glossary\/enfermedades-de-transmision-sexual-ets\/","name":"Enfermedades de transmisi\u00f3n sexual (ETS) - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"datePublished":"2024-10-28T12:05:57+00:00","dateModified":"2024-10-28T12:05:58+00:00","breadcrumb":{"@id":"https:\/\/xqthenews.com\/es\/glossary\/enfermedades-de-transmision-sexual-ets\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/es\/glossary\/enfermedades-de-transmision-sexual-ets\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/es\/glossary\/enfermedades-de-transmision-sexual-ets\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/es\/"},{"@type":"ListItem","position":2,"name":"Enfermedades de transmisi\u00f3n sexual (ETS)"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary\/25335","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":1,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary\/25335\/revisions"}],"predecessor-version":[{"id":25336,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary\/25335\/revisions\/25336"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/media?parent=25335"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/coauthors?post=25335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}