{"id":20001,"date":"2024-03-26T18:57:22","date_gmt":"2024-03-26T17:57:22","guid":{"rendered":"https:\/\/sad-borg.82-223-8-23.plesk.page\/?post_type=glossary&#038;p=20001"},"modified":"2024-03-26T18:57:25","modified_gmt":"2024-03-26T17:57:25","slug":"adaptacion","status":"publish","type":"glossary","link":"https:\/\/xqthenews.com\/es\/glossary\/adaptacion\/","title":{"rendered":"Adaptaci\u00f3n"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Proceso de ajuste al <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Cambio clim&aacute;tico&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Causado por el calentamiento global, el cambio clim&aacute;tico se refiere a las variaciones en los patrones clim&aacute;ticos a largo plazo en la Tierra, como la temperatura, el nivel del mar y las precipitaciones.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;em&amp;gt;(Fuente: European Youth Portal)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/economia-circular-materia-organica-en-el-pasado-el-presente-y-el-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Econom&iacute;a circular: materia org&aacute;nica en el pasado, el presente y el futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/emergencia-climatica-y-retos-sanitarios\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Emergencia clim&aacute;tica y retos sanitarios&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/portugal-entre-los-paises-europeos-mas-afectados-por-los-fenomenos-meteorologicos-extremos\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Portugal entre los pa&iacute;ses europeos m&aacute;s afectados por los fen&oacute;menos meteorol&oacute;gicos extremos&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ley-de-restauracion-de-la-naturaleza-como-se-propone-restaurar-los-ecosistemas-europeos\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ley de Restauraci&oacute;n de la Naturaleza: &iquest;C&oacute;mo se propone restaurar los ecosistemas europeos?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/descarbonizacion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Descarbonizaci&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/cambio-climatico\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">cambio clim&aacute;tico<\/a> actual o previsto y a sus efectos. Implica tomar medidas para reducir la vulnerabilidad y aumentar la resistencia de los sistemas humanos y naturales.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Proceso de ajuste al <a class=\"glossaryLink\" aria-describedby=\"tt\" data-cmtooltip=\"&lt;div class=glossaryItemTitle&gt;Cambio clim&aacute;tico&lt;\/div&gt;&lt;div class=glossaryItemBody&gt;&amp;lt;!-- wp:paragraph --&amp;gt;Causado por el calentamiento global, el cambio clim&aacute;tico se refiere a las variaciones en los patrones clim&aacute;ticos a largo plazo en la Tierra, como la temperatura, el nivel del mar y las precipitaciones.&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&amp;lt;!-- wp:paragraph --&amp;gt;&amp;lt;em&amp;gt;(Fuente: European Youth Portal)&amp;lt;\/em&amp;gt;&amp;lt;br\/&amp;gt;&amp;lt;!-- \/wp:paragraph --&amp;gt;&lt;\/div&gt;&lt;div id=&amp;quot;cmtt_related_articles&amp;quot; class=&amp;quot;cmtt_related_articles_wrapper&amp;quot;&gt;&lt;div class=&amp;quot;cmtt_related_title cmtt_related_articles_title&amp;quot;&gt;Related Articles: &lt;\/div&gt;&lt;ul class=&amp;quot;cmtt_related&amp;quot;&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/economia-circular-materia-organica-en-el-pasado-el-presente-y-el-futuro\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Econom&iacute;a circular: materia org&aacute;nica en el pasado, el presente y el futuro&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/emergencia-climatica-y-retos-sanitarios\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Emergencia clim&aacute;tica y retos sanitarios&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/portugal-entre-los-paises-europeos-mas-afectados-por-los-fenomenos-meteorologicos-extremos\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Portugal entre los pa&iacute;ses europeos m&aacute;s afectados por los fen&oacute;menos meteorol&oacute;gicos extremos&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/ley-de-restauracion-de-la-naturaleza-como-se-propone-restaurar-los-ecosistemas-europeos\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Ley de Restauraci&oacute;n de la Naturaleza: &iquest;C&oacute;mo se propone restaurar los ecosistemas europeos?&lt;\/a&gt;&lt;\/li&gt;&lt;li class=&amp;quot;cmtt_related_item&amp;quot;&gt;&lt;a href=&amp;quot;https:\/\/xqthenews.com\/es\/glossary\/descarbonizacion\/&amp;quot;target=&amp;quot;_blank&amp;quot;&gt;Glossary:  Descarbonizaci&oacute;n&lt;\/a&gt;&lt;\/li&gt;&lt;\/ul&gt;&lt;\/div&gt;\" href=\"https:\/\/xqthenews.com\/es\/glossary\/cambio-climatico\/\" data-gt-translate-attributes='[{\"attribute\":\"data-cmtooltip\", \"format\":\"html\"}]' tabindex=\"0\" role=\"link\">cambio clim&aacute;tico<\/a> actual o previsto y a sus efectos. Implica tomar medidas para reducir la vulnerabilidad y aumentar la resistencia de los sistemas humanos y naturales.<\/p>\n","protected":false},"author":27,"featured_media":0,"menu_order":0,"template":"","meta":{"_acf_changed":false,"footnotes":""},"coauthors":[],"class_list":["post-20001","glossary","type-glossary","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.9 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Adaptaci\u00f3n - xqthenews<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/xqthenews.com\/es\/glossary\/adaptacion\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Adaptaci\u00f3n - xqthenews\" \/>\n<meta property=\"og:description\" content=\"Proceso de ajuste al cambio clim&aacute;tico actual o previsto y a sus efectos. Implica tomar medidas para reducir la vulnerabilidad y aumentar la resistencia de los sistemas humanos y naturales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/xqthenews.com\/es\/glossary\/adaptacion\/\" \/>\n<meta property=\"og:site_name\" content=\"xqthenews\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-26T17:57:25+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Manuel Le\u00f3n Var\u00f3n\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/adaptacion\\\/\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/adaptacion\\\/\",\"name\":\"Adaptaci\u00f3n - xqthenews\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\"},\"datePublished\":\"2024-03-26T17:57:22+00:00\",\"dateModified\":\"2024-03-26T17:57:25+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/adaptacion\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/adaptacion\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/glossary\\\/adaptacion\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Adaptaci\u00f3n\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/\",\"name\":\"xqthenews\",\"description\":\"El porqu\u00e9 de las noticias\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/xqthenews.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Adaptaci\u00f3n - xqthenews","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/xqthenews.com\/es\/glossary\/adaptacion\/","og_locale":"es_ES","og_type":"article","og_title":"Adaptaci\u00f3n - xqthenews","og_description":"Proceso de ajuste al cambio clim&aacute;tico actual o previsto y a sus efectos. Implica tomar medidas para reducir la vulnerabilidad y aumentar la resistencia de los sistemas humanos y naturales.","og_url":"https:\/\/xqthenews.com\/es\/glossary\/adaptacion\/","og_site_name":"xqthenews","article_modified_time":"2024-03-26T17:57:25+00:00","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Manuel Le\u00f3n Var\u00f3n"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/xqthenews.com\/es\/glossary\/adaptacion\/","url":"https:\/\/xqthenews.com\/es\/glossary\/adaptacion\/","name":"Adaptaci\u00f3n - xqthenews","isPartOf":{"@id":"https:\/\/xqthenews.com\/es\/#website"},"datePublished":"2024-03-26T17:57:22+00:00","dateModified":"2024-03-26T17:57:25+00:00","breadcrumb":{"@id":"https:\/\/xqthenews.com\/es\/glossary\/adaptacion\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/xqthenews.com\/es\/glossary\/adaptacion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/xqthenews.com\/es\/glossary\/adaptacion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/xqthenews.com\/es\/"},{"@type":"ListItem","position":2,"name":"Adaptaci\u00f3n"}]},{"@type":"WebSite","@id":"https:\/\/xqthenews.com\/es\/#website","url":"https:\/\/xqthenews.com\/es\/","name":"xqthenews","description":"El porqu\u00e9 de las noticias","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/xqthenews.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"}]}},"_links":{"self":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary\/20001","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary"}],"about":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/types\/glossary"}],"author":[{"embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/users\/27"}],"version-history":[{"count":0,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/glossary\/20001\/revisions"}],"wp:attachment":[{"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/media?parent=20001"}],"wp:term":[{"taxonomy":"author","embeddable":true,"href":"https:\/\/xqthenews.com\/es\/wp-json\/wp\/v2\/coauthors?post=20001"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}